{"id":99100,"date":"2012-02-16T11:02:00","date_gmt":"2012-02-16T04:02:00","guid":{"rendered":"http:\/\/www.notebookspec.com\/web\/?p=99100"},"modified":"2012-02-16T11:02:00","modified_gmt":"2012-02-16T04:02:00","slug":"acer-%e0%b8%81%e0%b8%ad%e0%b8%9a%e0%b8%81%e0%b8%b9%e0%b9%89%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%81%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b2%e0%b9%80%e0%b8%9b%e0%b9%87","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/99100-acer-%e0%b8%81%e0%b8%ad%e0%b8%9a%e0%b8%81%e0%b8%b9%e0%b9%89%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%81%e0%b8%a5%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b2%e0%b9%80%e0%b8%9b%e0%b9%87","title":{"rendered":"Acer \u0e01\u0e2d\u0e1a\u0e01\u0e39\u0e49\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e27\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e1b\u0e16\u0e36\u0e07 2 \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e46"},"content":{"rendered":"<p>\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07 2 \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e15\u0e34\u0e14 Acer \u0e01\u0e47\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 4 \u0e02\u0e2d\u0e07\u0e1b\u0e35 2011 \u0e42\u0e14\u0e22\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e02\u0e2d\u0e07\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 2.5 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 77 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17) \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 Acer \u0e08\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e41\u0e15\u0e48\u0e22\u0e2d\u0e14\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e15\u0e01\u0e15\u0e48\u0e33\u0e25\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e04\u0e48\u0e2d\u0e22\u0e46\u0e14\u0e34\u0e48\u0e07\u0e25\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e19\u0e47\u0e15\u0e1a\u0e38\u0e4a\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07, \u0e04\u0e27\u0e32\u0e21\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c, \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.ibtimes.com\/www\/data\/images\/full\/2010\/04\/29\/7242-a-man-walks-past-an-acer-office.jpg\" alt=\"\" width=\"450\" height=\"276\"><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e1b\u0e35 2011 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19\u0e23\u0e32\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e41\u0e23\u0e01\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e25\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 2 \u0e41\u0e25\u0e30 3 \u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e46\u0e01\u0e31\u0e19 \u0e08\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e35 2011 \u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 212 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 6.5 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 601 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 18.5 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17)<\/p>\n<p>\u0e01\u0e47\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49 Acer \u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e2b\u0e19 \u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e40\u0e2b\u0e47\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32 Aspire S5 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Ultrabook \u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 CloudMobile S500 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: the verge<\/p>\n<p style=\"text-align:center\">\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07 2 \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e15\u0e34\u0e14 Acer \u0e01\u0e47\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 4 \u0e02\u0e2d\u0e07\u0e1b\u0e35 2011 \u0e42\u0e14\u0e22\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e02\u0e2d\u0e07\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 2.5 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 77 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17) \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 Acer \u0e08\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e41\u0e15\u0e48\u0e22\u0e2d\u0e14\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e15\u0e01\u0e15\u0e48\u0e33\u0e25\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e49\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e04\u0e48\u0e2d\u0e22\u0e46\u0e14\u0e34\u0e48\u0e07\u0e25\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e19\u0e47\u0e15\u0e1a\u0e38\u0e4a\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07, \u0e04\u0e27\u0e32\u0e21\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c, \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49 Advertisement \u0e1b\u0e35 2011 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19\u0e23\u0e32\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e41\u0e23\u0e01\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e25\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 2 \u0e41\u0e25\u0e30 3 \u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e46\u0e01\u0e31\u0e19 \u0e08\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e35 2011 \u0e02\u0e32\u0e14\u0e17\u0e38\u0e19\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 212 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 6.5 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 601 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 18.5 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17) \u0e01\u0e47\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49 Acer \u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e44\u0e2b\u0e19 \u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e40\u0e2b\u0e47\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32 Aspire S5 [&hellip;]<\/p>\n","protected":false},"author":1011016,"featured_media":566855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[204,8775,10138,6797],"class_list":["post-99100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-acer","tag-aspire-s5","tag-cloudmobile-s500","tag-ultrabook"],"views":306,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/99100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=99100"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/99100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/566855"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=99100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=99100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=99100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}