{"id":98555,"date":"2012-02-10T11:02:00","date_gmt":"2012-02-10T04:02:00","guid":{"rendered":"http:\/\/www.notebookspec.com\/web\/?p=98555"},"modified":"2012-02-10T11:02:00","modified_gmt":"2012-02-10T04:02:00","slug":"netbook-navigator-%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%87%e0%b8%9a%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%9a%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/98555-netbook-navigator-%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%87%e0%b8%9a%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%9a%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1","title":{"rendered":"Netbook Navigator \u0e2d\u0e2d\u0e01\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 Windows 7 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 NAV 10T \u0e21\u0e35 Dual-Core"},"content":{"rendered":"<div>\n<p dir=\"ltr\">\u0e19\u0e33\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e0a\u0e21\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07 Windows \u0e23\u0e32\u0e04\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 $499 (15,xxx \u0e1a\u0e32\u0e17) \u0e19\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e34\u0e14\u0e08\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e46 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e32\u0e21\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e04\u0e38\u0e49\u0e19\u0e2b\u0e39\u0e27\u0e48\u0e32 Netbook Navigator \u0e01\u0e47\u0e02\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e38\u0e48\u0e19\u0e27\u0e48\u0e32 NAV 10T \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e02\u0e36\u0e49\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e1a\u0e2d\u0e01\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 30 \u0e27\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 (\u0e21\u0e31\u0e19\u0e1f\u0e31\u0e07\u0e14\u0e39\u0e19\u0e32\u0e19\u0e44\u0e1b\u0e21\u0e31\u0e49\u0e22\u0e19\u0e30) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a WiFi \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30 WiFi + 3G<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.notebookcheck.net\/uploads\/tx_jppageteaser\/Netbook_Navigator_outs_the_dual_01.jpg\" alt=\"\" width=\"448\" height=\"299\"><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p dir=\"ltr\">NAV 10T \u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 8.5W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e0a\u0e34\u0e1e Intel Pineview Atom N570 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a dual-core \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 1.6GHz \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1e\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e43\u0e19\u0e15\u0e31\u0e27 Intel GMA 3150 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a capacitive multitouch \u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e32\u0e40\u0e19\u0e25\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19 LCD HD \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e27\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 10.1 \u0e19\u0e34\u0e49\u0e27 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 1366 x 768 \u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25<\/p>\n<div>\n<p dir=\"ltr\">\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 \u0e2b\u0e23\u0e37\u0e2d RAM \u0e20\u0e32\u0e22\u0e43\u0e19\u0e43\u0e2a\u0e48\u0e21\u0e32\u0e43\u0e2b\u0e49 2GB \u0e41\u0e1a\u0e1a DDR3 \u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e19\u0e31\u0e49\u0e19\u0e15\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07 SSD \u0e02\u0e19\u0e32\u0e14 128GB \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22\u0e41\u0e1a\u0e1a Wireless LAN \u0e01\u0e47\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a 802.11n, Bluetooth 2.1 \u0e41\u0e25\u0e30 3G \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e35\u0e1e\u0e2d\u0e23\u0e4c\u0e17 USB 2.0 \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e14\u0e49\u0e27\u0e22 2 \u0e0a\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e21\u0e35\u0e0a\u0e48\u0e2d\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 micro-SD \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48 SIM \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e19\u0e32\u0e14\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 1.3 \u0e25\u0e49\u0e32\u0e19\u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 video call<\/p>\n<\/div>\n<div>\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e21\u0e14\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e25\u0e33\u0e42\u0e1e\u0e07 stereo \u0e2a\u0e2d\u0e07\u0e15\u0e31\u0e27 \u0e0a\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e2b\u0e39\u0e1f\u0e31\u0e07 3.5 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 Li-Ion 3 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 680 \u0e01\u0e23\u0e31\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e01\u0e31\u0e1a Windows 7 \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07 Home Premium, Professional \u0e2b\u0e23\u0e37\u0e2d Ultimate \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07 32 \u0e41\u0e25\u0e30 64bit \u0e14\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/div>\n<\/div>\n<div>\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e08\u0e30\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 Windows \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e19\u0e31\u0e49\u0e19\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e17\u0e35 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e23\u0e32\u0e04\u0e32\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e21\u0e32\u0e2a\u0e39\u0e49\u0e01\u0e31\u0e1a iPad \u0e2b\u0e23\u0e37\u0e2d Android \u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e25\u0e48\u0e32<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: notebookcheck<\/p>\n<\/div>\n<p style=\"text-align:center\">\n","protected":false},"excerpt":{"rendered":"<p>\u0e19\u0e33\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e0a\u0e21\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07 Windows \u0e23\u0e32\u0e04\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 $499 (15,xxx \u0e1a\u0e32\u0e17) \u0e19\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e34\u0e14\u0e08\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e46 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e32\u0e21\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e04\u0e38\u0e49\u0e19\u0e2b\u0e39\u0e27\u0e48\u0e32 Netbook Navigator \u0e01\u0e47\u0e02\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e38\u0e48\u0e19\u0e27\u0e48\u0e32 NAV 10T \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e02\u0e36\u0e49\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e1a\u0e2d\u0e01\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 30 \u0e27\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 (\u0e21\u0e31\u0e19\u0e1f\u0e31\u0e07\u0e14\u0e39\u0e19\u0e32\u0e19\u0e44\u0e1b\u0e21\u0e31\u0e49\u0e22\u0e19\u0e30) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a WiFi \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30 WiFi + 3G Advertisement NAV 10T \u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 8.5W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e0a\u0e34\u0e1e Intel Pineview Atom N570 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a dual-core \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 1.6GHz \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1e\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e43\u0e19\u0e15\u0e31\u0e27 Intel GMA 3150 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a capacitive multitouch \u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e32\u0e40\u0e19\u0e25\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19 LCD HD \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e27\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 10.1 [&hellip;]<\/p>\n","protected":false},"author":1011016,"featured_media":566838,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5830,10086,476,9],"class_list":["post-98555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-atom-n570","tag-nav-10t","tag-tablet","tag-windows-7"],"views":327,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/98555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=98555"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/98555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/566838"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=98555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=98555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=98555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}