{"id":98511,"date":"2012-02-09T10:02:00","date_gmt":"2012-02-09T03:02:00","guid":{"rendered":"http:\/\/www.notebookspec.com\/web\/?p=98511"},"modified":"2012-02-09T10:02:00","modified_gmt":"2012-02-09T03:02:00","slug":"%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%9c%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a2%e0%b8%b1%e0%b8%94%e0%b9%84%e0%b8%9f%e0%b8%82%e0%b8%ad","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/98511-%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%9c%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%ab%e0%b8%a2%e0%b8%b1%e0%b8%94%e0%b9%84%e0%b8%9f%e0%b8%82%e0%b8%ad","title":{"rendered":"\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e44\u0e1f\u0e02\u0e2d\u0e07 Intel \u0e41\u0e25\u0e30 AMD \u0e2a\u0e39\u0e49\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b ARM \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49"},"content":{"rendered":"<p>\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19 CPU \u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e15\u0e48\u0e33\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07 Intel \u0e41\u0e25\u0e30 AMD \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e15\u0e48\u0e2a\u0e37\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48 CPU \u0e01\u0e34\u0e19\u0e44\u0e1f\u0e15\u0e48\u0e33\u0e1e\u0e27\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e49\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 CPU \u0e41\u0e1a\u0e1a ARM \u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e04\u0e48\u0e32\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e21\u0e31\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07?<\/p>\n<p>Intel \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e22\u0e38\u0e14\u0e1e\u0e31\u0e12\u0e19\u0e32 CPU \u0e01\u0e34\u0e19\u0e44\u0e1f\u0e19\u0e49\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e25\u0e07\u0e40\u0e25\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e31\u0e27\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e1b \u0e04\u0e37\u0e2d Medfield \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 32nm \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e25\u0e07\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a 11W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a Android 4.0 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e22\u0e31\u0e07\u0e2d\u0e2d\u0e01 CPU \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Atom \u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 10W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e41\u0e2b\u0e25\u0e48\u0e32\u0e07\u0e02\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e19\u0e31\u0e49\u0e19 Intel \u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 32nm Saltwell, 22nm Silvermont \u0e41\u0e25\u0e30 14nm Airmont \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/legitreviews.com\/images\/reviews\/news%20\/ARM_AMD_INTEL_logos.jpg\" alt=\"\" width=\"480\" height=\"202\"><\/p>\n<p>&nbsp;<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19 AMD \u0e01\u0e47\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Hondo \u0e0a\u0e34\u0e1e APU \u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e15\u0e48\u0e33\u0e41\u0e04\u0e48 5W \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e31\u0e19\u0e43\u0e19\u0e07\u0e32\u0e19 Computex 2012 \u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e08\u0e30\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e34\u0e1e APU 28nm \u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e41\u0e04\u0e48 2W \u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e2b\u0e31\u0e2a\u0e27\u0e48\u0e32 Temash \u0e19\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e31\u0e19\u0e43\u0e19\u0e1b\u0e35\u0e2b\u0e19\u0e49\u0e32<\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e31\u0e49\u0e07\u0e21\u0e27\u0e25\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e35 \u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e35\u0e46\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e41\u0e15\u0e48\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e07 \u0e01\u0e47\u0e04\u0e07\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e07\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01\u0e25\u0e07 \u0e1a\u0e27\u0e01\u0e01\u0e31\u0e1a\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e44\u0e1b\u0e43\u0e2a\u0e48\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e25\u0e07\u0e0b\u0e2d\u0e1f\u0e17\u0e4c\u0e41\u0e27\u0e23\u0e4c Windows 8 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30\u0e01\u0e47 \u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07 ARM \u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e35 2013 \u0e17\u0e35\u0e48\u0e04\u0e37\u0e1a\u0e04\u0e25\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e40\u0e23\u0e47\u0e27\u0e27\u0e31\u0e19<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: Digitimes<\/p>\n<p style=\"text-align:center\">\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19 CPU \u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e15\u0e48\u0e33\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07 Intel \u0e41\u0e25\u0e30 AMD \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e15\u0e48\u0e2a\u0e37\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48 CPU \u0e01\u0e34\u0e19\u0e44\u0e1f\u0e15\u0e48\u0e33\u0e1e\u0e27\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e49\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 CPU \u0e41\u0e1a\u0e1a ARM \u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e04\u0e48\u0e32\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e21\u0e31\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07? Intel \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e22\u0e38\u0e14\u0e1e\u0e31\u0e12\u0e19\u0e32 CPU \u0e01\u0e34\u0e19\u0e44\u0e1f\u0e19\u0e49\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e25\u0e07\u0e40\u0e25\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e31\u0e27\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e1b \u0e04\u0e37\u0e2d Medfield \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 32nm \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e25\u0e07\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a 11W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a Android 4.0 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e22\u0e31\u0e07\u0e2d\u0e2d\u0e01 CPU \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Atom \u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e44\u0e1f\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 10W \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e41\u0e2b\u0e25\u0e48\u0e32\u0e07\u0e02\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e19\u0e31\u0e49\u0e19 Intel \u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 32nm Saltwell, 22nm Silvermont \u0e41\u0e25\u0e30 14nm Airmont \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15Advertisement &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1011016,"featured_media":566835,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[21827,1838,456,308,4607],"class_list":["post-98511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-amd","tag-arm","tag-cpu","tag-intel","tag-notebook-"],"views":477,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/98511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=98511"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/98511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/566835"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=98511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=98511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=98511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}