{"id":841757,"date":"2025-11-03T11:13:25","date_gmt":"2025-11-03T04:13:25","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=841757"},"modified":"2025-11-03T11:13:28","modified_gmt":"2025-11-03T04:13:28","slug":"linux-radeon-driver-support","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/841757-linux-radeon-driver-support","title":{"rendered":"AMD \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d Radeon \u0e1a\u0e19 Linux \u0e17\u0e31\u0e49\u0e07 RDNA 1 \u0e41\u0e25\u0e30 RDNA 2 \u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e15\u0e48\u0e2d"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support.jpg\" alt=\"linux radeon driver support\" class=\"wp-image-841758\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support.jpg 1200w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-375x211.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-780x439.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-225x126.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-768x432.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-1024x576.jpg 1024w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-600x337.jpg 600w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/11\/251103_linux-radeon-driver-support-320x180.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure>\n\n\n\n<p>\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e04\u0e19\u0e40\u0e25\u0e48\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d <a href=\"https:\/\/notebookspec.com\/web\/topics\/amd\">AMD<\/a> \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1d\u0e31\u0e48\u0e07 Windows \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e08\u0e2b\u0e32\u0e22\u0e41\u0e27\u0e1a\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e2d\u0e1a \u0e2b\u0e25\u0e31\u0e07 AMD \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e27\u0e48\u0e32\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a RDNA 1 (RX 5000 series) \u0e41\u0e25\u0e30 RDNA 2 (RX 6000 series) \u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48 \u201cmaintenance mode\u201d \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e2b\u0e21\u0e14\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e21\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e22\u0e38\u0e14\u0e44\u0e1b\u0e40\u0e25\u0e22<\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e1a\u0e2a\u0e19\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e04\u0e37\u0e2d \u0e04\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 <strong>\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 Linux \u0e08\u0e30\u0e42\u0e14\u0e19\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22<\/strong><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<p>\u0e41\u0e25\u0e30\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e04\u0e37\u0e2d <strong>\u0e44\u0e21\u0e48\u0e42\u0e14\u0e19\u0e04\u0e23\u0e31\u0e1a!<\/strong><\/p>\n\n\n\n<p>\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Phoronix \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d Linux \u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e44\u0e14\u0e49\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32 <strong>\u0e1d\u0e31\u0e48\u0e07 Linux \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a<\/strong> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07 AMD \u0e1a\u0e19 Linux \u0e19\u0e31\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e22\u0e01\u0e08\u0e32\u0e01 Windows \u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e16\u0e21\u0e42\u0e21\u0e40\u0e14\u0e25\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e25\u0e01\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e22\u0e31\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e1a\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e38\u0e14<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Linux \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a \u201c\u0e42\u0e25\u0e01\u0e2d\u0e35\u0e01\u0e43\u0e1a\u201d<\/h3>\n\n\n\n<p>\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e02\u0e2d\u0e07 AMD \u0e1a\u0e19 Linux \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01 Windows \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e23\u0e27\u0e21\u0e44\u0e27\u0e49\u0e43\u0e19\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e25\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07 Linux \u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a GPU \u0e02\u0e2d\u0e07 AMD \u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e41\u0e1a\u0e1a proprietary drivers \u0e1a\u0e19 Windows<\/p>\n\n\n\n<p>\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d Linux \u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e48\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong>GCN 1.2<\/strong> (\u0e40\u0e0a\u0e48\u0e19 R9 390X \u0e41\u0e25\u0e30 R9 Fury X) \u0e2d\u0e22\u0e39\u0e48\u0e08\u0e19\u0e16\u0e36\u0e07\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e01\u0e48\u0e32\u0e21\u0e32\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e41\u0e15\u0e01\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01<\/p>\n\n\n\n<p>\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e27\u0e48\u0e32 <strong>\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1a\u0e19 Linux \u0e19\u0e31\u0e49\u0e19\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 Windows \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e19\u0e31\u0e22\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e08\u0e32\u0e01 AMDVLK \u0e2a\u0e39\u0e48 RADV: \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e04\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07<\/h3>\n\n\n\n<p>\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 AMD \u0e21\u0e35\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d <strong>AMDVLK<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07 AMD \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07 Linux \u0e22\u0e31\u0e07\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e47\u0e01\u0e15\u0e4c\u0e2d\u0e35\u0e01\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e37\u0e2d <strong>RADV<\/strong> \u0e17\u0e35\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e16\u0e21\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07 Valve, Google \u0e41\u0e25\u0e30 Red Hat<\/p>\n\n\n\n<p><strong>\u0e2a\u0e23\u0e38\u0e1b\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22\u0e01\u0e47\u0e04\u0e37\u0e2d:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>AMDVLK = \u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48 AMD \u0e17\u0e33\u0e40\u0e2d\u0e07<\/li>\n\n\n\n<li>RADV = \u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e17\u0e35\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e33 \u0e41\u0e15\u0e48\u0e42\u0e2b\u0e14\u0e01\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e22\u0e21\u0e01\u0e27\u0e48\u0e32<\/li>\n<\/ul>\n\n\n\n<p>\u0e08\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 <strong>15 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2025<\/strong> AMD \u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e34\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32 AMDVLK \u0e41\u0e25\u0e49\u0e27\u0e44\u0e1b\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 RADV \u0e40\u0e15\u0e47\u0e21\u0e15\u0e31\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07 RADV \u0e14\u0e35\u0e21\u0e32\u0e01\u0e08\u0e19\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e2a\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e47\u0e01\u0e15\u0e4c\u0e0b\u0e49\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n\n\n\n<p>\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?<br><strong>\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49 AMD \u0e2b\u0e22\u0e38\u0e14\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e2d\u0e07\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35<\/strong><\/p>\n\n\n\n<p>\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e01\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 Linux \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e32\u0e22 AMD<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e41\u0e25\u0e49\u0e27\u0e04\u0e19\u0e40\u0e25\u0e48\u0e19 Linux \u0e04\u0e27\u0e23\u0e01\u0e31\u0e07\u0e27\u0e25\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e2b\u0e21?<\/h3>\n\n\n\n<p>\u0e2a\u0e31\u0e49\u0e19 \u0e46 \u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d <strong>\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e04\u0e23\u0e31\u0e1a<\/strong><\/p>\n\n\n\n<p>\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c GPU \u0e1a\u0e19 Linux \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b<\/li>\n\n\n\n<li>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e2d\u0e17\u0e35\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 RADV \u0e43\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07<\/li>\n<\/ul>\n\n\n\n<p>\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e21\u0e49 AMD \u0e08\u0e30 \u201c\u0e25\u0e14\u0e1a\u0e17\u0e1a\u0e32\u0e17\u201d \u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e43\u0e19\u0e1a\u0e32\u0e07\u0e21\u0e34\u0e15\u0e34 \u0e41\u0e15\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28 Linux \u0e22\u0e31\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35<\/p>\n\n\n\n<p>\u0e43\u0e19\u0e41\u0e07\u0e48\u0e02\u0e2d\u0e07 <strong>Linux gaming<\/strong> \u0e01\u0e47\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e22\u0e31\u0e07\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22 \u0e46<\/li>\n\n\n\n<li>\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e40\u0e01\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e44\u0e14\u0e49<\/li>\n\n\n\n<li>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a Proton \u0e41\u0e25\u0e30 SteamOS \u0e41\u0e1a\u0e1a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e39\u0e1a<\/li>\n\n\n\n<li>\u0e04\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e31\u0e1a Linux ecosystem \u0e22\u0e31\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48<\/li>\n<\/ul>\n\n\n\n<p>\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 <strong>\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07 Linux gaming \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e38\u0e14<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e41\u0e25\u0e49\u0e27 Windows \u0e25\u0e48\u0e30?<\/h3>\n\n\n\n<p>AMD \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e41\u0e21\u0e49 RDNA 1 \u0e41\u0e25\u0e30 RDNA 2 \u0e1a\u0e19 Windows \u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e42\u0e2b\u0e21\u0e14\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e15\u0e48 <strong>\u0e22\u0e31\u0e07\u0e04\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e21\u0e2d\u0e22\u0e39\u0e48<\/strong> \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e46 \u0e41\u0e1a\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e41\u0e25\u0e49\u0e27<\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a Linux \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e21\u0e31\u0e19\u0e04\u0e19\u0e25\u0e30\u0e2a\u0e40\u0e01\u0e25\u0e40\u0e25\u0e22<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Windows = AMD \u0e04\u0e38\u0e21\u0e40\u0e15\u0e47\u0e21<\/li>\n\n\n\n<li>Linux = \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 + \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e08\u0e49\u0e32<\/li>\n<\/ul>\n\n\n\n<p>\u0e40\u0e25\u0e22\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e1e\u0e27\u0e48\u0e32 <strong>Linux \u0e21\u0e35 safety net \u0e2b\u0e19\u0e32\u0e01\u0e27\u0e48\u0e32<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e1a\u0e17\u0e2a\u0e23\u0e38\u0e1b<\/h3>\n\n\n\n<p>\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e04\u0e37\u0e2d\u0e04\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d Radeon \u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e1a\u0e19 Linux \u0e2d\u0e22\u0e39\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49<br>\u0e14\u0e35\u0e43\u0e08\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07 AMD \u0e1d\u0e31\u0e48\u0e07 Windows <strong>\u0e44\u0e21\u0e48\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e04\u0e38\u0e13<\/strong> \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e23\u0e34\u0e07\u0e04\u0e37\u0e2d Linux ecosystem \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a AMD \u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e0b\u0e49\u0e33 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 RADV \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22 \u0e46<\/p>\n\n\n\n<p>\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e19\u0e15\u0e23\u0e07 \u0e46 \u0e19\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32<br><strong>\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49 Windows \u0e01\u0e47\u0e22\u0e31\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e1a\u0e19 Linux \u0e44\u0e14\u0e49 \u201c\u0e41\u0e1a\u0e1a\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08\u201d \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22 \u0e46<\/strong><\/p>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tomshardware.com\/pc-components\/gpus\/linux-gamers-wont-be-affected-by-rx-5000-6000-series-driver-shift-amd-changes-limited-to-windows-thanks-to-separated-development\"  target=\"_blank\" rel=\"noopener\">tomshardware<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e04\u0e19\u0e40\u0e25\u0e48\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d AMD \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1d\u0e31\u0e48\u0e07 Windows \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e08\u0e2b\u0e32\u0e22\u0e41\u0e27\u0e1a\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e2d\u0e1a \u0e2b\u0e25\u0e31\u0e07 AMD \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e27\u0e48\u0e32\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a RDNA 1 (RX 5000 series) \u0e41\u0e25\u0e30 RDNA 2 (RX 6000 series) \u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48 \u201cmaintenance mode\u201d \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e2b\u0e21\u0e14\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e21\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e22\u0e38\u0e14\u0e44\u0e1b\u0e40\u0e25\u0e22 \u0e41\u0e15\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e1a\u0e2a\u0e19\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e04\u0e37\u0e2d \u0e04\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 Linux \u0e08\u0e30\u0e42\u0e14\u0e19\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22 Advertisement \u0e41\u0e25\u0e30\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e08\u0e23\u0e34\u0e07\u0e04\u0e37\u0e2d \u0e44\u0e21\u0e48\u0e42\u0e14\u0e19\u0e04\u0e23\u0e31\u0e1a! \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Phoronix \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d Linux \u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e44\u0e14\u0e49\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e1d\u0e31\u0e48\u0e07 Linux \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07 AMD \u0e1a\u0e19 Linux \u0e19\u0e31\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e22\u0e01\u0e08\u0e32\u0e01 Windows \u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e16\u0e21\u0e42\u0e21\u0e40\u0e14\u0e25\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e25\u0e01\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e22\u0e31\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e1a\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e38\u0e14 Linux \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a \u201c\u0e42\u0e25\u0e01\u0e2d\u0e35\u0e01\u0e43\u0e1a\u201d \u0e44\u0e14\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e02\u0e2d\u0e07 AMD \u0e1a\u0e19 Linux [&hellip;]<\/p>\n","protected":false},"author":1011030,"featured_media":841758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28823,16807],"tags":[24982,1034,31523,21829],"class_list":["post-841757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech-news","category-pc-news","tag-amd-readon","tag-linux","tag-news","tag-software"],"views":686,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/841757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011030"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=841757"}],"version-history":[{"count":1,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/841757\/revisions"}],"predecessor-version":[{"id":841773,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/841757\/revisions\/841773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/841758"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=841757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=841757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=841757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}