{"id":829619,"date":"2025-07-09T09:48:20","date_gmt":"2025-07-09T02:48:20","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=829619"},"modified":"2025-07-09T09:48:28","modified_gmt":"2025-07-09T02:48:28","slug":"apple-in-house-chipsets-leak","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/829619-apple-in-house-chipsets-leak","title":{"rendered":"Apple \u0e0b\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e16\u0e36\u0e07 7 \u0e23\u0e38\u0e48\u0e19! \u0e42\u0e04\u0e49\u0e14\u0e2b\u0e25\u0e38\u0e14\u0e43\u0e19 iOS 18 \u0e40\u0e1c\u0e22\u0e40\u0e1a\u0e32\u0e30\u0e41\u0e2a A19, M5, \u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 5G C2 \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak.jpg\" alt=\"Apple \" class=\"wp-image-829620\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak.jpg 1200w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-375x211.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-780x439.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-225x126.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-768x432.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-1024x576.jpg 1024w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-600x337.jpg 600w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2025\/07\/250709_NBS-apple-in-house-chipsets-a19-m5-c2-ios18-leak-320x180.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/notebookspec.com\/web\/topics\/apple\">Apple<\/a> \u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e42\u0e04\u0e49\u0e14 iOS 18 \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19 (Internal build) \u0e01\u0e47\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e34\u0e1b\u0e41\u0e1a\u0e1a In-house \u0e2d\u0e22\u0e39\u0e48\u0e16\u0e36\u0e07 7 \u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e1b\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c A19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a iPhone 17, \u0e0a\u0e34\u0e1b\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 M5 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a MacBook Pro \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e1b\u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 5G \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Apple Watch \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e40\u0e1a\u0e32\u0e30\u0e41\u0e2a\u0e08\u0e32\u0e01\u0e42\u0e04\u0e49\u0e14 iOS 18 \u0e41\u0e09\u0e0a\u0e34\u0e1b\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e1a\u0e1a\u0e08\u0e38\u0e43\u0e08<\/h3>\n\n\n\n<p>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 Bilibili \u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e01\u0e47\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e0b\u0e49\u0e33\u0e1a\u0e19 YouTube \u0e42\u0e14\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 <em>\u8bd7\u7bc7\u91cc\u7684\u843d\u82b1<\/em> \u0e44\u0e14\u0e49\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21\u0e41\u0e25\u0e30\u0e23\u0e2b\u0e31\u0e2a CPID \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e16\u0e39\u0e01\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e16\u0e31\u0e14\u0e44\u0e1b\u0e02\u0e2d\u0e07 Apple \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">1. A19 \u0e41\u0e25\u0e30 A19 Pro \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a iPhone 17<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A19 (\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21: Tilos):<\/strong> \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a iPhone 17 Air \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e38\u0e48\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c iPhone 17 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49<\/li>\n\n\n\n<li><strong>A19 Pro (\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21: Thera, CPID: T8150):<\/strong> \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19 iPhone 17 Pro \u0e41\u0e25\u0e30 iPhone 17 Pro Max \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e18\u0e07\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c<\/li>\n<\/ul>\n\n\n\n<p>\u0e0a\u0e34\u0e1b\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e32\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e08\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c AI \u0e2b\u0e23\u0e37\u0e2d Machine Learning \u0e17\u0e35\u0e48\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">2. M5 \u0e41\u0e25\u0e30 M5 Pro \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a MacBook Pro<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>M5 (\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21: Hidra)<\/strong><\/li>\n\n\n\n<li><strong>M5 Pro (\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21: Sotra)<\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e43\u0e19 MacBook Pro \u0e23\u0e38\u0e48\u0e19\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e02\u0e19\u0e32\u0e14 14 \u0e41\u0e25\u0e30 16 \u0e19\u0e34\u0e49\u0e27 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e21\u0e32\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48 M3 \u0e23\u0e38\u0e48\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01, \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e2d\u0e1b\u0e2a\u0e32\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e32\u0e2a\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e07\u0e44\u0e14\u0e49\u0e25\u0e37\u0e48\u0e19\u0e44\u0e2b\u0e25\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">3. \u0e0a\u0e34\u0e1b \u2018Bora\u2019 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Apple Watch \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Bora (CPID: T8320):<\/strong> \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Apple Watch Series 11 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e08\u0e32\u0e01\u0e42\u0e04\u0e49\u0e14 \u0e08\u0e30\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01 A18 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e1b\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49<\/li>\n<\/ul>\n\n\n\n<p>\u0e41\u0e21\u0e49\u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e04\u0e32\u0e14\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e0a\u0e34\u0e1b Bora \u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a AI \u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">4. \u0e0a\u0e34\u0e1b \u2018Proxima\u2019 \u0e23\u0e27\u0e21 Wi-Fi \u0e41\u0e25\u0e30 Bluetooth \u0e44\u0e27\u0e49\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27<\/h3>\n\n\n\n<p>\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07 Apple \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e0a\u0e34\u0e1b\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e34\u0e1b\u0e0a\u0e37\u0e48\u0e2d <strong>Proxima<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 Wi-Fi \u0e41\u0e25\u0e30 Bluetooth \u0e44\u0e27\u0e49\u0e43\u0e19\u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p>\n\n\n\n<p>\u0e19\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07 Apple \u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">5. \u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 5G \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u2018C2\u2019 \u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23<\/h3>\n\n\n\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 C1 \u0e43\u0e19 iPhone 16e \u0e44\u0e1b\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 Apple \u0e01\u0e47\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 <strong>C2<\/strong> \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e23\u0e38\u0e48\u0e19\u0e16\u0e31\u0e14\u0e44\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a iPhone 17e \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1b\u0e35 2026<\/p>\n\n\n\n<p>\u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 C2 \u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Apple \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/h3>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 Apple \u0e0b\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e16\u0e36\u0e07 7 \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07 \u201c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u201d \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e0a\u0e49\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25, \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22<\/p>\n\n\n\n<p>\u0e41\u0e21\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e08\u0e32\u0e01 Apple \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 \u0e01\u0e47\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e1b\u0e35 2025 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e1b\u0e35 2026<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u0e2a\u0e23\u0e38\u0e1b\u0e0a\u0e34\u0e1b\u0e17\u0e31\u0e49\u0e07 7 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e43\u0e19\u0e42\u0e04\u0e49\u0e14 iOS 18<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">\u0e0a\u0e37\u0e48\u0e2d\u0e0a\u0e34\u0e1b<\/th><th class=\"has-text-align-center\" data-align=\"center\">\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21<\/th><th class=\"has-text-align-center\" data-align=\"center\">\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">A19<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tilos<\/td><td class=\"has-text-align-center\" data-align=\"center\">iPhone 17 Air<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">A19 Pro<\/td><td class=\"has-text-align-center\" data-align=\"center\">Thera<\/td><td class=\"has-text-align-center\" data-align=\"center\">iPhone 17 Pro \/ Pro Max<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Hidra<\/td><td class=\"has-text-align-center\" data-align=\"center\">MacBook Pro 14&#8243;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">M5 Pro<\/td><td class=\"has-text-align-center\" data-align=\"center\">Sotra<\/td><td class=\"has-text-align-center\" data-align=\"center\">MacBook Pro 16&#8243;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Bora<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2013<\/td><td class=\"has-text-align-center\" data-align=\"center\">Apple Watch Series 11<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Proxima<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2013<\/td><td class=\"has-text-align-center\" data-align=\"center\">Wi-Fi + Bluetooth Combo<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">C2 5G<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2013<\/td><td class=\"has-text-align-center\" data-align=\"center\">iPhone 17e<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>\u0e2b\u0e32\u0e01 Apple \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19 \u0e01\u0e47\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/wccftech.com\/apple-working-on-seven-different-custom-chipsets-reveals-early-ios-18-code\/\"  target=\"_blank\" rel=\"noopener\">wccftech<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple \u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e42\u0e04\u0e49\u0e14 iOS 18 \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19 (Internal build) \u0e01\u0e47\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e34\u0e1b\u0e41\u0e1a\u0e1a In-house \u0e2d\u0e22\u0e39\u0e48\u0e16\u0e36\u0e07 7 \u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e1b\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c A19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a iPhone 17, \u0e0a\u0e34\u0e1b\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 M5 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a MacBook Pro \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e1b\u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 5G \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Apple Watch \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 Advertisement \u0e40\u0e1a\u0e32\u0e30\u0e41\u0e2a\u0e08\u0e32\u0e01\u0e42\u0e04\u0e49\u0e14 iOS 18 \u0e41\u0e09\u0e0a\u0e34\u0e1b\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e1a\u0e1a\u0e08\u0e38\u0e43\u0e08 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 Bilibili \u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e01\u0e47\u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e0b\u0e49\u0e33\u0e1a\u0e19 YouTube \u0e42\u0e14\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 \u8bd7\u7bc7\u91cc\u7684\u843d\u82b1 \u0e44\u0e14\u0e49\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e04\u0e49\u0e14\u0e40\u0e19\u0e21\u0e41\u0e25\u0e30\u0e23\u0e2b\u0e31\u0e2a CPID \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e16\u0e39\u0e01\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e16\u0e31\u0e14\u0e44\u0e1b\u0e02\u0e2d\u0e07 Apple \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49: 1. A19 \u0e41\u0e25\u0e30 A19 Pro [&hellip;]<\/p>\n","protected":false},"author":1011030,"featured_media":829620,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28823,11050,16807,19055],"tags":[19575,1297,391,31523],"class_list":["post-829619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech-news","category-other-news","category-pc-news","category-smartphone-news","tag-5g","tag-apple","tag-chip","tag-news"],"views":847,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/829619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011030"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=829619"}],"version-history":[{"count":1,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/829619\/revisions"}],"predecessor-version":[{"id":829621,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/829619\/revisions\/829621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/829620"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=829619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=829619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=829619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}