{"id":79150,"date":"2011-07-21T08:15:52","date_gmt":"2011-07-21T01:15:52","guid":{"rendered":"http:\/\/notebookspec.com\/web\/?p=79150"},"modified":"2011-07-22T00:15:19","modified_gmt":"2011-07-21T17:15:19","slug":"%e0%b8%a3%e0%b8%a7%e0%b8%a1%e0%b8%a1%e0%b8%b4%e0%b8%95%e0%b8%a3%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b9%82%e0%b8%a1%e0%b8%8a%e0%b8%b1%e0%b9%88%e0%b8%99%e0%b9%80%e0%b8%94%e0%b9%87%e0%b8%94%e0%b8%82%e0%b8%ad","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/79150-%e0%b8%a3%e0%b8%a7%e0%b8%a1%e0%b8%a1%e0%b8%b4%e0%b8%95%e0%b8%a3%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b9%82%e0%b8%a1%e0%b8%8a%e0%b8%b1%e0%b9%88%e0%b8%99%e0%b9%80%e0%b8%94%e0%b9%87%e0%b8%94%e0%b8%82%e0%b8%ad","title":{"rendered":"\u0e23\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e14\u0e47\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e48\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 Commart X Gen 2011"},"content":{"rendered":"<p>\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e48\u0e32\u0e27\u0e41\u0e25\u0e49\u0e27\u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e08\u0e30\u0e07\u0e07\u0e40\u0e25\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e27\u0e21\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e23\u0e23\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e08\u0e1a<\/p>\n<p><!--more--><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p><strong><span style=\"text-decoration: underline;\">MSI<\/span><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto; border: 0px;\" title=\"clip_image002\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/clip_image0022.jpg\" border=\"0\" alt=\"clip_image002\" hspace=\"12\" width=\"228\" height=\"473\" \/><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.facebook.com\/IamMSI\" name=\"_GoBack\"><\/a>MSI \u0e08\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e01!! \u0e43\u0e19\u0e07\u0e32\u0e19 Commart X?Gen 2011<\/p>\n<p>MSI \u0e40\u0e2d\u0e32\u0e43\u0e08\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e40\u0e01\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e40\u0e1e\u0e28\u0e17\u0e38\u0e01\u0e27\u0e31\u0e22\u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e16\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e40\u0e21\u0e32\u0e2a\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01 SteelSeries \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e38\u0e48\u0e19\u0e17\u0e47\u0e2d\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07 GT780 \u0e2b\u0e23\u0e37\u0e2d\u0e1f\u0e23\u0e35 VAT \u0e43\u0e19\u0e40\u0e01\u0e34\u0e48\u0e21\u0e21\u0e34\u0e48\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e22\u0e2d\u0e14\u0e19\u0e34\u0e22\u0e21 GE620, GX660, \u0e41\u0e25\u0e30 GX640 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e17\u0e31\u0e19\u0e17\u0e35 10% \u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 GT680 \u0e41\u0e25\u0e30 GT680R \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e47\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 U270 \u0e41\u0e25\u0e30 CR650 \u0e01\u0e47\u0e21\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e2d\u0e35\u0e01 2GB \u0e23\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19 4GB \u0e17\u0e31\u0e19\u0e17\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e41\u0e27\u0e30\u0e40\u0e27\u0e35\u0e22\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e39\u0e18\u0e02\u0e2d\u0e07 MSI \u0e43\u0e19\u0e07\u0e32\u0e19 Commart X?Gen 2011 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e46 \u0e0a\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1f\u0e23\u0e35!!! \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e41\u0e25\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e42\u0e1a\u0e23\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a  target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/IamMSI<\/a><\/p>\n<p>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 \u0e04\u0e38\u0e13\u0e40\u0e17\u0e1e\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 \u0e1a\u0e27\u0e23\u0e1e\u0e34\u0e0a\u0e22\u0e32\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c (080-269-5489) \u0e2b\u0e23\u0e37\u0e2d <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.facebook.com\/IamMSI\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/IamMSI<\/a><\/p>\n<p>?<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Acer<\/span><\/strong><\/p>\n<p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.commartshop.com\/brochure\/commart\/acer.zip\"  target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image124.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"258\" \/><\/a><\/p>\n<p>\u0e1b\u0e31\u0e48\u0e19\u0e23\u0e32\u0e04\u0e32 \u0e25\u0e14\u0e41\u0e2b\u0e25\u0e01 \u0e43\u0e19\u0e07\u0e32\u0e19 Acer Fair @ Commart X?Gen Thailand 2011<br \/>\n\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e22\u0e01\u0e02\u0e1a\u0e27\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e14\u0e2e\u0e2d\u0e15!!! \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e23\u0e32\u0e04\u0e32\u0e42\u0e14\u0e19 \u0e21\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e1a!!!<\/p>\n<p>ICONIA TAB A500 32GB \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e40\u0e1b\u0e47\u0e19 Andriod Honeycomb 3.1<br \/>\n\u0e40\u0e1e\u0e35\u0e22\u0e07 16,900.- (\u0e23\u0e32\u0e04\u0e32\u0e23\u0e27\u0e21 VAT \u0e41\u0e25\u0e49\u0e27)<\/p>\n<p>\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e02\u0e2d\u0e07\u0e41\u0e16\u0e21\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e22\u0e21\u0e32\u0e01<br \/>\n200 \u0e17\u0e48\u0e32\u0e19\u0e41\u0e23\u0e01 \u0e1f\u0e23\u0e35 !!! Wireless Keyboard + Mouse \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1,990 \u0e1a\u0e32\u0e17<\/p>\n<p>\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e01\u0e0b\u0e37\u0e49\u0e2d<\/p>\n<ol>\n<li>iconia tablet A500 docking station \u0e2b\u0e23\u0e37\u0e2d Wireless Keyboard + Mouse \u0e25\u0e14\u0e16\u0e36\u0e07 50% \u0e08\u0e32\u0e01\u0e23\u0e32\u0e04\u0e32\u0e40\u0e15\u0e47\u0e21 1990 \u0e1a\u0e32\u0e17 \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 995 \u0e1a\u0e32\u0e17<\/li>\n<li>Huawei E5836 3G Wi-Fi Router \u0e08\u0e32\u0e01\u0e23\u0e32\u0e04\u0e32\u0e40\u0e15\u0e47\u0e21 3,990.-? \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 990 \u0e1a\u0e32\u0e17<\/li>\n<\/ol>\n<p>\u0e1f\u0e23\u0e35 !!! Kreba backcover 4 \u0e2a\u0e35\u0e42\u0e14\u0e19\u0e43\u0e08<br \/>\n\u0e1f\u0e23\u0e35 !!! Download app \u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 150,000 app? \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e2b\u0e25\u0e14 app \u0e43\u0e2b\u0e49\u0e1f\u0e23\u0e35 \u0e01\u0e27\u0e48\u0e32 100 app<br \/>\n\u0e1f\u0e23\u0e35 !!! \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e25\u0e30\u0e42\u0e08\u0e23\u0e01\u0e23\u0e23\u0e21 1 \u0e1b\u0e35 \u0e40\u0e15\u0e47\u0e21 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 3,500 \u0e1a\u0e32\u0e17<\/p>\n<ul>\n<li>Notebook Aspire TimelineX \u0e23\u0e38\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 2 Gen Intel core i3 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e07\u0e32\u0e19 Commart \u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 19,900.- (\u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21 VAT)<\/li>\n<\/ul>\n<ul>\n<li>Notebook Aspire 4750Z-B942G50Mnkk\/C007_Mesh Black \u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 200 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e08\u0e32\u0e01\u0e1b\u0e01\u0e15\u0e34 12,900.- \u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 9,900.-<\/li>\n<\/ul>\n<ul>\n<li>Netbook Aspire One AO522 C5ckk \u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 100 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e08\u0e32\u0e01\u0e1b\u0e01\u0e15\u0e34 7,990.- \u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 5,990.-<\/li>\n<\/ul>\n<p>?<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Fujitsu<\/span><\/strong><\/p>\n<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36 \u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e23\u0e30\u0e14\u0e21\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e1e\u0e48\u0e27\u0e07\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e1a\u0e1a\u0e40\u0e15\u0e47\u0e21\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e1c\u0e48\u0e2d\u0e19 0% \u0e19\u0e32\u0e19 10 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35\u0e41\u0e1e\u0e01\u0e40\u0e01\u0e08\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e2b\u0e23\u0e39\u0e17\u0e35\u0e48\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e25\u0e07\u0e07\u0e32\u0e19 COMMART X?GEN 2011 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e17\u0e35\u0e48\u0e1a\u0e39\u0e18\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36 P17 Plenary Hall \u0e41\u0e25\u0e30 \u0e1a\u0e39\u0e18 A2 \u0e0a\u0e31\u0e49\u0e19 2 Hall C \u0e17\u0e35\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c<\/p>\n<p>\u0e19\u0e32\u0e22\u0e27\u0e23\u0e27\u0e38\u0e12\u0e34 \u0e42\u0e01\u0e28\u0e25\u0e01\u0e34\u0e08\u0e27\u0e07\u0e28\u0e4c \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36 \u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 COMMART X?GEN 2011 \u0e42\u0e14\u0e22\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e1c\u0e48\u0e2d\u0e19\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 0% \u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 10 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image120.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"300\" \/><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 COMMART X?GEN 2011 \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 \u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 LH531-Vi3S \u0e43\u0e0a\u0e49\u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Intel Core i3 \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2 \u0e41\u0e25\u0e30 \u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 LH531-Vi5 \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c Intel Core i5 \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e21 2GB \u0e41\u0e25\u0e30\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e16\u0e36\u0e07 500GB \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01 NVIDIA GeForce 410M \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c Optimus \u0e42\u0e14\u0e22<strong>\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 <\/strong><strong>LH531-Vi3S<\/strong> \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c Intel Core i3 \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e35\u0e14\u0e33\u0e27\u0e32\u0e27 <strong>\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e1e\u0e35\u0e22\u0e07 <\/strong><strong>16,900 \u0e1a\u0e32\u0e17 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 7%) \u0e41\u0e25\u0e30 \u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 LH531-Vi5<\/strong> \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c Intel Core i5 \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2 <strong>\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e1e\u0e35\u0e22\u0e07 19,900 \u0e1a\u0e32\u0e17 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 7%) \u0e08\u0e32\u0e01\u0e23\u0e32\u0e04\u0e32\u0e40\u0e14\u0e34\u0e21 23,900 \u0e1a\u0e32\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e1c\u0e48\u0e2d\u0e19 0% \u0e19\u0e32\u0e19 6 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/strong> \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 LH531-Vi5 \u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 3 \u0e2a\u0e35 \u0e04\u0e37\u0e2d \u0e2a\u0e35\u0e14\u0e33\u0e21\u0e31\u0e19\u0e27\u0e32\u0e27, \u0e2a\u0e35\u0e41\u0e14\u0e07\u0e40\u0e02\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e0a\u0e21\u0e1e\u0e39\u0e40\u0e08\u0e34\u0e14\u0e08\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1d\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e35\u0e40\u0e07\u0e34\u0e19\u0e27\u0e32\u0e27 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e04\u0e38\u0e49\u0e21\u0e23\u0e32\u0e04\u0e32<\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e22\u0e31\u0e07\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e32\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22<strong>\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e44\u0e25\u0e1f\u0e4c\u0e1a\u0e38\u0e4a\u0e01 <\/strong><strong>NH751<\/strong> \u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e14\u0e49\u0e27\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e08\u0e32\u0e01 Intel Core i7 \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01 NVIDIA GT525M \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c Optimus \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e2d\u0e35\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e41\u0e23\u0e21 8GB \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e16\u0e36\u0e07 640GB \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14 \u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e35\u0e14\u0e33\u0e27\u0e32\u0e27\u0e43\u0e19<strong>\u0e23\u0e32\u0e04\u0e32 <\/strong><strong>83,900 \u0e1a\u0e32\u0e17 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 7%) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e48\u0e2d\u0e19 0% \u0e19\u0e32\u0e19 10 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 Package \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e2b\u0e23\u0e39\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 3 \u0e27\u0e31\u0e19 2 \u0e04\u0e37\u0e19 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 42,600 \u0e1a\u0e32\u0e17<\/strong> \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e39\u0e18\u0e02\u0e2d\u0e07\u0e1f\u0e39\u0e08\u0e34\u0e15\u0e2a\u0e36\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e42\u0e0b\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e19\u0e33\u0e21\u0e32 Clearance Sales \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image122.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"325\" \/><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38: \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e02\u0e2d\u0e2a\u0e07\u0e27\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e23\u0e32\u0e1a\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14<\/strong><\/p>\n<p>?<!--nextpage--><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Toshiba<\/span><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image130.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"256\" \/><\/p>\n<p><strong>1. Upgrade RAM upto Max 8GB<\/strong><\/p>\n<ul>\n<li>All Pdual B940 &amp; Core i3 2ndGen-upgrade from 2GB to 4GB (Free 2GB)<\/li>\n<li>All Core i5 2ndGen-upgrade from 2GB to 6GB (Free 4GB)<\/li>\n<li>All Qosmio F60, Satellite M645 -upgrade from 4GB to 8GB (Free 4GB)<\/li>\n<li>Satellite L745-1103UT 18,990 Free VAT(Core i5\/No OS\/RAM 2GB\/HDD 500GB)- upgrade RAM \u0e08\u0e32\u0e01 2GB \u0e40\u0e1b\u0e47\u0e196GB (Free 4GB)- \u0e1c\u0e48\u0e2d\u0e19 0% \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e40\u0e14\u0e37\u0e2d\u0e19- \u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 !! \u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 1 \u0e1b\u0e35 + Transformer Flash Drive 4GB \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19 1,000 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01<\/li>\n<li>Satellite L745-1089XT 20,990 19,990(Core i5\/No OS\/RAM 2GB\/HDD 640GB\/NVIDIA)- upgrade RAM \u0e08\u0e32\u0e01 2GB \u0e40\u0e1b\u0e47\u0e196GB (Free 4GB) ? \u0e1c\u0e48\u0e2d\u0e19 0% \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e40\u0e14\u0e37\u0e2d\u0e19 ? \u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 !! \u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 1 \u0e1b\u0e35 + Transformer Flash Drive 4GB \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19 1,000 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image131.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"300\" \/><\/p>\n<p><strong> <\/strong><strong>2. Upgrade \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e40\u0e14\u0e34\u0e21<\/strong><\/p>\n<ul>\n<li>\u0e0b\u0e37\u0e49\u0e2d PortegeR700 Core i3-370 upgrade \u0e23\u0e38\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19 Core i5-460 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 31,900<\/li>\n<li>\u0e0b\u0e37\u0e49\u0e2d PortegeR700 Core i5-460 upgrade \u0e23\u0e38\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19 Core i5-560 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 33,900<\/li>\n<li>\u0e0b\u0e37\u0e49\u0e2d PortegeR700-2021U 36,900 31,900(Core i3\/Win Professional\/RAM 4GB\/HDD 500GB) -upgrade \u0e23\u0e38\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19 PortegeR700-1004U \u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e35\u0e22\u0e07 31,900(Core i5-460\/Win Home Premium\/RAM 4GB\/HDD 500GB)<\/li>\n<li>\u0e0b\u0e37\u0e49\u0e2d PortegeR700-1004U 38,900 33,900(Core i5-460\/Win Home Premium\/RAM 4GB\/HDD 500GB) -upgrade \u0e23\u0e38\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19 PortegeR700-2014U \u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e35\u0e22\u0e07 33,900(Core i5-560\/Win Professional\/RAM 4GB\/HDD 500GB)<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image132.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"277\" \/><\/p>\n<p><strong> <\/strong><strong>3. Upgrade \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22 Options \u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29<\/strong><\/p>\n<ul>\n<li>\u0e0b\u0e37\u0e49\u0e2d Netbook NB520\/NB500 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e23\u0e38\u0e48\u0e19 -\u0e41\u0e25\u0e01\u0e0b\u0e37\u0e49\u0e2d External DVD \u0e08\u0e32\u0e01 2,990 \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 990<\/li>\n<li>\u0e0b\u0e37\u0e49\u0e2d Satellite E300 -\u0e41\u0e25\u0e01\u0e0b\u0e37\u0e49\u0e2d NetGear Widi Adaptor \u0e08\u0e32\u0e01 4,990 \u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 1,990<\/li>\n<\/ul>\n<p><strong><\/strong><strong>4. Upgrade \u0e02\u0e2d\u0e07\u0e41\u0e16\u0e21 \u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e2a\u0e32\u0e2b\u0e23\u0e31\u0e1a1,000 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/strong><\/p>\n<ul>\n<li>\u0e0b\u0e37\u0e49\u0e2d Notebook \u0e43\u0e19\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Satellite L700 series, P series, E series, Qosmio F750 &amp; X770 series 1,000 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01\u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 !! \u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 1 \u0e1b\u0e35 + Transformer Flash Drive 4GB \u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 4,689<\/li>\n<\/ul>\n<p><strong>5. Warranty<\/strong><\/p>\n<ul>\n<li>\u0e0b\u0e37\u0e49\u0e2d\u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 1 \u0e1b\u0e35 (Local 01)-\u0e02\u0e22\u0e32\u0e22\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19 13 \u0e40\u0e14\u0e37\u0e2d\u0e19 -\u0e1f\u0e23\u0e35!! \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e32\u0e22\u0e08\u0e32\u0e01 \u0e17\u0e34\u0e1e\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e1b\u0e35<\/li>\n<li>\u0e0b\u0e37\u0e49\u0e2d\u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 2 \u0e1b\u0e35 (Local 02)-\u0e02\u0e22\u0e32\u0e22\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19 27 \u0e40\u0e14\u0e37\u0e2d\u0e19 -\u0e1f\u0e23\u0e35!! \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31<\/li>\n<\/ul>\n<p>?<\/p>\n<p><strong><span style=\"text-decoration: underline;\">ASUS<\/span><\/strong><\/p>\n<p>\u0e40\u0e2d\u0e0b\u0e38\u0e2a \u0e22\u0e01\u0e02\u0e1a\u0e27\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e17\u0e38\u0e01\u0e2b\u0e21\u0e27\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 \u0e2d\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e2d\u0e21\u0e42\u0e1e\u0e40\u0e19\u0e49\u0e19\u0e17\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e21\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d \u0e41\u0e25\u0e30\u0e44\u0e27\u0e25\u0e40\u0e25\u0e2a\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e23\u0e07\u0e46 \u0e13 \u0e1a\u0e39\u0e18\u0e40\u0e2d\u0e0b\u0e38\u0e2a \u0e43\u0e19\u0e07\u0e32\u0e19 ?\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c 2011? \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e43\u0e15\u0e49 \u0e1e\u0e1a\u0e01\u0e31\u0e19\u0e43\u0e19\u0e07\u0e32\u0e19 ?\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e44\u0e2d\u0e17\u0e35 2011? \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e19\u0e35\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p>\u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e \u0e27\u0e31\u0e0a\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e31\u0e2a\u0e0b\u0e38\u0e2a\u0e40\u0e17\u0e04 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 ?\u0e40\u0e2d\u0e0b\u0e38\u0e2a \u0e17\u0e22\u0e2d\u0e22\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e44\u0e2d\u0e17\u0e35\u0e15\u0e32\u0e21\u0e20\u0e32\u0e04\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e1f\u0e4c\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e32\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 -24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e19\u0e35\u0e49 \u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49 \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c<strong> <\/strong>\u0e07\u0e32\u0e19 <strong>?\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c 2011? <\/strong>\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e0a\u0e32\u0e27\u0e43\u0e15\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e0b\u0e38\u0e2a\u0e44\u0e14\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19 <strong>?\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e44\u0e2d\u0e17\u0e35 <\/strong><strong>2011? <\/strong>\u0e13<strong> <\/strong><strong>\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48?<\/strong><strong><\/strong><\/p>\n<p>?\u0e42\u0e14\u0e22\u0e17\u0e31\u0e49\u0e07 2 \u0e07\u0e32\u0e19 \u0e40\u0e2d\u0e0b\u0e38\u0e2a\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d ?\u0e21\u0e34\u0e19\u0e34\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04? \u0e23\u0e38\u0e48\u0e19 1215B \u0e02\u0e19\u0e32\u0e14\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14 \u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e02\u0e2d\u0e07 ?\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27? \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e21\u0e32\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e08\u0e2d\u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 ?\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e42\u0e19? \u0e1a\u0e32\u0e07\u0e40\u0e09\u0e35\u0e22\u0e1a \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e01\u0e27\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 178 \u0e2d\u0e07\u0e28\u0e32 \u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Good Design Award \u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d MATRIX GTX580 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e47\u0e2d\u0e01 \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e02\u0e38\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e0a\u0e31\u0e49\u0e19?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image123.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"330\" \/><\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e2d\u0e0b\u0e38\u0e2a\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e21\u0e32\u0e43\u0e19\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e32\u0e23\u0e30\u0e04\u0e38\u0e13\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 A43SJ-VX349D \u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e2d 14? HD Glare \u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Intel Core i5 2410 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01 GeForces GT 520M VRAM 1 GB \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c 500GB, RAM 4 GB \u0e41\u0e16\u0e21 Wireless Access Point (WL-330gE) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30 0% \u0e19\u0e32\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 10 \u0e40\u0e14\u0e37\u0e2d\u0e19 <strong>\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e1e\u0e35\u0e22\u0e07 18,900 \u0e1a\u0e32\u0e17 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21) <\/strong>\u0e1e\u0e25\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a<strong> <\/strong>Mini Notebook \u0e23\u0e38\u0e48\u0e19 1215B <strong>\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 <\/strong>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d 12? <strong>\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 9,990 \u0e1a\u0e32\u0e17<\/strong> \u0e25\u0e14\u0e08\u0e32\u0e01\u0e1b\u0e01\u0e15\u0e34 10,900 \u0e1a\u0e32\u0e17 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30 0% \u0e19\u0e32\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 6 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/p>\n<p>\u0e22\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e20\u0e32\u0e1e \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a <strong>PA Series \u0e08\u0e2d\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e04\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e<\/strong> \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e21\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14Maximus IV GENE-Z \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d MATRIX GTX580 \u0e08\u0e30\u0e44\u0e21\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e04\u0e2d\u0e22\u0e1c\u0e34\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d \u0e21\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e2b\u0e23\u0e37\u0e2d VGA card \u0e23\u0e32\u0e04\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 3,001 \u0e16\u0e36\u0e07 7,000 \u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35! \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 ROG \u0e2b\u0e23\u0e37\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 7,001 \u0e1a\u0e32\u0e17 \u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e23\u0e31\u0e1a\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e19\u0e32\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d Wireless Network<strong> <\/strong>(\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23) \u0e41\u0e25\u0e30 O! play \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e19\u0e32\u0e04\u0e38\u0e13\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e1f\u0e23\u0e35! \u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p>\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e48\u0e32\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e35\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35\u0e48\u0e1a\u0e39\u0e18\u0e40\u0e2d\u0e0b\u0e38\u0e2a \u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e16\u0e36\u0e07 10,000 \u0e1a\u0e32\u0e17 \u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e44\u0e1b-\u0e01\u0e25\u0e31\u0e1a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f-\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f-\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e25\u0e30 2 \u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 10,000 \u0e1a\u0e32\u0e17<\/p>\n<p>\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e23\u0e32\u0e04\u0e32\u0e42\u0e14\u0e19\u0e43\u0e08 \u0e23\u0e2d\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e39\u0e48 \u0e13 \u0e1a\u0e39\u0e18\u0e40\u0e2d\u0e0b\u0e38\u0e2a (P6) \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13 \u0e40\u0e1e\u0e25\u0e19\u0e32\u0e23\u0e35\u0e2e\u0e2d\u0e25 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e02\u0e27\u0e32\u0e08\u0e32\u0e01 Main Foyer (\u0e2b\u0e19\u0e49\u0e32\u0e22\u0e31\u0e01\u0e29\u0e4c) \u0e43\u0e19\u0e07\u0e32\u0e19 ?\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c 2011? \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e15\u0e34\u0e4c \u0e41\u0e25\u0e30 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e27\u0e01\u0e44\u0e2d\u0e17\u0e35\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e07\u0e32\u0e19 \u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e44\u0e2d\u0e17\u0e35 2011 \u0e2b\u0e23\u0e37\u0e2d Southern IT 2011 \u0e13 <strong>\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21<\/strong><strong>\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/strong><strong> <\/strong>\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p>?<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Lenovo<\/span><\/strong><\/p>\n<p><strong>\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27<\/strong> \u0e22\u0e01\u0e02\u0e1a\u0e27\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e21\u0e32\u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e07\u0e32\u0e19 <strong>?Commart X?Gen Thailand 2011? <\/strong>\u0e2d\u0e32\u0e17\u0e34 \u0e40\u0e15\u0e47\u0e21\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e23\u0e07\u0e40\u0e15\u0e47\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e31\u0e1a <strong>IdeadPad Y470 \u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48<\/strong> <strong>24<\/strong>,<strong>900\u0e1a\u0e32\u0e17 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14<\/strong> \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e14\u0e43\u0e2a\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e34\u0e2a\u0e15\u0e49\u0e32\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong>IdeadPad Z470 \u0e23\u0e32\u0e04\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 20<\/strong>,<strong>900 \u0e1a\u0e32\u0e17*<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19 2<strong> <\/strong>\u0e1b\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e01\u0e31\u0e1a <strong>IdeadPad G470 \u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 15<\/strong>,<strong>900 \u0e1a\u0e32\u0e17*<\/strong> \u0e08\u0e32\u0e01\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e01\u0e15\u0e34 17<strong>,<\/strong>000 \u0e1a\u0e32\u0e17* \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e04\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e17\u0e19\u0e17\u0e32\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a <strong>ThinkPad X201i \u0e23\u0e32\u0e04\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 23<\/strong>,<strong>900 \u0e1a\u0e32\u0e17*<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 Lenovo USB Portable DVD drive? <strong>ThinkPad Edge E420 \u0e23\u0e32\u0e04\u0e32 20<\/strong>,<strong>900 \u0e1a\u0e32\u0e17*<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e19\u0e32\u0e04\u0e38\u0e13\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\u0e41\u0e25\u0e30\u0e25\u0e38\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19\u0e04\u0e37\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 50% \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e1e\u0e35\u0e22\u0e1a \u0e1e\u0e25\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e1a\u0e39\u0e18\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e13 Plenery Hall<strong> <\/strong>\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13 A9 \u0e42\u0e0b\u0e19 C<strong> <\/strong>\u0e0a\u0e31\u0e49\u0e19 2 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21-24 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<strong> <\/strong>(*\u0e23\u0e32\u0e04\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"display: block; float: none; margin-left: auto; margin-right: auto; border: 0px;\" title=\"image\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2011\/07\/image136.png\" border=\"0\" alt=\"image\" width=\"400\" height=\"332\" \/><\/p>\n<p>\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e2d\u0e07\u0e15\u0e48\u0e2d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e16\u0e48\u0e32\u0e22 \u0e20\u0e32\u0e1e\u0e04\u0e38\u0e13\u0e04\u0e39\u0e48\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04 Lenovo Lover \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 100 \u0e17\u0e48\u0e32\u0e19\u0e41\u0e23\u0e01 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e15\u0e23 &#8220;Are you Lenovo? Movie Gift Card 1 \u0e43\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e0a\u0e21\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2dSF\u0e08\u0e33\u0e19\u0e27\u0e19 4 \u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 Transformer3 ?Do The extraordinary with Lenovo&#8221; 1\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e04\u0e19\u0e17\u0e35\u0e48 101-300 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 Transformer3 ?Do The extraordinary with Lenovo&#8221; \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e15\u0e31\u0e27 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 Facebook Lenovo Lover \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 &#8211; 15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 <strong><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e04\u0e25\u0e34\u0e01\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e33\u0e16\u0e32\u0e21\u0e07\u0e48\u0e32\u0e22\u0e46\u0e40\u0e1e\u0e35\u0e22\u0e07 1 \u0e02\u0e49\u0e2d \u0e43\u0e19 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.lenovodomachines.com\/th\"  target=\"_blank\" rel=\"noopener\">www.lenovodomachines.com\/th<\/a><strong> <\/strong>\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e25\u0e38\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1c\u0e39\u0e49\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14\u0e41\u0e25\u0e30 &#8220;For those who do&#8221; USB Flash Drive \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 16 GB \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 <strong>? <\/strong>15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2554 \u0e19\u0e35\u0e49 \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<strong><\/strong><\/p>\n<p>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e42\u0e17\u0e23.02-6896451 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e17\u0e23.1800-060-087 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e40\u0e27\u0e1b\u0e44\u0e0b\u0e15\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.lenovo.com\/th\"  target=\"_blank\" rel=\"noopener\">www.lenovo.com\/th<\/a> \u0e2b\u0e23\u0e37\u0e2d <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/news.lenovo.com\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/news.lenovo.com<\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19 Facebook Lenovo Lover<strong> <\/strong>\u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.facebook.com\/lenovo.lover\"  target=\"_blank\" rel=\"noopener\">www.facebook.com\/lenovo.lover<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e48\u0e32\u0e27\u0e41\u0e25\u0e49\u0e27\u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e08\u0e30\u0e07\u0e07\u0e40\u0e25\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e27\u0e21\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e23\u0e23\u0e1e\u0e02\u0e48\u0e32\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e08\u0e1a Advertisement<\/p>\n","protected":false},"author":1011016,"featured_media":561731,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,6],"tags":[2566,6831,6861],"class_list":["post-79150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","category-hot-promotion","tag-commart-promotion","tag-commart-x-gen-2011","tag-6861"],"views":5673,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/79150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=79150"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/79150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/561731"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=79150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=79150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=79150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}