{"id":766560,"date":"2024-05-27T09:58:26","date_gmt":"2024-05-27T02:58:26","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=766560"},"modified":"2024-05-27T09:58:29","modified_gmt":"2024-05-27T02:58:29","slug":"photo-translate-applications-suggestion","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/766560-photo-translate-applications-suggestion","title":{"rendered":"\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e34\u0e18\u0e35\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u0e27\u0e34\u0e18\u0e35\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e41\u0e1b\u0e25\u0e41\u0e21\u0e48\u0e19 \u0e17\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e20\u0e32\u0e29\u0e32 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\" class=\"wp-image-767268\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024.jpg 1200w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-375x211.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-780x439.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-225x126.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-768x432.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-1024x576.jpg 1024w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-600x337.jpg 600w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/TranslateImage2024-320x180.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<p>\u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01 \u0e41\u0e16\u0e21\u0e22\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e16\u0e34\u0e48\u0e19\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e01\u0e47\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e19\u0e31\u0e49\u0e19\u0e25\u0e14\u0e25\u0e07\u0e40\u0e22\u0e2d\u0e30 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.notebookspec.com\" >NotebookSPEC<\/a> \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e21\u0e35\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e08\u0e30\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e1f\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e19\u0e33\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e2b\u0e25\u0e31\u0e01\u0e46 \u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e2d\u0e48\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 <\/li><li>\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 Google Translate \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e43\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 Google Translate \u0e40\u0e2d\u0e07\u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e31\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2a\u0e33\u0e19\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e25\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e14\u0e35\u0e19\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e14\u0e35\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e32\u0e07 Google \u0e40\u0e2d\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32 Translate \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32 Translate \u0e01\u0e47\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e46 \u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"#k\">\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e1a\u0e19 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/a><\/strong><\/li><li><a href=\"#a\"><strong>\u0e27\u0e34\u0e18\u0e35\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/strong><\/a><ul><li><a href=\"#h\"><strong>\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/strong><\/a><ol><li><strong><a class=\"rank-math-link\" href=\"#b\">Google Translate<\/a><\/strong><\/li><li><strong><a class=\"rank-math-link\" href=\"#c\">Google Lens<\/a><\/strong><\/li><li><strong><a class=\"rank-math-link\" href=\"#d\">U-Dictionary<\/a><\/strong><\/li><li><strong><a class=\"rank-math-link\" href=\"#e\">Microsoft Translator<\/a><\/strong><\/li><li><strong><a class=\"rank-math-link\" href=\"#f\">Naver Papago<\/a><\/strong><\/li><li><strong><a class=\"rank-math-link\" href=\"#g\">Scan &amp; Translate<\/a><\/strong><\/li><li><strong><a href=\"#i\">Translate<\/a><\/strong><\/li><\/ol><\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"k\">\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e1a\u0e19 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"656\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\" class=\"wp-image-767441\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1.jpg 1536w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1-375x160.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1-780x333.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1-225x96.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1-768x328.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl1-320x137.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07 Google Translate \u0e1a\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48 &#8220;<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/translate.google.com\/?sl=auto&amp;tl=th&amp;op=images\"  target=\"_blank\" rel=\"noopener\"><strong>Google \u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32<\/strong><\/a>&#8221; (\u0e2b\u0e23\u0e37\u0e2d Google &gt;&gt; Translate &gt;&gt; Image)<\/li><li>\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e25\u0e32\u0e07\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e21\u0e32\u0e27\u0e32\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e31\u0e1e\u0e42\u0e2b\u0e25\u0e14\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e27\u0e32\u0e07\u0e08\u0e32\u0e01\u0e04\u0e25\u0e34\u0e1b\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"650\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Google Translate\" class=\"wp-image-767443\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2.jpg 1537w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2-375x159.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2-780x330.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2-225x95.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2-768x325.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/tsl2-320x135.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2b\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/li><\/ul>\n\n\n\n<p>\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e44\u0e14\u0e49\u0e1f\u0e23\u0e35\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07 Google \u0e41\u0e25\u0e49\u0e27 \u0e41\u0e16\u0e21\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e14\u0e35\u0e21\u0e32\u0e01\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"a\">\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e1c\u0e48\u0e32\u0e19<a href=\"https:\/\/notebookspec.com\/web\/?s=%E0%B9%81%E0%B8%AD%E0%B8%9E%E0%B8%9E%E0%B8%A5%E0%B8%B4%E0%B9%80%E0%B8%84%E0%B8%8A%E0%B8%B1%E0%B8%99\">\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h\">\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/h3>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e1f\u0e23\u0e35<\/th><th class=\"has-text-align-center\" data-align=\"center\">\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a<\/th><th class=\"has-text-align-left\" data-align=\"left\">\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08<\/th><th class=\"has-text-align-left\" data-align=\"left\">\u0e02\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#b\" class=\"rank-math-link\">Google Translate<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<br>Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49<br>&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01<br>&#8211; \u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04 \u0e27\u0e25\u0e35 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e41\u0e2a\u0e25\u0e07 \u0e04\u0e33\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e31\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e14\u0e35\u0e19\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e19\u0e33\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#c\" class=\"rank-math-link\">Google Lens<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49<br>&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30 Android \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a iOS \u0e19\u0e31\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e41\u0e2d\u0e1e Google<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#d\" class=\"rank-math-link\">U-Dictionary<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<br>Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 <br>&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e23\u0e35\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e33\u0e01\u0e31\u0e14\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e44\u0e27\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#e\" class=\"rank-math-link\">Microsoft Translator<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<br>Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<br>&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1b\u0e25\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e21\u0e48 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e17\u0e35\u0e48 Close \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e40\u0e21\u0e19\u0e39\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e01\u0e14\u0e17\u0e35\u0e48\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e22\u0e38\u0e48\u0e07\u0e22\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e07<br>&#8211; \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e1a\u0e1a Real-Time \u0e44\u0e14\u0e49<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#f\" class=\"rank-math-link\">Naver Papago<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<br>Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e41\u0e1b\u0e25\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35<br>&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#g\" class=\"rank-math-link\">Scan &amp; Translate<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<br>Android<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22<br>&#8211; \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e21\u0e35\u0e42\u0e06\u0e29\u0e13\u0e32<br>&#8211; \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e23\u0e35\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e33\u0e01\u0e31\u0e14\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e44\u0e27\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"#i\">Translate<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">iOS<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22<br>&#8211; \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<\/td><td class=\"has-text-align-left\" data-align=\"left\">&#8211; \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e41\u0e2a\u0e25\u0e07 \u0e04\u0e33\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e31\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e14\u0e35\u0e19\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e19\u0e33\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b\">1. Google Translate<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t1.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e1f\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\" class=\"wp-image-632459\" width=\"193\" height=\"186\"\/><\/figure><\/div>\n\n\n\n<p>\u0e21\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48<a href=\"https:\/\/notebookspec.com\/web\/?s=%E0%B9%81%E0%B8%AD%E0%B8%9E\">\u0e41\u0e2d\u0e1e<\/a>\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e41\u0e2d\u0e1e\u0e41\u0e23\u0e01\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07 Google Translate \u0e41\u0e2d\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30 Google Translate \u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e14\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 Google \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e16\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e42\u0e25\u0e01 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e27\u0e48\u0e32 133 \u0e20\u0e32\u0e29\u0e32 <em>(11 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2022) <\/em>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c (<a class=\"rank-math-link\" href=\"https:\/\/notebookspec.com\/web\/532397-google-translate-features\"><em>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07 Google Translate \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/em><\/a>)&nbsp;<\/p>\n\n\n\n<p>\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e22\u0e32\u0e27 \u0e46 \u0e41\u0e16\u0e21\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e23\u0e39\u0e1b\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25 (Google Lens) \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e2d\u0e1e\u0e01\u0e47\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e41\u0e1a\u0e1a Real-time \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 Google Translate \u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e19\u0e34\u0e22\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e23\u0e21\u0e35\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a Real-Time \u0e40\u0e25\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e1b\u0e25\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e01\u0e47\u0e44\u0e14\u0e49<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/th\/app\/google-translate\/id414706506\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\"><strong>\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/strong><\/a><\/li><li><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.google.android.apps.translate&amp;hl=en\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\"><strong>\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19:<\/strong> <strong>Android<\/strong><\/a><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802541-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Google Translate\" class=\"wp-image-632520\" width=\"345\" height=\"230\"\/><\/figure><\/div>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\u0e01\u0e47\u0e08\u0e30\u0e40\u0e08\u0e2d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e01\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e23\u0e39\u0e1b\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e2b\u0e23\u0e37\u0e2d Camera \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/li><li>\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e41\u0e01\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e08\u0e32\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e19\u0e33\u0e21\u0e32\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e41\u0e01\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30 Import \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e41\u0e1b\u0e25\u0e01\u0e47\u0e44\u0e14\u0e49<ul><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e21\u0e19\u0e39 Instant \u0e19\u0e31\u0e49\u0e19 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a Real-Time \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e23\u0e32\u0e19\u0e33\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e08\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e01\u0e47\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e40\u0e25\u0e22<\/li><li>\u0e40\u0e21\u0e19\u0e39 Scan \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e41\u0e25\u0e49\u0e27\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32<\/li><li>\u0e40\u0e21\u0e19\u0e39 Import \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e43\u0e19\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e08\u0e32\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2d\u0e35\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c\">2. Google Lens<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"182\" height=\"185\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t2.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Google Lens\" class=\"wp-image-632460\"\/><\/figure><\/div>\n\n\n\n<p>Google Lens \u0e19\u0e31\u0e49\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e14\u0e22 Google \u0e41\u0e22\u0e01\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01 Google Translate \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e, \u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e1a\u0e1a Real-time \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 Ai \u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\/\u0e2a\u0e20\u0e32\u0e19\u0e17\u0e35\u0e48\/\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e16\u0e48\u0e32\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19\u0e21\u0e32\u0e01 \u0e46 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e1e\u0e2f \u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 Google Lens \u0e21\u0e35\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e41\u0e1a\u0e1a Real-time&nbsp;<\/li><li>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e01\u0e27\u0e48\u0e32 100 \u0e20\u0e32\u0e29\u0e32<\/li><li>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 Google Lens \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2f\u0e25\u0e2f \u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e16\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49<\/li><li>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e0a\u0e37\u0e48\u0e2d \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34 (\u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e15\u0e36\u0e01\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e46 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07) \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e40\u0e21\u0e19\u0e39\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/us\/app\/google\/id284815942\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS (\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 Google Translate \u0e2b\u0e23\u0e37\u0e2d Google)<\/a><\/strong><\/li><li><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.google.ar.lens\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\"><strong>\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19:<\/strong> <strong>Android<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>Google Lens \u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d (\u0e17\u0e35\u0e48\u0e2d\u0e48\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e07) \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19 Google Translate \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e04\u0e31\u0e14\u0e25\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e14\u0e2a\u0e38\u0e14 \u0e46 \u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e1e\u0e2f \u0e19\u0e35\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e31\u0e14\u0e25\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c&nbsp;\u201ccopy to computer\u201d \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35 Google Chrome (\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14) \u0e41\u0e25\u0e30 Log in \u0e1a\u0e31\u0e0d\u0e0a\u0e35 Google \u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e43\u0e19\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19&nbsp;\u0e41\u0e16\u0e21\u0e43\u0e19 Google Lens \u0e01\u0e47\u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e01\u0e27\u0e48\u0e32 100+ \u0e20\u0e32\u0e29\u0e32<\/p>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/05\/139796.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35\" class=\"wp-image-521235\" width=\"217\" height=\"471\"\/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e40\u0e25\u0e22 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 Google Lens \u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23&nbsp;<strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.google.ar.lens\"  target=\"_blank\" rel=\"noreferrer noopener\">Android<\/a>&nbsp;<\/strong>\u0e41\u0e25\u0e30<strong>&nbsp;<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/us\/app\/google\/id284815942\"  target=\"_blank\" rel=\"noreferrer noopener\">iOS<\/a>&nbsp;<\/strong>(\u0e41\u0e15\u0e48\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c \u2018Listen\u2019 \u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e04\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 Android \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a iOS \u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e01\u0e14\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e &gt;&gt; \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e47\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 &gt;&gt; \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e23\u0e39\u0e1b\u0e44\u0e1f\u0e25\u0e4c\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 &gt;&gt; \u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e25\u0e38\u0e21\u0e14\u0e33\u0e17\u0e35\u0e48\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 (\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e04\u0e25\u0e38\u0e21\u0e14\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01 \u201c\u0e04\u0e31\u0e14\u0e25\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u201d (\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e35\u0e49\u0e16\u0e49\u0e32\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Google \u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 Log in \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 Chome \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e08\u0e30\u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c \u2018\u0e04\u0e31\u0e14\u0e25\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u2019 \u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e31\u0e14\u0e25\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22) \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/li><\/ul>\n\n\n\n<p>\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e19\u0e32\u0e17\u0e35\u0e40\u0e23\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e41\u0e25\u0e49\u0e27 \u0e07\u0e48\u0e32\u0e22\u0e21\u0e32\u0e01 \u0e46 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d\u0e19\u0e31\u0e49\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e34\u0e14\u0e40\u0e1e\u0e35\u0e49\u0e22\u0e19\u0e44\u0e1b\u0e1a\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e02\u0e35\u0e22\u0e19\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d\u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e23\u0e08\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e48\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e19\u0e31\u0e49\u0e19 Google Lens \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01 \u0e46 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e2d\u0e22\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e37\u0e2d<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"d\">3. U-Dictionary<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t3.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 U-Dictionary\" class=\"wp-image-632462\" width=\"188\" height=\"188\"\/><\/figure><\/div>\n\n\n\n<p><a href=\"https:\/\/notebookspec.com\/web\/735956-8-app-voice-translate-2024\">\u0e41\u0e2d\u0e1e\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32<\/a>\u0e08\u0e32\u0e01 Oxford Dictionary \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e19\u0e31\u0e49\u0e19\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e2f \u0e22\u0e31\u0e07\u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e14\u0e49\u0e27\u0e22 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e1d\u0e36\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19\u0e02\u0e48\u0e32\u0e27\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e01\u0e34\u0e25\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35 English Corner \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1d\u0e36\u0e01\u0e17\u0e31\u0e01\u0e29\u0e30\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14 \u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e01\u0e23\u0e21\u0e21\u0e48\u0e32 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1d\u0e36\u0e01\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e40\u0e25\u0e22 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29&nbsp;<\/p>\n\n\n\n<p>\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e27\u0e48\u0e32 108 \u0e20\u0e32\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e27\u0e48\u0e32 58 \u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e41\u0e01\u0e23\u0e21\u0e21\u0e48\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/ug\/app\/u-dictionary\/id1319771553\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/a><\/strong><\/li><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.youdao.hindict&amp;hl=en\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: Android<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802547-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b U-Dictionary\" class=\"wp-image-632524\" width=\"345\" height=\"230\"\/><\/figure><\/div>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e40\u0e25\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 Google Translate \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e04\u0e37\u0e2d\u0e21\u0e35\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2a\u0e48\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e33 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e19\u0e31\u0e49\u0e19\u0e46 <\/li><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e23\u0e32\u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e23\u0e39\u0e1b\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e2b\u0e23\u0e37\u0e2d Camera Translation \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 3 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e46 <ul><li>Word \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e19\u0e33\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 Lock \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e01\u0e47\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e25\u0e47\u0e2d\u0e01\u0e44\u0e27\u0e49\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e40\u0e25\u0e22<\/li><li>Text: \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04 (\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19 Upgrade \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e23\u0e35\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49)<\/li><li>Object: \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e08\u0e32\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 (\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19 Upgrade \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e23\u0e35\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49)<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"e\">4. Microsoft Translator<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t4.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Microsoft Translator\" class=\"wp-image-632463\" width=\"184\" height=\"187\"\/><\/figure><\/div>\n\n\n\n<p>\u0e41\u0e2d\u0e1e\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01 Microsoft \u0e17\u0e35\u0e48\u0e17\u0e33\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e2f \u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e01\u0e27\u0e48\u0e32 70 \u0e20\u0e32\u0e29\u0e32 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07 &#8216;Phrasebook&#8217; \u0e17\u0e35\u0e48\u0e08\u0e30\u0e04\u0e2d\u0e22\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e01\u0e14\u0e4c\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04 \u0e04\u0e33\u0e1e\u0e39\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1a\u0e48\u0e2d\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u0e40\u0e0a\u0e48\u0e19 Travel, Dining, Time, Date \u0e2f\u0e25\u0e2f&nbsp;<\/p>\n\n\n\n<p>\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e2f \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e2f \u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e21\u0e32\u0e43\u0e2b\u0e49 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e1a\u0e1a\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23 Join Group \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1b\u0e25\u0e41\u0e1a\u0e1a Real-time \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e21\u0e49\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e21\u0e32\u0e01\u0e46&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/us\/app\/microsoft-translator\/id1018949559\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/a><\/strong><\/li><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.translator&amp;hl=en\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: Android<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"460\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b Microsoft Translator\" class=\"wp-image-632525\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side.jpg 920w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side-375x188.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side-780x390.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side-225x113.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side-768x384.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802556-side-320x160.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e07\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e14\u0e46 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e23\u0e39\u0e1b\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 <\/li><li>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e1a\u0e1a Real-Time \u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e21\u0e48\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e14\u0e17\u0e35\u0e48\u0e40\u0e21\u0e19\u0e39 Close \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e14\u0e17\u0e35\u0e48\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e22\u0e38\u0e48\u0e07\u0e22\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22<\/li><li>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"f\">5. Naver Papago<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t5.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Naver Papago\" class=\"wp-image-632465\" width=\"178\" height=\"187\"\/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Naver Papago \u0e15\u0e49\u0e2d\u0e07\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19<a href=\"https:\/\/notebookspec.com\/web\/topics\/%E0%B9%81%E0%B8%AD%E0%B8%9E%E0%B8%9F%E0%B8%A3%E0%B8%B5\">\u0e41\u0e2d\u0e1e\u0e1f\u0e23\u0e35<\/a> \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e21\u0e32\u0e01\u0e46 \u0e2d\u0e35\u0e01\u0e41\u0e2d\u0e1e\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e25\u0e22 \u0e42\u0e14\u0e22\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a LINE \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e0a\u0e17\u0e2a\u0e19\u0e19\u0e32\u0e22\u0e2d\u0e14\u0e2e\u0e34\u0e15\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e25\u0e22 \u0e41\u0e15\u0e48\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 \u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e44\u0e21\u0e48\u0e40\u0e22\u0e2d\u0e30\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e19\u0e41\u0e2d\u0e1e\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22 <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/us\/app\/naver-papago-ai-translator\/id1147874819\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/a><\/strong><\/li><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.naver.labs.translator&amp;hl=en&amp;gl=US\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: Android<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802561-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b Never Papago\" class=\"wp-image-632526\" width=\"230\" height=\"232\"\/><\/figure><\/div>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e40\u0e25\u0e22 \u0e04\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e23\u0e32\u0e40\u0e02\u0e49\u0e32\u0e41\u0e2d\u0e1e\u0e21\u0e32 \u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\u0e01\u0e47\u0e08\u0e30\u0e40\u0e08\u0e2d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e14\u0e17\u0e35\u0e48\u0e40\u0e21\u0e19\u0e39 Image \u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e21\u0e19\u0e39\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 <\/li><li>\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e01\u0e14\u0e17\u0e35\u0e48\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c Translate all \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c Translate partially<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"g\">6. Scan &amp; Translate<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/t6.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35  Scan &amp; Translate\" class=\"wp-image-632468\" width=\"194\" height=\"195\"\/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e2d\u0e1e Scan &amp; Translate \u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e22 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e22\u0e2d\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e40\u0e25\u0e22 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e31\u0e07\u0e17\u0e33\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e14\u0e35\u0e19\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e07\u0e25\u0e33\u0e14\u0e31\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e19\u0e35\u0e49\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e41\u0e2d\u0e1e\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e25\u0e22 <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/th\/app\/scan-translate-text-grabber\/id845139175\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/a><\/strong><\/li><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.datacomprojects.scanandtranslate&amp;hl=en&amp;gl=US\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: Android<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1150\" height=\"460\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Scan &amp; Translate\" class=\"wp-image-632527\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side.jpg 1150w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side-375x150.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side-780x312.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side-225x90.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side-768x307.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2022\/01\/S__29802566-side-320x128.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"i\">7. Translate<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt1.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Translate iPhone\" class=\"wp-image-751361\" width=\"194\" height=\"184\"\/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e2d\u0e1e Translate \u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 iOS 16 \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e44\u0e14\u0e49\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e14\u0e35\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e08\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e08\u0e32\u0e01 App Store \u0e21\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e15\u0e31\u0e27\u0e41\u0e2d\u0e1e\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e17\u0e19\u0e32 (\u0e14\u0e49\u0e27\u0e22\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a) \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/th\/app\/translate\/id1514844618\"  target=\"_blank\" rel=\"noopener\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19: iOS<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"995\" height=\"503\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Translate iPhone\" class=\"wp-image-751365\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2.jpg 995w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2-375x190.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2-780x394.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2-225x114.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2-768x388.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/tt2-320x162.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure><\/div>\n\n\n\n<p><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/strong><\/p>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e2d\u0e1e Translate \u0e1a\u0e19 iOS \u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a Google Translate \u0e40\u0e25\u0e22 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e21\u0e32\u0e01\u0e46<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e14\u0e39\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e19\u0e39\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 &gt;&gt; \u0e40\u0e25\u0e37\u0e2d\u0e01  Camera<\/li><li>\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25 &gt;&gt; \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/li><li>\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e1a Real-time \u0e41\u0e25\u0e30\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1b\u0e25\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49<\/li><\/ul>\n\n\n\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e43\u0e19 iOS \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 iOS 16 \u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b Apple \u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 <strong>Live Text<\/strong> \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e22\u0e01\u0e01\u0e25\u0e49\u0e2d\u0e07 iPhone \u0e2b\u0e23\u0e37\u0e2d iPad \u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491470_0-side.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Live Text\" class=\"wp-image-751377\" width=\"433\" height=\"449\"\/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23 Live Text \u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48 Settings &gt;&gt; \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48 General<\/li><li>\u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32 General \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48 Language &amp; Region &gt;&gt; \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e25\u0e07\u0e21\u0e32\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 Live Text<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-scaled.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 Live Text\" class=\"wp-image-751378\" width=\"640\" height=\"442\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-scaled.jpg 2560w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-375x259.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-780x539.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-182x126.jpg 182w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-768x530.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-1536x1061.jpg 1536w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-2048x1414.jpg 2048w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/03\/S__43491473_0-side-320x221.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure><\/div>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e2d\u0e1e Camera \u0e41\u0e25\u0e49\u0e27\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25<\/li><li>\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e17\u0e35\u0e48\u0e21\u0e38\u0e21\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e23\u0e39\u0e1b\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 &gt;&gt; \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e19\u0e35\u0e49<\/li><li>\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e49\u0e27\u0e01\u0e32\u0e23\u0e01\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48 Translate \u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 <\/li><\/ul>\n\n\n\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e1c\u0e48\u0e32\u0e19 Live Text \u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@notebookspec\/video\/7215968276021513478\" data-video-id=\"7215968276021513478\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/@notebookspec?refer=embed\" target=\"_blank\" title=\"@notebookspec\"  rel=\"noopener\">@notebookspec<\/a> <p>\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07 \u0e2a\u0e48\u0e2d\u0e07 \u0e41\u0e1b\u0e25\u0e07\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35  <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/tag\/ios16?refer=embed\" title=\"ios16\" target=\"_blank\"  rel=\"noopener\">#ios16<\/a>  <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/tag\/iphone?refer=embed\" title=\"iphone\" target=\"_blank\"  rel=\"noopener\">#iphone<\/a> <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/tag\/iphonetricks?refer=embed\" title=\"iphonetricks\" target=\"_blank\"  rel=\"noopener\">#iphonetricks<\/a>  <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/tag\/PepsiApplePieChallenge?refer=embed\" title=\"PepsiApplePieChallenge\" target=\"_blank\"  rel=\"noopener\">#PepsiApplePieChallenge<\/a> <\/p> <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.tiktok.com\/music\/FEEL-THE-GROOVE-6769046027488987137?refer=embed\" target=\"_blank\" title=\"\u266c FEEL THE GROOVE - Queens Road, Fabian Graetz\"  rel=\"noopener\">\u266c FEEL THE GROOVE &#8211; Queens Road, Fabian Graetz<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>\u0e41\u0e25\u0e30\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e41\u0e2d\u0e1e\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e22\u0e01\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e14\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1f\u0e23\u0e35 \u0e46 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 iOS \u0e41\u0e25\u0e30 Android&nbsp;\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e2d\u0e07\u0e2b\u0e32 \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e14\u0e35\u0e46 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e22\u0e38\u0e48\u0e07\u0e22\u0e32\u0e01\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u0e2d\u0e48\u0e32\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \/ \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.youtube.com\/watch?v=FAmltTccVm8&amp;ab_channel=NotebookSPEC\"  target=\"_blank\" rel=\"noopener\">\u0e08\u0e2d\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 OLED 240Hz \u0e2a\u0e35\u0e2a\u0e14 GIGABYTE AORUS FO32U2P \u0e1a\u0e34\u0e4a\u0e01\u0e44\u0e0b\u0e2a\u0e4c\u0e41\u0e04\u0e48 50K \u0e25\u0e39\u0e01\u0e40\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32 <\/a><\/strong><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u0e08\u0e2d\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 OLED 240Hz \u0e2a\u0e35\u0e2a\u0e14 GIGABYTE AORUS FO32U2P \u0e1a\u0e34\u0e4a\u0e01\u0e44\u0e0b\u0e2a\u0e4c\u0e41\u0e04\u0e48 50K \u0e25\u0e39\u0e01\u0e40\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/FAmltTccVm8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/766337-knowing-obs-studio-suggestion\">\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a OBS \u0e2d\u0e31\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e1a\u0e19 Windows 11 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024 (notebookspec.com)<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/766337-knowing-obs-studio-suggestion\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/WhatisOBS.jpg\" alt=\"\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 OBS \u0e2d\u0e31\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d, OBS Studio\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/765201-easy-way-converting-pdf-to-word\">7 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e25\u0e4c PDF to Word \u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e49\u0e22\u0e19 \u0e1f\u0e23\u0e35 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/765201-easy-way-converting-pdf-to-word\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/PDFtoWord.jpg\" alt=\"\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e25\u0e4c PDF to Word \u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e49\u0e22\u0e19\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/764927-special-font-for-game-free-fire\">\u0e41\u0e08\u0e01\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d \u0e1f\u0e35\u0e1f\u0e32\u0e22 \u0e40\u0e17\u0e48\u0e46 \u0e2d\u0e31\u0e01\u0e29\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01\u0e46 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/764927-special-font-for-game-free-fire\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/FREEFIRENAME2024.jpg\" alt=\"\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d \u0e1f\u0e35\u0e1f\u0e32\u0e22 \u0e40\u0e17\u0e48\u0e46 \u0e2d\u0e31\u0e01\u0e29\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/764247-iphone-cases-suggest-for-you\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e04\u0e2a\u0e44\u0e2d\u0e42\u0e1f\u0e19\u0e19\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e14\u0e35 \u0e2a\u0e27\u0e22\u0e40\u0e17\u0e48 \u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e22 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/764247-iphone-cases-suggest-for-you\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/iPhoneCase2024.jpg\" alt=\"\u0e40\u0e04\u0e2a\u0e44\u0e2d\u0e42\u0e1f\u0e19, \u0e40\u0e04\u0e2a iPhone\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/764034-chinese-makeup-photo-editor-apps\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e2d\u0e1e\u0e08\u0e35\u0e19\u0e41\u0e15\u0e48\u0e07\u0e23\u0e39\u0e1b\u0e2a\u0e27\u0e22\u0e46 \u0e1f\u0e34\u0e25\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e47\u0e14\u0e35 \u0e23\u0e35\u0e17\u0e31\u0e0a\u0e01\u0e47\u0e1b\u0e31\u0e07 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/764034-chinese-makeup-photo-editor-apps\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/BeautyApps2024.jpg\" alt=\"\u0e41\u0e2d\u0e1e\u0e08\u0e35\u0e19\u0e41\u0e15\u0e48\u0e07\u0e23\u0e39\u0e1b, \u0e41\u0e2d\u0e1e\u0e41\u0e15\u0e48\u0e07\u0e23\u0e39\u0e1b\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/763296-7-recommend-5g-smartphone-2024\">7 \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d 5G \u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 5000 \u0e1b\u0e35 2024 \u0e19\u0e48\u0e32\u0e43\u0e0a\u0e49 \u0e2a\u0e40\u0e1b\u0e04\u0e14\u0e35 \u0e23\u0e32\u0e04\u0e32\u0e04\u0e38\u0e49\u0e21<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/763296-7-recommend-5g-smartphone-2024\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/Phone5K2024.jpg\" alt=\"\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d 5G \u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 5000 \u0e1b\u0e35 2024\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/760261-how-to-scan-qr-code-on-pc\">\u0e2a\u0e41\u0e01\u0e19\u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14\u0e43\u0e19\u0e04\u0e2d\u0e21 \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07 \u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/760261-how-to-scan-qr-code-on-pc\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/05\/HowtoScanQRCode2024.jpg\" alt=\"\u0e2a\u0e41\u0e01\u0e19\u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14\u0e43\u0e19\u0e04\u0e2d\u0e21\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/758465-online-cartoons-free-reading\">18 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e2d\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e1f\u0e23\u0e35 \u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e46 \u0e04\u0e23\u0e1a\u0e23\u0e2a\u0e17\u0e38\u0e01\u0e41\u0e19\u0e27 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/758465-online-cartoons-free-reading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/04\/WapCartoon2024.jpg\" alt=\"\u0e40\u0e27\u0e47\u0e1a\u0e2d\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e1f\u0e23\u0e35\" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/notebookspec.com\/web\/757789-free-games-mobile-pc-suggestion\">20 \u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e1f\u0e23\u0e35\u0e2a\u0e19\u0e38\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e21\u0e32\u0e40\u0e25\u0e48\u0e19\u0e41\u0e01\u0e49\u0e40\u0e1a\u0e37\u0e48\u0e2d \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024<\/a><\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/notebookspec.com\/web\/757789-free-games-mobile-pc-suggestion\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2024\/04\/20Game2024.jpg\" alt=\"\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e1f\u0e23\u0e35\u0e2a\u0e19\u0e38\u0e01\u0e46 \" width=\"350\" height=\"195\"\/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e34\u0e18\u0e35\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e41\u0e1b\u0e25\u0e41\u0e21\u0e48\u0e19 \u0e17\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e20\u0e32\u0e29\u0e32 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17 2024 \u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01 \u0e41\u0e16\u0e21\u0e22\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e16\u0e34\u0e48\u0e19\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e01\u0e47\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e32\u0e19\u0e31\u0e49\u0e19\u0e25\u0e14\u0e25\u0e07\u0e40\u0e22\u0e2d\u0e30 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 NotebookSPEC \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e1f\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e21\u0e35\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e08\u0e30\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e1f\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e19\u0e33\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e41\u0e1b\u0e25\u0e44\u0e14\u0e49\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e2b\u0e25\u0e31\u0e01\u0e46 \u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d \u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e2d\u0e48\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 Google Translate \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e43\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 Google Translate \u0e40\u0e2d\u0e07\u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e31\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e2a\u0e33\u0e19\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e25\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e14\u0e35\u0e19\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e14\u0e35\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e32\u0e07 Google \u0e40\u0e2d\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32 Translate \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32 Translate \u0e01\u0e47\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e46 [&hellip;]<\/p>\n","protected":false},"author":1011054,"featured_media":767268,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[27578,28431,28669],"class_list":["post-766560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-tricks","tag-27578","tag-28431","tag-28669"],"views":3305,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/766560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011054"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=766560"}],"version-history":[{"count":16,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/766560\/revisions"}],"predecessor-version":[{"id":767462,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/766560\/revisions\/767462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/767268"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=766560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=766560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=766560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}