{"id":694301,"date":"2023-03-28T19:09:14","date_gmt":"2023-03-28T12:09:14","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=694301"},"modified":"2023-03-28T19:09:24","modified_gmt":"2023-03-28T12:09:24","slug":"openai-chatgpt-4-trademark-chaina","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/694301-openai-chatgpt-4-trademark-chaina","title":{"rendered":"OpenAI \u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 ChatGPT-4 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"439\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-780x439.jpg\" alt=\"\" class=\"wp-image-694312\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-780x439.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-375x211.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-225x126.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-768x432.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-1024x576.jpg 1024w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-600x337.jpg 600w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81-320x180.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2023\/03\/NBS-cover-image_4.pdf-81.jpg 1280w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure><\/div>\n\n\n\n<p>\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 ChatGPT \u0e02\u0e2d\u0e07 OpenAI \u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e15\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e08\u0e35\u0e19\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07 ChatGPT \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 AI \u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e25\u0e32\u0e14\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e21\u0e32\u0e22\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07 Nikkei Asia \u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49 \u0e27\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 ChatGPT \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49 ChatGPT \u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e31\u0e19\u0e43\u0e01\u0e25\u0e49\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 AASTOCKS \u0e44\u0e14\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 Tianyancha \u0e17\u0e35\u0e48\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 OPENAI OPCO, LLC \u0e44\u0e14\u0e49\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 &#8216;GPT-4&#8217; \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 &#8216;WHISPER&#8217; \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 &#8220;\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d&#8221; \u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<p>Chinastarmarket \u0e22\u0e31\u0e07\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a Microsoft \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e22\u0e49\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e43\u0e19\u0e08\u0e35\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07 OpenAI API \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e25\u0e32\u0e14\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07 Chinastarmarket \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e19\u0e08\u0e35\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a ChatGPT \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 ZKTeco, Shunya International \u0e41\u0e25\u0e30 Wondershare \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e22\u0e31\u0e07\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48 Beijing Kingsoft Office Software \u0e27\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e02\u0e22\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e47\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a OpenAI \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p>\n\n\n\n<p>ChatGPT \u0e02\u0e2d\u0e07 OpenAI \u0e44\u0e14\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e39\u0e48\u0e04\u0e49\u0e32\u0e0a\u0e32\u0e27\u0e08\u0e35\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01 Baidu \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Ernie Bot \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 Kai-Fu Lee \u0e2d\u0e14\u0e35\u0e15\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32 Google China \u0e1a\u0e2d\u0e01\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e02\u0e48\u0e32\u0e27 China Daily \u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 ChatGPT \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e47\u0e01\u0e15\u0e4c AI 2.0 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 Alibaba, iFlytek, NetEase \u0e41\u0e25\u0e30 Tencent \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e1a ChatGPT \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e44\u0e01\u0e25 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e17\u0e48\u0e32\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e01\u0e47\u0e15\u0e32\u0e21<\/p>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.digitimes.com\/news\/a20230325VL202\/ai-chatgpt-china-generative-ai-openai-software-big-data.html\"  target=\"_blank\" rel=\"noopener\">digitimes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32 ChatGPT \u0e02\u0e2d\u0e07 OpenAI \u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e15\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e32\u0e02\u0e32\u0e43\u0e19\u0e08\u0e35\u0e19\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07 ChatGPT \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 AI \u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e25\u0e32\u0e14\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e21\u0e32\u0e22\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07 Nikkei Asia \u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49 \u0e27\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 ChatGPT \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49 ChatGPT \u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e31\u0e19\u0e43\u0e01\u0e25\u0e49\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 AASTOCKS \u0e44\u0e14\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 Tianyancha \u0e17\u0e35\u0e48\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 OPENAI OPCO, LLC \u0e44\u0e14\u0e49\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 &#8216;GPT-4&#8217; \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 &#8216;WHISPER&#8217; \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 &#8220;\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d&#8221; \u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 Advertisement Chinastarmarket \u0e22\u0e31\u0e07\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a Microsoft \u0e42\u0e14\u0e22\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e22\u0e49\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e43\u0e19\u0e08\u0e35\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07 OpenAI API \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e25\u0e32\u0e14\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07 Chinastarmarket \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e19\u0e08\u0e35\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a ChatGPT \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 ZKTeco, Shunya International [&hellip;]<\/p>\n","protected":false},"author":1011064,"featured_media":694312,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28823,11050],"tags":[25752],"class_list":["post-694301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech-news","category-other-news","tag-openai"],"views":322,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/694301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011064"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=694301"}],"version-history":[{"count":1,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/694301\/revisions"}],"predecessor-version":[{"id":694313,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/694301\/revisions\/694313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/694312"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=694301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=694301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=694301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}