{"id":568634,"date":"2021-01-09T11:17:09","date_gmt":"2021-01-09T04:17:09","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=568634"},"modified":"2021-01-09T11:17:23","modified_gmt":"2021-01-09T04:17:23","slug":"pc-spec-2021-value-set","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/568634-pc-spec-2021-value-set","title":{"rendered":"\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e41\u0e04\u0e48 7,000 \u0e1a\u0e32\u0e17 3 \u0e2a\u0e40\u0e1b\u0e04 \u0e17\u0e33\u0e07\u0e32\u0e19 \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21"},"content":{"rendered":"\n<p>\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e04\u0e2d\u0e21\u0e2a\u0e31\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e41\u0e1e\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e1b <a href=\"https:\/\/notebookspec.com\/pc\/spec\" class=\"rank-math-link\">\u0e04\u0e2d\u0e21\u0e2a\u0e40\u0e1b\u0e04<\/a>\u0e19\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e23\u0e32\u0e04\u0e32\u0e22\u0e48\u0e2d\u0e21\u0e40\u0e22\u0e32\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e22\u0e2d\u0e30 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e25\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e43\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e2b\u0e25\u0e31\u0e01\u0e1e\u0e31\u0e19\u0e1a\u0e32\u0e17 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e15\u0e49\u0e19\u0e46 \u0e01\u0e31\u0e19\u0e14\u0e39\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e08\u0e36\u0e07\u0e08\u0e30\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"410\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-780x410.jpg\" alt=\"\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021\" class=\"wp-image-568814\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-780x410.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-375x197.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-225x118.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-768x403.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value-320x168.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-value.jpg 1200w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021<\/h2>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e41\u0e1e\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1b \u0e01\u0e47\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e22\u0e34\u0e48\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e47\u0e22\u0e34\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e48\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"#PCSpec7000\" class=\"rank-math-link\">\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 7,000 \u0e1a\u0e32\u0e17<\/a><\/li><li><a href=\"#PCSpec9000\" class=\"rank-math-link\">\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b 9,000 \u0e1a\u0e32\u0e17<\/a><\/li><li><a href=\"#PCSpec12000\" class=\"rank-math-link\">\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 12,000 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<p><strong>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e14\u0e35?<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"401\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-780x401.jpg\" alt=\"\" class=\"wp-image-554553\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-780x401.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-375x193.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-225x116.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-768x394.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F-320x164.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/12\/Intel-Core-i3-10100F.jpg 1408w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p><strong><a href=\"https:\/\/notebookspec.com\/pc\/cpu.html\" class=\"rank-math-link\">\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39<\/a>:<\/strong> \u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e16\u0e49\u0e32\u0e40\u0e14\u0e34\u0e21\u0e21\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e47\u0e01\u0e44\u0e1b \u0e01\u0e47\u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e15\u0e47\u0e21\u0e40\u0e21\u0e47\u0e14\u0e40\u0e15\u0e47\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e01\u0e34\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e46 \u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e47\u0e1a \u0e14\u0e39\u0e22\u0e39\u0e17\u0e39\u0e1b \u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 Intel Pentium \u0e2b\u0e23\u0e37\u0e2d AMD Athlon \u0e01\u0e47\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a 2 core\/ 4 thread \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e30\u0e14\u0e31\u0e1a 3.xxGHz \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e1e\u0e23\u0e35\u0e40\u0e0b\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e19\u0e49\u0e2d\u0e22\u0e46 \u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Intel Core i3 \u0e2b\u0e23\u0e37\u0e2d AMD Ryzen &#8220;G&#8221; series \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e2a\u0e19\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 2-3 \u0e1e\u0e31\u0e19\u0e1a\u0e32\u0e17 <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/pc-cpu\/379-INTEL-Pentium-Gold%20G6400.html\" class=\"rank-math-link\">Intel Pentium G6400<\/a>: 2 core\/ 4 thread, Base clock 4.00GHz\/ <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.intel.com\/content\/www\/us\/en\/support\/products\/98910\/graphics\/graphics-for-7th-generation-intel-processors\/intel-hd-graphics-610.html\"  class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">UHD Graphic 610<\/a> \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,950 \u0e1a\u0e32\u0e17<\/li><li><a href=\"https:\/\/notebookspec.com\/pc-cpu\/395-INTEL-Core-i3-10100.html\" class=\"rank-math-link\">Intel Core i3-10100<\/a>: 4 core\/ 8 thread, Base\/ Boost clock 3.60GHz\/ 4.30GHz\/ UHD Graphic 630 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 3,950 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/pc-cpu\/350-AMD-Athlon-3000G.html\" class=\"rank-math-link\">AMD Athlon 3000G<\/a>: 2 core\/ 4 thread, Base clock 3.50GHz\/ Radeon\u2122 Vega 3 Graphics \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,750 \u0e1a\u0e32\u0e17<\/li><li><a href=\"https:\/\/notebookspec.com\/pc-cpu\/343-AMD-Ryzen-3%203200G.html\" class=\"rank-math-link\">AMD Ryzen 3 3200G<\/a>: 4 core\/ 4 thread, Base\/ Boost clock 3.60GHz\/ 4.0GHz\/ Radeon\u2122 Vega 8 Graphics \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 3,250 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e41\u0e17\u0e1a\u0e08\u0e30\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e07\u0e27\u0e25\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e0a\u0e49\u0e23\u0e38\u0e48\u0e19\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e2a\u0e38\u0e14\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e38\u0e48\u0e19\u0e01\u0e25\u0e32\u0e07\u0e46 \u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e25\u0e14\u0e17\u0e2d\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1a\u0e23\u0e23\u0e14\u0e32\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e47\u0e2d\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e2a\u0e07\u0e44\u0e1f RGB \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"520\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-780x520.jpg\" alt=\"\" class=\"wp-image-499916\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11-320x213.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/10\/Set-XMP-DDR4-BIOS-11.jpg 1200w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p><strong><a href=\"https:\/\/notebookspec.com\/pc\/ram.html\" class=\"rank-math-link\">\u0e41\u0e23\u0e21<\/a>:<\/strong>\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e41\u0e23\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e19 Windows 10 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e23\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48 8GB \u0e40\u0e19\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07 Bus speed \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e41\u0e23\u0e21 DDR4 3200 \u0e08\u0e30\u0e41\u0e1e\u0e07\u0e01\u0e27\u0e48\u0e32 DDR4 2666 \u0e1a\u0e19\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e41\u0e04\u0e48\u0e2b\u0e25\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e22\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e25\u0e22 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e1a\u0e19\u0e2a\u0e25\u0e47\u0e2d\u0e15\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1a\u0e19\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"520\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-780x520.jpg\" alt=\"\" class=\"wp-image-547090\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076-320x213.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/11\/AMD-Radeon-RX6800-XT-076.jpg 1000w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p><strong><a href=\"https:\/\/notebookspec.com\/pc\/vga.html\" class=\"rank-math-link\">\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14<\/a>:<\/strong> \u0e16\u0e49\u0e32\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e08\u0e33\u0e01\u0e31\u0e14\u0e21\u0e32\u0e01\u0e46 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e46 \u0e44\u0e1b \u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e23\u0e2d\u0e07\u0e46 \u0e08\u0e32\u0e01\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e1a\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 \u0e14\u0e39\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e25\u0e07\u0e15\u0e31\u0e27\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e04\u0e2d\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e1e\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01 (Discrete graphic) \u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e1a\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 (Integrate graphic) \u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e15\u0e01\u0e23\u0e38\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01\u0e21\u0e32\u0e01\u0e46 \u0e21\u0e32\u0e43\u0e2a\u0e48 \u0e22\u0e34\u0e48\u0e07\u0e43\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 iGPU \u0e40\u0e0a\u0e48\u0e19 Intel UHD graphic \u0e2b\u0e23\u0e37\u0e2d AMD Vega graphic \u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e23\u0e38\u0e48\u0e19\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e0a\u0e23\u0e4c\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07\u0e2a\u0e31\u0e01 2GB \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e1e\u0e31\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e02\u0e22\u0e31\u0e1a\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e15\u0e49\u0e19\u0e46 \u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 GeForce GTX 1650 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 Radeon RX 570 \u0e2b\u0e23\u0e37\u0e2d RX 5500 XT \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e1e\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e23\u0e38\u0e48\u0e19\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e47\u0e01\u0e17\u0e31\u0e49\u0e07 Intel \u0e41\u0e25\u0e30 AMD \u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e19\u0e19\u0e23\u0e32\u0e04\u0e32\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e35\u0e48 4,xxx \u0e1a\u0e32\u0e17 \u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"520\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-780x520.jpg\" alt=\"\" class=\"wp-image-494306\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50-320x213.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2019\/09\/WD-SSD-M.2-50.jpg 900w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p><strong><a href=\"https:\/\/notebookspec.com\/pc\/ssd.html\" class=\"rank-math-link\">Storage<\/a>:<\/strong> \u0e19\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e34\u0e48\u0e07\u0e2d\u0e35\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e22\u0e34\u0e48\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e2b\u0e49\u0e16\u0e35\u0e48\u0e16\u0e49\u0e27\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e14\u0e49 2 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e41\u0e04\u0e48 1,000-1,500 \u0e1a\u0e32\u0e17 \u0e2b\u0e32\u0e01\u0e40\u0e19\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 SSD 240-480GB \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e2a\u0e41\u0e1a\u0e1a SATA3 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e27 \u0e40\u0e02\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e16\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e25\u0e4c\u0e43\u0e19\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e2d\u0e36\u0e14\u0e43\u0e08 \u0e41\u0e15\u0e48\u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e17\u0e35\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e35\u0e44\u0e1f\u0e25\u0e4c\u0e20\u0e32\u0e1e \u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e1f\u0e25\u0e4c\u0e07\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e0b\u0e35\u0e40\u0e23\u0e35\u0e22\u0e2a\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c \u0e43\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e21\u0e32\u0e19\u0e35\u0e49 \u0e2d\u0e32\u0e08\u0e44\u0e14\u0e49\u0e40\u0e01\u0e37\u0e2d\u0e1a 2TB \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,6xx \u0e1a\u0e32\u0e17 \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e17\u0e35\u0e48\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 2,000GB \u0e19\u0e35\u0e49 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 SSD \u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e17\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e16\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e25\u0e4c \u0e01\u0e47\u0e08\u0e30\u0e0a\u0e49\u0e32\u0e01\u0e27\u0e48\u0e32 SSD \u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e14\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e2d\u0e07<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>HDD WD Blue 1TB: 7200RPM, 64MB \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,045 \u0e1a\u0e32\u0e17<\/li><li><a href=\"https:\/\/notebookspec.com\/pc-ssd\/385-Western-Digital-Blue%20250GB%203D%20NAND%20.html\" class=\"rank-math-link\">SSD WD Blue 250GB<\/a>: Read 550MB\/s, Write 525MB\/s \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,250 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"PCSpec7000\">\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 7,000 \u0e1a\u0e32\u0e17<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"478\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-7000.jpg\" alt=\"\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021\" class=\"wp-image-568799\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-7000.jpg 760w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-7000-375x236.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-7000-200x126.jpg 200w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-7000-320x201.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e40\u0e1b\u0e04\u0e41\u0e23\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e19\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e07\u0e1a\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e1a\u0e48\u0e07\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e2d\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e30\u0e14\u0e31\u0e1a 6,000-7,000 \u0e1a\u0e32\u0e17 \u0e01\u0e47\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Intel Pentium G6400 \u0e17\u0e35\u0e48\u0e21\u0e32\u0e43\u0e19\u0e0b\u0e47\u0e2d\u0e01\u0e40\u0e01\u0e47\u0e15\u0e43\u0e2b\u0e21\u0e48 LGA1200 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48 10 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a 2 core\/ 4 thread \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a 4.00GHz \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e04\u0e39\u0e48\u0e21\u0e32\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e21 DDR4 8GB \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e37\u0e48\u0e19\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c 1TB \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e08\u0e30\u0e44\u0e1b SSD \u0e2d\u0e32\u0e08\u0e44\u0e14\u0e49\u0e41\u0e04\u0e48 240GB \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e07\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e1a\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 iGPU Intel UHD Graphic \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39: INTEL Pentium Gold G6400<\/li><li>\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14: ASROCK H410M-HVS<\/li><li>\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01: Intel UHD Graphic (Integrate)<\/li><li>\u0e41\u0e23\u0e21: Apacer Panther DDR4 8GB (8GBx1) 2666<\/li><li>Storage: Toshiba P300 1TB HDWD110<\/li><li>\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22: DTECH PW007 500W<\/li><li>\u0e40\u0e04\u0e2a: CUBIC Hornets Black<\/li><\/ul>\n\n\n\n<p>\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e40\u0e1b\u0e04\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48 <a href=\"https:\/\/notebookspec.com\/pc\/8292207\" class=\"rank-math-link\">\u0e04\u0e2d\u0e21\u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"PCSpec9000\">\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b 9,000 \u0e1a\u0e32\u0e17<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"481\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-9000.jpg\" alt=\"\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021\" class=\"wp-image-568805\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-9000.jpg 760w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-9000-375x237.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-9000-199x126.jpg 199w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-9000-320x203.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e43\u0e19\u0e40\u0e0b\u0e47\u0e15\u0e16\u0e31\u0e14\u0e21\u0e32\u0e19\u0e35\u0e49 \u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2,000 \u0e1a\u0e32\u0e17 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e25\u0e40\u0e27\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e07\u0e1a 9,000 \u0e1a\u0e32\u0e17\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e23\u0e30\u0e14\u0e31\u0e1a AMD Ryzen 5 3400G \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e32\u0e01 Athlon series \u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a 4 core\/ 8 thread \u0e41\u0e25\u0e30\u0e1a\u0e39\u0e2a\u0e17\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 4.2GHz \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 Radeon Vega 11 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23 \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07 Clock \u0e41\u0e25\u0e30 CUs \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 Vega 8 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e49\u0e2d\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e19\u0e35\u0e49 \u0e08\u0e36\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e33\u0e1e\u0e23\u0e35\u0e40\u0e0b\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e25\u0e25\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 PUBG Lite \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e2d\u0e1e\u0e2f \u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e21\u0e32\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e21 DDR4 8GB \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49 SSD 240GB \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e1a\u0e39\u0e15\u0e23\u0e30\u0e1a\u0e1a \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e14\u0e39\u0e19\u0e49\u0e2d\u0e22\u0e44\u0e1b\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e41\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39: AMD Ryzen 5 3400G<\/li><li>\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14: GIGABYTE A320M-S2H<\/li><li>\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01: AMD Radeon Vega 11 (Integrate)<\/li><li>\u0e41\u0e23\u0e21: ADATA Premier DDR4 8GB 2666<\/li><li>Storage: Apacer AS350 PANTHER 240GB<\/li><li>\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22: NEOLUTION Gamemaster Pro 700W<\/li><li>\u0e40\u0e04\u0e2a: CUBIC Hornets Black<\/li><\/ul>\n\n\n\n<p>\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e40\u0e1b\u0e04\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48 <a href=\"https:\/\/notebookspec.com\/pc\/8292251\" class=\"rank-math-link\">\u0e04\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"PCSpec12000\">\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 12,000 \u0e1a\u0e32\u0e17<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"482\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12000.jpg\" alt=\"\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021\" class=\"wp-image-568813\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12000.jpg 760w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12000-375x238.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12000-199x126.jpg 199w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12000-320x203.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p>\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e19\u0e34\u0e14\u0e46 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e15\u0e31\u0e27\u0e04\u0e38\u0e49\u0e21\u0e08\u0e32\u0e01 Intel Core i3-10100F \u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a 4 core\/ 8 thread \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e1a\u0e39\u0e2a\u0e17\u0e4c\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 4GHz \u0e41\u0e15\u0e48\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35 UHD graphic \u0e21\u0e32\u0e43\u0e19\u0e15\u0e31\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01 \u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e41\u0e23\u0e21 DDR4 8GB \u0e41\u0e25\u0e30\u0e43\u0e2a\u0e48\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c 1TB \u0e21\u0e32\u0e41\u0e17\u0e19 SSD \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 \u0e40\u0e01\u0e47\u0e1a\u0e44\u0e1f\u0e25\u0e4c\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e37\u0e48\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1e\u0e31\u0e19\u0e1a\u0e32\u0e17 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2a\u0e48 SSD 240GB \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e40\u0e23\u0e35\u0e22\u0e07\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e01\u0e21\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e15\u0e48\u0e33\u0e08\u0e19\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e08\u0e36\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d GeForce GTX 1650 GDDR6 4GB \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 PUBG, NFS, FIFA \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e41\u0e2d\u0e47\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e2d\u0e36\u0e14\u0e2d\u0e31\u0e14\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e21\u0e16\u0e36\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e21\u0e35\u0e1c\u0e48\u0e2d\u0e19\u0e01\u0e47 0% 10 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2a\u0e1a\u0e32\u0e22\u0e46<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39: INTEL Core i3-10100F<\/li><li>\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14: ASROCK H410M-HVS<\/li><li>\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14: MSI GTX 1650 AERO ITX 4G OCV1 4GB<\/li><li>\u0e41\u0e23\u0e21: ADATA Premier DDR4 8GB 2666<\/li><li>Storage: Western Digital Blue 1TB WD10EZEX<\/li><li>\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22: NEOLUTION Gamemaster Pro 700W<\/li><li>\u0e40\u0e04\u0e2a: CUBIC Hornets Black<\/li><\/ul>\n\n\n\n<p>\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e40\u0e1b\u0e04\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48 <a href=\"https:\/\/notebookspec.com\/pc\/8292403\" class=\"rank-math-link\">\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"410\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-780x410.jpg\" alt=\"\" class=\"wp-image-568838\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-780x410.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-375x197.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-225x118.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-768x403.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12-320x168.jpg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2021\/01\/PC-spec-2021-12.jpg 1200w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e04\u0e34\u0e14\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e04\u0e2d\u0e21\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07 \u0e01\u0e47\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e27\u0e32\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e43\u0e04\u0e23\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07 \u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e41\u0e04\u0e48 20,000 \u0e1a\u0e32\u0e17 \u0e01\u0e47\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e25\u0e37\u0e48\u0e19\u0e43\u0e19 <a href=\"https:\/\/notebookspec.com\/web\/568498-pc-spec-2021-gaming-pc\" class=\"rank-math-link\">\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e25\u0e48\u0e19\u0e01\u0e21 2021<\/a><\/p>\n\n\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19 \u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e2d\u0e35\u0e01\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e04\u0e2d\u0e21\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e19\u0e49\u0e2d\u0e22 6,000-7,000 \u0e1a\u0e32\u0e17 \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e17\u0e33\u0e1e\u0e23\u0e35\u0e40\u0e0b\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e48\u0e19 \u0e43\u0e19\u0e07\u0e1a 9,000 \u0e1a\u0e32\u0e17 \u0e01\u0e47\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e2d\u0e40\u0e2b\u0e21\u0e32\u0e30 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e41\u0e22\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49 \u0e23\u0e32\u0e04\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e35\u0e48 12,000 \u0e1a\u0e32\u0e17 \u0e01\u0e47\u0e1e\u0e2d\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e04\u0e25\u0e48\u0e2d\u0e07 \u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e25\u0e37\u0e48\u0e19\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e08\u0e30\u0e21\u0e35\u0e04\u0e2d\u0e21\u0e2a\u0e31\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e41\u0e1e\u0e07\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e1b \u0e04\u0e2d\u0e21\u0e2a\u0e40\u0e1b\u0e04\u0e19\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e23\u0e32\u0e04\u0e32\u0e22\u0e48\u0e2d\u0e21\u0e40\u0e22\u0e32\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e22\u0e2d\u0e30 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e25\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e43\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e2b\u0e25\u0e31\u0e01\u0e1e\u0e31\u0e19\u0e1a\u0e32\u0e17 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e15\u0e49\u0e19\u0e46 \u0e01\u0e31\u0e19\u0e14\u0e39\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e08\u0e36\u0e07\u0e08\u0e30\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e41\u0e1e\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1b \u0e01\u0e47\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e22\u0e34\u0e48\u0e07\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e47\u0e22\u0e34\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e48\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 Advertisement \u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 7,000 \u0e1a\u0e32\u0e17 \u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b 9,000 \u0e1a\u0e32\u0e17 \u0e08\u0e31\u0e14\u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 12,000 \u0e1a\u0e32\u0e17 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e14\u0e35? \u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39: \u0e2a\u0e40\u0e1b\u0e04\u0e04\u0e2d\u0e21\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01 2021 \u0e16\u0e49\u0e32\u0e40\u0e14\u0e34\u0e21\u0e21\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e47\u0e01\u0e44\u0e1b \u0e01\u0e47\u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e15\u0e47\u0e21\u0e40\u0e21\u0e47\u0e14\u0e40\u0e15\u0e47\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e01\u0e34\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e46 \u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e47\u0e1a \u0e14\u0e39\u0e22\u0e39\u0e17\u0e39\u0e1b \u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 Intel Pentium \u0e2b\u0e23\u0e37\u0e2d AMD Athlon [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":568839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,28821],"tags":[18239,24353],"class_list":["post-568634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buyers-guide","category-content","tag-18239","tag-24353"],"views":26970,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/568634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=568634"}],"version-history":[{"count":25,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/568634\/revisions"}],"predecessor-version":[{"id":568915,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/568634\/revisions\/568915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/568839"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=568634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=568634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=568634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}