{"id":524808,"date":"2020-06-13T17:39:06","date_gmt":"2020-06-13T10:39:06","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=524808"},"modified":"2020-10-05T11:40:27","modified_gmt":"2020-10-05T04:40:27","slug":"introducing-the-new-asus-notebook-2020-the-new-core-i-gen-10-specification","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/524808-introducing-the-new-asus-notebook-2020-the-new-core-i-gen-10-specification","title":{"rendered":"\u0e41\u0e19\u0e30\u0e19\u0e33 ASUS Notebook \u0e1b\u0e35 2020 \u0e2a\u0e40\u0e1b\u0e01 Core i Gen 10 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e32\u0e07\u0e40\u0e1a\u0e32 \u0e41\u0e23\u0e07\u0e25\u0e49\u0e33 \u0e17\u0e33\u0e07\u0e32\u0e19 \/ Gaming \u0e40\u0e23\u0e34\u0e48\u0e21 23,990 \u0e1a\u0e32\u0e17"},"content":{"rendered":"\n<p>\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e32\u0e07 ASUS \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Notebook \u0e1b\u0e35 2020 \u0e2a\u0e40\u0e1b\u0e01 Core i Gen 10 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e32\u0e07\u0e40\u0e1a\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e40\u0e1b\u0e01 Gaming \u0e2b\u0e23\u0e37\u0e2d\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e49\u0e33\u0e46 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 ROG Strix G15 (GL542) \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 Gaming Notebook \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 ROG \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e44\u0e1f RGB \u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 Intel Core i Gen 10H \u0e15\u0e31\u0e27\u0e41\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 GeForce GTX 1650 Ti \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e0a\u0e31\u0e49\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e2d\u0e35\u0e01\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e08\u0e4b\u0e07\u0e40\u0e19\u0e49\u0e19\u0e1a\u0e32\u0e07\u0e40\u0e1a\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 VivoBook Series (S413\/S533) \u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e02\u0e19\u0e32\u0e14 14\u201d \u0e41\u0e25\u0e30 15.6\u201d \u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e16\u0e36\u0e07 6 \u0e2a\u0e35 \u0e2a\u0e40\u0e1b\u0e01\u0e40\u0e1b\u0e47\u0e19 Core i Gen 10U \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48 GeForce MX350 \u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e25\u0e37\u0e48\u0e19\u0e44\u0e2b\u0e25<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1.jpg\" alt=\"\" class=\"wp-image-524832\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1.jpg 1200w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/103976078_3402032336498173_7234178586174089968_o-1-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/figure>\n\n\n\n<p>\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22 VivoBook Gaming A571 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a Gaming Notebook \u0e43\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e2b\u0e23\u0e39\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e2a\u0e40\u0e1b\u0e01\u0e40\u0e1b\u0e47\u0e19 Intel Core i Gen 10H + GTX 1650 Ti  \u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22 ZenBook Duo UX481 \u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2a\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e40\u0e1b\u0e01\u0e40\u0e1b\u0e47\u0e19 Intel Core i Gen 10U \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e40\u0e1b\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e44\u0e14\u0e49\u0e41\u0e23\u0e21\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19 16GB \u0e1e\u0e23\u0e49\u0e2d\u0e21 SSD M.2 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 1TB \u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e46 <\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n\n\n\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 ASUS Notebook \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 2 \u0e1b\u0e35\u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e40\u0e04\u0e25\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e32\u0e19 7-11 \u0e44\u0e14\u0e49\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e01\u0e15\u0e34\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e35\u0e41\u0e23\u0e01\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e32\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ASUS \u0e43\u0e19\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33 ASUS Notebook \u0e1b\u0e35 2020 \u0e2a\u0e40\u0e1b\u0e01 Core i Gen 10 \u0e01\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e21\u0e35\u0e23\u0e38\u0e48\u0e23\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e1b\u0e0a\u0e21\u0e01\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e25\u0e22<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ASUS ROG Strix G15 GL542 \u0e23\u0e32\u0e04\u0e32 32,990 &#8211; 36,990 \u0e1a\u0e32\u0e17<\/h2>\n\n\n\n<p>ROG Strix G15 GL542 \u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14 Gaming Notebook \u0e17\u0e35\u0e48\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 eSport \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a Intel Core i7-10750H \u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e32\u0e2a\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e27\u0e34\u0e14\u0e34\u0e42\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 (\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35 Core i5-10300H \u0e21\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e35\u0e01\u0e17\u0e35) \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19 Nvidia GeForce GTX 1650 Ti  (RTX 2060 \u0e08\u0e30\u0e15\u0e32\u0e21\u0e21\u0e32\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 ROG Boost \u0e17\u0e33\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e47\u0e2d\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e2b\u0e49\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34 7% \u0e21\u0e32\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/notebook-picture\/Asus\/ROG%20Strix%20G15\/ROG%20Strix%20G15-bo.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>\u0e43\u0e2b\u0e49\u0e41\u0e23\u0e21\u0e41\u0e1a\u0e1a DDR4 (2933 MHz) \u0e02\u0e19\u0e32\u0e14\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 16GB \u0e41\u0e25\u0e30 M.2 PCIe SSD \u0e02\u0e19\u0e32\u0e14 512GB (\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01\u0e2a\u0e2d\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33 RAID 0) \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e02\u0e19\u0e32\u0e14 15.6\u201d \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 Full HD \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e1f\u0e23\u0e0a\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 144Hz \u0e1e\u0e2d\u0e23\u0e4c\u0e17\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19\u0e41\u0e25\u0e30 Wi-Fi 6 (802.11ax) \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07 ROG Strix G15 \u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2d\u0e31\u0e14\u0e41\u0e19\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1f RGB \u0e41\u0e1a\u0e1a ROG Aura Sync \u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e44\u0e1f RGB Light Bar \u0e23\u0e2d\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/notebook-picture\/Asus\/ROG%20Strix%20G15\/ROG%20Strix%20G15-f.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>ROG \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e0a\u0e31\u0e49\u0e19\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e02\u0e31\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e42\u0e25\u0e2b\u0e30\u0e40\u0e2b\u0e25\u0e27 (liquid metal) \u0e08\u0e32\u0e01\u0e17\u0e32\u0e07 Thermal Grizzly \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0b\u0e34\u0e25\u0e34\u0e42\u0e04\u0e19\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e42\u0e14\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 ROG Intelligent Cooling \u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e14\u0e25\u0e21\u0e04\u0e39\u0e48\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a 3D Thermal Design \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e48\u0e33\u0e25\u0e07\u0e21\u0e32\u0e01\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 10 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 <\/p>\n\n\n\n<p><strong><u>ROG Strix G15 GL542LI-HN053T<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Core i5-10300H \/ GTX 1650 Ti \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 15.6&#8243; IPS 144Hz \u0e23\u0e32\u0e04\u0e32 32,990 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<p><strong><u>ROG Strix G15 GL542LI-HN051T<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Core i7-10750H \/ GTX 1650 Ti \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 15.6&#8243; IPS 144Hz \u0e23\u0e32\u0e04\u0e32 36,990 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">ASUS VivoBook Series (S413 \/ S533) \u0e23\u0e32\u0e04\u0e32 23,990 &#8211; 28,990 \u0e1a\u0e32\u0e17<\/h2>\n\n\n\n<p>ASUS VivoBook Series (S413 \/ S533) \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 Intel Core i Gen 10U \u0e2d\u0e22\u0e48\u0e32\u0e07 Core i5-10210U \/ Core i7-10510U \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e08\u0e32\u0e01 NVIDIA GeForce MX350 \u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e25\u0e37\u0e48\u0e19\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a Gaming \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e39 6 \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e14\u0e43\u0e2a \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 Resolute Red, Gaia Green, Indy Black, Hearty Gold, Transparent Silver, Dreamy White \u0e41\u0e25\u0e30\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e1b\u0e49\u0e19&nbsp; \u2018Enter\u2019&nbsp; \u0e02\u0e2d\u0e1a\u0e15\u0e31\u0e14\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e15\u0e31\u0e14\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e31\u0e17\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e25\u0e39\u0e01\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e30\u0e14\u0e38\u0e14\u0e15\u0e32<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/notebook-picture\/Asus\/VivoBook%2014%20S413FQ%20Gold\/VivoBook%2014%20S413FQ%20Gold-l.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e02\u0e32\u0e14\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e14\u0e43\u0e2a \u0e43\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u2018Dare to be different\u2019 \u0e01\u0e25\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21 Windows 10 Home \u0e41\u0e25\u0e30 Pre-installed Office Home &amp; Student 2019 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49 Asus VivoBook Series (S413 \/ S533) \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e43\u0e08\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e25\u0e30\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e17\u0e38\u0e01\u0e42\u0e21\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/notebook-picture\/Asus\/VivoBook%2014%20S413FQ%20Black\/VivoBook%2014%20S413FQ%20Black-l.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>Series (S413 \/ S533) \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e43\u0e08\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e25\u0e30\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e17\u0e38\u0e01\u0e42\u0e21\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 New Asus VivoBook Series \u0e02\u0e19\u0e32\u0e14 14 \u0e19\u0e34\u0e49\u0e27 (S413) \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07 1.4 \u0e01\u0e01. (\u0e1a\u0e32\u0e07 17.9 \u0e21\u0e21.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e1a\u0e08\u0e2d\u0e1a\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e2d\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e07\u0e16\u0e36\u0e07 86% \u0e41\u0e25\u0e30 VivoBook \u0e02\u0e19\u0e32\u0e14 15.6 \u0e19\u0e34\u0e49\u0e27 (S533) \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 1.8 \u0e01\u0e01. \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 Wi-Fi 6 (GIG+) (802.11AX) 2*2<\/p>\n\n\n\n<p><strong><u>S413FQ-EB044TS (Hearty Gold)<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/notebook\/10134-Asus-Vivobook-S14-EB044TS.html\">i5-10210U \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 14&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 23,990 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<p><strong><u>S413FQ-EB045TS (Indie Black)<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/notebook\/10133-Asus-Vivobook-S14-EB045TS.html\">i5-10210U \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 14&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 23,990 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<p><strong><u>S413FQ-EB046TS (Transparent Silver<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/notebook\/10132-Asus-Vivobook-S14-EB046TS.html\">i5-10210U \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 14&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 23,990 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<p><strong><u>S533JQ-BQ027TS (Dreamy White)<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>i5-1035G1 \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 15.6&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 25,990 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<p><strong><u>S533JQ-BQ083TS (Gaia Green)<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>i5-1035G1 \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 15.6&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 25,990 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<p><strong><u>S413FQ-EB047TS (Indie Black)<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/notebook\/10135-Asus-Vivobook-S14-EB047TS.html\">i7-107510U \/ MX350 \/ RAM 8GB \/ SSD 512GB \/ \u0e08\u0e2d 14&#8243; IPS \/ MS Office \u0e23\u0e32\u0e04\u0e32 28,990 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">ASUS VivoBook Gaming A571 \u0e23\u0e32\u0e04\u0e32 36,990 \u0e1a\u0e32\u0e17<\/h2>\n\n\n\n<p>ASUS VivoBook Gaming A571 \u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e43\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e2b\u0e23\u0e39\u0e2a\u0e30\u0e01\u0e14\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e42\u0e2d\u0e01\u0e32\u0e2a \u0e25\u0e37\u0e48\u0e19\u0e44\u0e2b\u0e25\u0e15\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22 Intel Core i7-10750H \u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e41\u0e1a\u0e1a 6 \u0e04\u0e2d\u0e23\u0e4c 12 \u0e40\u0e18\u0e23\u0e14 \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e42\u0e2b\u0e14\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e40\u0e1b\u0e47\u0e19 Nvidia GeForce GTX 1650Ti 4GB GDDR6 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e37\u0e48\u0e19\u0e44\u0e2b\u0e25 <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/nbs\/upload_notebook\/20190923-142230_c.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e02\u0e19\u0e32\u0e14 15.6\u201d \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 Full HD \u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07\u0e15\u0e23\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a 100% sRGB \u0e41\u0e23\u0e21\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e02\u0e19\u0e32\u0e14 16GB \u0e41\u0e25\u0e30 SSD \u0e41\u0e1a\u0e1a M.2 PCIe \u0e02\u0e19\u0e32\u0e14 512GB \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e14\u0e25\u0e21\u0e04\u0e39\u0e48\u0e41\u0e22\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e25\u0e33\u0e42\u0e1e\u0e07\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e34\u0e42\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01 Harman\/Kardon \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600.jpeg\" alt=\"\" class=\"wp-image-524833\" width=\"600\" height=\"600\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600.jpeg 600w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600-375x375.jpeg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600-126x126.jpeg 126w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600-100x100.jpeg 100w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600-320x320.jpeg 320w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/P_setting_fff_1_90_end_600-150x150.jpeg 150w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure><\/div>\n\n\n\n<p>ASUS VivoBook A571GT \u0e44\u0e14\u0e49\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07&nbsp;Star Black \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1d\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e43\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e14\u0e39\u0e14\u0e35\u0e40\u0e01\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e1a\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48 7.4 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e34\u0e15\u0e34\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d 14\u2033 \u0e2a\u0e21\u0e31\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48 21.9 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e47\u0e04\u0e37\u0e2d&nbsp;\u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a ErgoLift Hinge \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e30\u0e22\u0e01\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<p><strong><u>ASUS VivoBook<\/u><\/strong> <strong><u>A571LI-BN008T \u0e23\u0e32\u0e04\u0e32 36,990 \u0e1a\u0e32\u0e17:<\/u><\/strong> <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/notebookspec.com\/notebook\/10129-Asus-VivoBook-A571LI-BN008T.html\">Core i7-10750H \/ GTX 1650Ti \/ RAM 16GB \/ SSD 512GB \/ \u0e08\u0e2d 15.6&#8243; IPS sRGB 100% \u0e23\u0e32\u0e04\u0e32 36,990 \u0e1a\u0e32\u0e17<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">ASUS ZenBook Duo UX481 \u0e23\u0e32\u0e04\u0e32 35,990 &#8211; 40,990 \u0e1a\u0e32\u0e17<\/h2>\n\n\n\n<p>\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e22\u0e32\u0e22\u0e17\u0e38\u0e01\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e08\u0e34\u0e19\u0e15\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e27\u0e22 Screenpad Plus \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e02\u0e19\u0e32\u0e14 12.65\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e19\u0e32\u0e14 14\u201d \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e02\u0e38\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 Intel Core i Gen 10U \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d Nvidia GeForce MX250 \u0e41\u0e23\u0e21\u0e02\u0e19\u0e32\u0e14 16GB \u0e41\u0e25\u0e30 SSD M.2 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e02\u0e19\u0e32\u0e14 1TB \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22 Windows 10 Home<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c.jpg\" alt=\"\" class=\"wp-image-524834\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c.jpg 800w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c-375x281.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c-780x585.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c-168x126.jpg 168w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c-768x576.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2020\/06\/20191008-155235_c-320x240.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/figure>\n\n\n\n<p>\u0e2a\u0e40\u0e1b\u0e01\u0e02\u0e2d\u0e07 ASUS ZenBook Duo UX481 \u0e08\u0e30\u0e16\u0e39\u0e01\u0e41\u0e1a\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19 2 \u0e23\u0e38\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e46 \u0e04\u0e37\u0e2d Core i5-10210U \/&nbsp;Core i7-10510U \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 Intel Core i Gen 10U (Comet Lake) \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48 14 \u0e19\u0e32\u0e42\u0e19\u0e40\u0e21\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d 14 \u0e19\u0e34\u0e49\u0e27 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 1920&nbsp;x 1080 \u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25 \u0e1e\u0e32\u0e40\u0e19\u0e25\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 IPS \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21 ScreenPad Plus \u0e02\u0e19\u0e32\u0e14&nbsp;12.6\u2033 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 1920 x 515 \u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25 \u0e1e\u0e32\u0e40\u0e19\u0e25 IPS \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a Touchscreen \u0e41\u0e25\u0e30 ASUS&nbsp;Active Stylus Pen&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/notebookspec.com\/web\/notebook-picture\/Asus\/ZenBook%20Duo%20UX481\/ZenBook%20Duo%20UX481-bo.jpg\" alt=\"\"><\/figure>\n\n\n\n<p>\u0e08\u0e32\u0e01\u0e2a\u0e40\u0e1b\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a 3 \u0e21\u0e34\u0e15\u0e34\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1e\u0e2d\u0e44\u0e14\u0e49 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d Wi-Fi 6 AX \u0e41\u0e25\u0e30 Bluetooth 5.0 \u0e14\u0e49\u0e27\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07 1.5 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 VDO Call \u0e41\u0e25\u0e30 IR Camera \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a Windows Hello \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a Military Standard&nbsp;\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14<\/p>\n\n\n\n<p><strong><u>ZenBook Duo UX481FL-HJ096T<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Core i5-10210U \/ MX250 \/ RAM 16GB \/ SSD 512GB \/ \u0e08\u0e2d 14&#8243; + 12.1&#8243; IPS Touch \u0e23\u0e32\u0e04\u0e32 35,990 \u0e1a\u0e32\u0e17<\/li><\/ul>\n\n\n\n<p><strong><u>ZenBook Duo UX481FL-HJ113T<\/u><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Core i7-10510U \/ MX250 \/ RAM 16GB \/ SSD 1TB \/ \u0e08\u0e2d 14&#8243; + 12.1&#8243; IPS Touch \u0e23\u0e32\u0e04\u0e32 40,990 \u0e1a\u0e32\u0e17 <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e17\u0e32\u0e07 ASUS \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Notebook \u0e1b\u0e35 2020 \u0e2a\u0e40\u0e1b\u0e01 Core i Gen 10 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e32\u0e07\u0e40\u0e1a\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e40\u0e1b\u0e01 Gaming \u0e2b\u0e23\u0e37\u0e2d\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e49\u0e33\u0e46 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 ROG Strix G15 (GL542) \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 Gaming Notebook \u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 ROG \u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e44\u0e1f RGB \u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21<\/p>\n","protected":false},"author":29,"featured_media":524837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[313,1467,308,26572,26811],"class_list":["post-524808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-asus","tag-asus-notebook","tag-intel","tag-intel-notebook","tag-notebook-2020"],"views":16323,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/524808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=524808"}],"version-history":[{"count":5,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/524808\/revisions"}],"predecessor-version":[{"id":524836,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/524808\/revisions\/524836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/524837"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=524808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=524808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=524808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}