{"id":450368,"date":"2018-08-11T12:04:46","date_gmt":"2018-08-11T05:04:46","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=450368"},"modified":"2018-08-11T12:09:29","modified_gmt":"2018-08-11T05:09:29","slug":"samsung-galaxy-note-9-is-official","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/450368-samsung-galaxy-note-9-is-official","title":{"rendered":"Samsung &#8211; \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Galaxy Note 9 \u0e07\u0e32\u0e19\u0e14\u0e35 \u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e35\u0e22\u0e1a \u0e23\u0e32\u0e04\u0e32  33,900 \u0e1a\u0e32\u0e17"},"content":{"rendered":"<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e23\u0e2a\u0e38\u0e21\u0e02\u0e48\u0e32\u0e27\u0e25\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e32\u0e07 Samsung \u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e18\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Galaxy Note 9 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e1a \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e19\u0e31\u0e01\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e02\u0e32\u0e2b\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e15\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e31\u0e49\u0e07\u0e21\u0e27\u0e25\u0e19\u0e31\u0e49\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e19\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32 Galaxy Note 9 \u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e16\u0e39\u0e01\u0e43\u0e08\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e04\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e27\u0e48\u0e32\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e44\u0e1b\u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07 Galaxy Note 9 \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-450369\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412.jpg\" alt=\"\" width=\"640\" height=\"356\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412.jpg 740w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412-375x209.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412-225x126.jpg 225w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.47.20-PM-740x412-320x178.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e40\u0e1b\u0e04\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e2a\u0e40\u0e1b\u0e04\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e1c\u0e34\u0e14\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 Note 9 \u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e17 Qualcomm Snapdragon 845 \u0e15\u0e31\u0e27\u0e41\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2018 \u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 2 \u0e42\u0e21\u0e40\u0e14\u0e25\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e02\u0e19\u0e32\u0e14 6 GB \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e02\u0e19\u0e32\u0e14 8 GB(\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 512 GB) \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 128 GB, 256 GB \u0e41\u0e25\u0e30 512 GB \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e1a\u0e1a MicroSD Card \u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e2a\u0e38\u0e14\u0e2d\u0e35\u0e01 512 GB \u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 4,000 mAh \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u00a0water-carbon cooling system \u0e41\u0e25\u0e30\u00a0smart performance adjuster \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e23\u0e49\u0e2d\u0e19\u0e01\u0e27\u0e19\u0e43\u0e08\u0e21\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-450370\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513.jpg\" alt=\"\" width=\"640\" height=\"400\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513.jpg 820w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513-375x235.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513-780x488.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513-201x126.jpg 201w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513-768x480.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.16.55-PM-820x513-320x200.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19 Samsung \u0e40\u0e2d\u0e07\u0e01\u0e47\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e21\u0e32\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e04\u0e39\u0e48\u0e41\u0e1a\u0e1a 12+12 MP \u0e42\u0e14\u0e22\u0e40\u0e25\u0e19\u0e0b\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e39\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07 f\/2.4 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 1\u00a0\u00b5m \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a AutoFocus \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e48\u0e19 OIS \u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e35\u0e01\u0e40\u0e25\u0e19\u0e0b\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 f\/1.5 &#8211; f\/2.4 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u00a0Phase Detection AutoFocus(\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e04\u0e21\u0e0a\u0e31\u0e14\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19) \u0e41\u0e16\u0e21\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e48\u0e19 OIS \u0e2d\u0e35\u0e01 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a\u00a0Super Slo-Mo \u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e2a\u0e1a\u0e32\u0e22\u0e46<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19\u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e25\u0e19\u0e0b\u0e4c\u0e04\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07\u0e41\u0e15\u0e48\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e15\u0e31\u0e27\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 8 MP \u0e23\u0e39\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e02\u0e19\u0e32\u0e14 f\/1.7 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 AutoFocus \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e17\u0e32\u0e07 Samsung \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e08\u0e38\u0e14\u0e1a\u0e01\u0e1e\u0e23\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e01\u0e49\u0e44\u0e02\u0e44\u0e14\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u00a0\u2018Scene Optimized Mode\u2019 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e selfie \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e09\u0e32\u0e01\u0e2b\u0e25\u0e31\u0e07 20 \u0e09\u0e32\u0e01\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e16\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e41\u0e08\u0e48\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-450371\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513.jpg\" alt=\"\" width=\"640\" height=\"400\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513.jpg 820w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513-375x235.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513-780x488.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513-201x126.jpg 201w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513-768x480.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.10.53-PM-820x513-320x200.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07 Note 8 \u0e21\u0e32\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e19\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e41\u0e01\u0e19\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e22\u0e49\u0e32\u0e22\u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e16\u0e19\u0e31\u0e14\u0e21\u0e37\u0e2d\u0e0b\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e02\u0e27\u0e32 \u0e23\u0e2d\u0e1a\u0e46 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e38\u0e48\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e08\u0e31\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19, \u0e0a\u0e48\u0e2d\u0e07\u0e25\u0e33\u0e42\u0e1e\u0e07, \u0e0a\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e14\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e07\u0e0b\u0e49\u0e32\u0e22\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e38\u0e48\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e38\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 Bixby \u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e02\u0e27\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48 Sim \u0e41\u0e25\u0e30 MicroSD card \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e21\u0e32\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07 Samsung \u0e40\u0e25\u0e22\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e02\u0e19\u0e32\u0e14 6.4 \u0e19\u0e34\u0e49\u0e27\u0e43\u0e0a\u0e49\u0e1e\u0e32\u0e40\u0e19\u0e25\u0e41\u0e1a\u0e1a Super AMOLED \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a QHD+ \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e08\u0e38\u0e14 pixel \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 516 ppi \u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e01\u0e34\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07\u0e01\u0e27\u0e48\u0e32 Note 8 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 Galaxy Note 9 \u0e08\u0e30\u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e16\u0e36\u0e07 4 \u0e2a\u0e35\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48\u00a0Ocean Blue, Lavender Purple, Metallic Copper\u00a0\u0e41\u0e25\u0e30 Midnight Black \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-450382\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513.jpg\" alt=\"\" width=\"640\" height=\"400\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513.jpg 820w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513-375x235.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513-780x488.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513-201x126.jpg 201w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513-768x480.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2018\/08\/Screen-Shot-2018-08-09-at-8.21.23-PM-820x513-320x200.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e22\u0e31\u0e07\u0e04\u0e23\u0e31\u0e1a \u0e22\u0e31\u0e07\u0e08\u0e1a\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e22\u0e31\u0e07\u0e02\u0e32\u0e14\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e23\u0e35\u0e22\u0e4c Note \u0e2d\u0e22\u0e48\u0e32\u0e07 S-Pen \u0e17\u0e35\u0e48\u0e04\u0e23\u0e32\u0e27\u0e19\u0e35\u0e49\u0e19\u0e35\u0e48\u0e19\u0e17\u0e32\u0e07 Samsung \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 S-Pen \u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21\u0e42\u0e14\u0e22\u0e21\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e35\u0e42\u0e21\u0e17\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Note 9 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e16\u0e36\u0e07 10 \u0e40\u0e21\u0e15\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e1a\u0e19\u0e40\u0e08\u0e49\u0e32 S-Pen \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e15\u0e47\u0e21\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 40 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 30 \u0e19\u0e32\u0e17\u0e35\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07 Galaxy Note 9 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e04\u0e23\u0e31\u0e1a \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48 \u0e13 \u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e17\u0e32\u0e07 Samsung \u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e08\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e42\u0e14\u0e22\u0e23\u0e32\u0e04\u0e32\u0e04\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 33,900 \u0e1a\u0e32\u0e17\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e22\u0e31\u0e07\u0e08\u0e30\u0e21\u0e35\u0e02\u0e2d\u0e07\u0e41\u0e16\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e27\u0e01 Samsung \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e1e\u0e25\u0e32\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/wccftech.com\/samsung-galaxy-note-9-launch-specifications-features-price-design-release-availability\/\"  target=\"_blank\" rel=\"noopener noreferrer\">wccftech<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e23\u0e2a\u0e38\u0e21\u0e02\u0e48\u0e32\u0e27\u0e25\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e32\u0e07 Samsung \u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e18\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e04\u0e23\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Galaxy Note 9 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e1a \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e19\u0e31\u0e01\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c<\/p>\n","protected":false},"author":53,"featured_media":450369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11050,19055],"tags":[498,24386],"class_list":["post-450368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news","category-smartphone-news","tag-samsung","tag-samsung-galaxy-note-9"],"views":295,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/450368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=450368"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/450368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/450369"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=450368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=450368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=450368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}