{"id":407778,"date":"2017-07-14T11:36:22","date_gmt":"2017-07-14T04:36:22","guid":{"rendered":"https:\/\/notebookspec.com\/web\/?p=407778"},"modified":"2017-07-14T11:41:38","modified_gmt":"2017-07-14T04:41:38","slug":"acer-day-2017-campaign-final","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/407778-acer-day-2017-campaign-final","title":{"rendered":"[Acer] \u0e0b\u0e38\u0e48\u0e21\u0e17\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19\u0e08\u0e31\u0e14 Acer Day \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e40\u0e01\u0e21 \u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e08\u0e01\u0e02\u0e2d\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e19\u0e31\u0e1a\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e38\u0e48\u0e21\u0e17\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19\u0e08\u0e31\u0e14 <\/strong><strong>Acer Day \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e40\u0e01\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 12 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<br \/>\n<\/strong><strong>\u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e44\u0e2d\u0e17\u0e35\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19<br \/>\n<\/strong><strong>BUSAN 9<sup>th<\/sup> Esport 2017 World Championship \u0e13 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e15\u0e49<\/strong><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/JV63TO9OPBE\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: left;\"><strong>\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/strong><strong>: <\/strong><strong>13<\/strong> <strong>\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 <\/strong><strong>25<\/strong><strong>60<\/strong> \u2013 <strong>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 <\/strong>\u0e22\u0e01\u0e17\u0e31\u0e1e\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e42\u0e0a\u0e27\u0e4c\u0e42\u0e09\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 Acer Day \u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e40\u0e14\u0e47\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e14\u0e49\u0e27\u0e22 3 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 1.) \u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e30\u0e41\u0e19\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acer-day.com\/th\"  target=\"_blank\" rel=\"noopener\">www.acer-day.com\/th<\/a> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Acer Day 2.) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e0a\u0e34\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 1,000,000 \u0e1a\u0e32\u0e17 \u0e08\u0e32\u0e01\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<br \/>\n3.) \u0e1e\u0e1a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Predator 21X, Predator Helios 300, Nitro 5 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e25\u0e38\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e21 Acer Unlocked Game Unlocked Me \u0e43\u0e19\u0e42\u0e0b\u0e19 Acer Unlock Zone \u0e23\u0e48\u0e27\u0e21\u0e0a\u0e21\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 E-Sport Thailand Championship 2017 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Acer Day: Game\u2019s On \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e25\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-407781 aligncenter\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652.jpg 800w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2652-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p><strong>\u0e19\u0e32\u0e22\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e1b\u0e23\u0e30\u0e27\u0e35\u0e13\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e38\u0e12\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Acer Day \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 12 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e18\u0e35\u0e21\u0e02\u0e2d\u0e07 <strong>\u201cAcer Day: Game\u2019s On\u201d<\/strong> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e44\u0e2d\u0e17\u0e35\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u0e08\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 3 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e08\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c <strong>(<\/strong><strong>Acer Day\u00a0 Game Site)<\/strong>, \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 <strong>(Nationwide Promotion Campaign)<\/strong> \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 <strong>(Event Promotion)<\/strong> <strong>Acer Day: Game\u2019s On<\/strong> \u0e42\u0e14\u0e22\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e25\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-407780 aligncenter\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re.jpg\" alt=\"\" width=\"800\" height=\"624\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re.jpg 800w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re-375x293.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re-780x608.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re-162x126.jpg 162w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re-768x599.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2560-re-320x250.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/p>\n<p>\u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n<p><strong>Acer Day Game Site<\/strong> \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e43\u0e19 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acer-day.com\/th\"  target=\"_blank\" rel=\"noopener\">www.acer-day.com\/th<\/a> \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u2013 9 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e19\u0e33\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e30\u0e2a\u0e21\u0e08\u0e32\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Acer Day Game Site \u0e08\u0e32\u0e01\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c www.acer-day.com\/th \u0e21\u0e32\u0e41\u0e25\u0e01\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e07\u0e32\u0e19 Acer Day \u0e42\u0e14\u0e22 20,000 point =1 \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35\u0e04\u0e33\u0e16\u0e32\u0e21\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23 \u0e25\u0e38\u0e49\u0e19\u0e0a\u0e34\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e27\u0e21\u00a0 4\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07<\/p>\n<p><strong>Nationwide Promotion <\/strong>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u2013 6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n<ul>\n<li><strong>Nationwide Lucky Draw: <\/strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e21\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c (Inbox) <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/messages\/t\/AcerThailand\"  target=\"_blank\" rel=\"noopener\">Facebook Acer Thailand<\/a> \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e16\u0e36\u0e07 6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 \u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e0a\u0e34\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 18 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 600,000 \u0e1a\u0e32\u0e17<\/li>\n<li><strong>Cash Back: <\/strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35 \u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 2,000 \u0e1a\u0e32\u0e17 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19 \u0e41\u0e21\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c (Inbox) <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/messages\/t\/AcerThailand\"  target=\"_blank\" rel=\"noopener\">Facebook Acer Thailand<\/a> (\u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14)<br \/>\n\u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 500,000 \u0e1a\u0e32\u0e17<\/li>\n<li><strong>Trade in: <\/strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 (\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22) \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e21\u0e32\u0e40\u0e0a\u0e47\u0e04\u0e2a\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48 (\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14) \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e21\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c (Inbox) <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/messages\/t\/AcerThailand\"  target=\"_blank\" rel=\"noopener\">Facebook Acer Thailand<\/a> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2a\u0e48 Promotion Code \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e04\u0e37\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19 14 \u0e27\u0e31\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19 Acer Day: Game\u2019s On \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c 10 \u0e2a\u0e32\u0e02\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 &#8211; 31 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2560 (\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e1a\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49 \u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.tradeinacer.com\"  target=\"_blank\" rel=\"noopener\">tradeinacer.com<\/a> \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2560)<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-407779 aligncenter\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637.jpg 800w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2637-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/p>\n<p><strong>Event Promotion<\/strong>: <strong>Acer Day: Game\u2019s On<\/strong> \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3-6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e13. \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e25\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19 Next@Acer 2017 \u0e16\u0e36\u0e07\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e40\u0e1b\u0e04\u0e2a\u0e38\u0e14\u0e41\u0e23\u0e07\u0e25\u0e49\u0e33\u0e02\u0e2d\u0e07 Predator 21X, Predator Helios 300, Nitro 5 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e42\u0e14\u0e22\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 5 \u0e42\u0e0b\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n<ul>\n<li><strong>Acer Unlock Zone:<\/strong> \u0e25\u0e38\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Acer Unlocked Game Unlocked Me \u0e43\u0e19\u0e07\u0e32\u0e19 Acer Day: Game\u2019s On \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e14\u0e23\u0e2b\u0e31\u0e2a 4 \u0e2b\u0e25\u0e31\u0e01\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35<\/li>\n<li><strong>Dream Team Zone:<\/strong> \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e23\u0e27\u0e21\u0e17\u0e35\u0e21\u0e01\u0e31\u0e19\u0e21\u0e32 (5\u0e17\u0e48\u0e32\u0e19 : 1 \u0e17\u0e35\u0e21) \u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07 (\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14) \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e43\u0e19\u0e1a\u0e34\u0e25\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e21\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c (Inbox) <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.facebook.com\/messages\/t\/AcerThailand\"  target=\"_blank\" rel=\"noopener\">Facebook Acer Thailand<\/a> \u0e23\u0e31\u0e1a\u0e17\u0e31\u0e19\u0e17\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 5,000 \u0e1a\u0e32\u0e17 \/ \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 (\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30 20 \u0e17\u0e35\u0e21\u0e41\u0e23\u0e01\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e19)<\/li>\n<li><strong>New <\/strong><strong>Arrival<\/strong> \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 Predator 21X, Predator Helios 300, Nitro 5 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e32\u0e2d\u0e27\u0e14\u0e42\u0e09\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e08\u0e32\u0e01\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e01\u0e17\u0e31\u0e1e\u0e21\u0e32\u0e2d\u0e27\u0e14\u0e42\u0e09\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49<\/li>\n<li><strong>Free Check Up Zone:<\/strong> \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e1f\u0e23\u0e35!\u0e43\u0e19\u0e07\u0e32\u0e19<\/li>\n<li><strong>Clearance Zone: <\/strong>\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c Clearance \u0e08\u0e32\u0e01\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 70%<\/li>\n<\/ul>\n<p>\u201c\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 <strong>Acer Day: Game\u2019s On<\/strong> \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e44\u0e17\u0e22\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (Thai E-Sports Association: TESA) \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 <strong>E-Sport Thailand Championship 2017 <\/strong>\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e44\u0e1b\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e35\u0e48 BUSAN 9<sup>th<\/sup> E-Sport 2017 World Championship \u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2560 \u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3-6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e13 Pantip E-Sport Arena, \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22\u201d <strong>\u0e19\u0e32\u0e22\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e2a\u0e23\u0e34\u0e21<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-407782 aligncenter\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881.jpg\" alt=\"\" width=\"800\" height=\"555\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881.jpg 800w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881-375x260.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881-780x541.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881-182x126.jpg 182w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881-768x533.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2881-320x222.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/p>\n<p>\u0e1e\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e14\u0e47\u0e14 \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e42\u0e14\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Acer Day \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acer-day.com\/th\"  target=\"_blank\" rel=\"noopener\">www.acer-day.com\/th<\/a> \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u2013 9 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u2013\u00a0 6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Acer Day: Game\u2019s On \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3-6 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2560 \u0e13 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acerthailnd.com\/privilege\"  target=\"_blank\" rel=\"noopener\">www.acerthailnd.com\/privilege<\/a> \u00a0\u0e41\u0e25\u0e30 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.facebook.com\/AcerThailand\"  target=\"_blank\" rel=\"noopener\">www.facebook.com\/AcerThailand<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-407783 aligncenter\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708.jpg\" alt=\"\" width=\"1365\" height=\"910\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708.jpg 1365w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708-780x520.jpg 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708-768x512.jpg 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2017\/07\/ARR_2708-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 400px, 1200px\" \/><\/p>\n<p>########################<\/p>\n<p><strong>\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c<\/strong><\/p>\n<p>\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e35 1976 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e2d\u0e21\u0e2d\u0e19\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2d\u0e2d\u0e1f \u0e18\u0e34\u0e07\u0e2a\u0e4c. \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 40 \u0e1b\u0e35\u0e43\u0e19\u0e1b\u0e35 2016 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19 5 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01 \u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 7,000 \u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 160 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.acer.com\"  target=\"_blank\" rel=\"noopener\">www.acer.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e38\u0e48\u0e21\u0e17\u0e38\u0e48\u0e21\u0e44\u0e21\u0e48\u0e2d\u0e31\u0e49\u0e19\u0e08\u0e31\u0e14 Acer Day \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e40\u0e01\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19 12 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e44\u0e2d\u0e17\u0e35\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 BUSAN 9th Esport 2017 World Championship \u0e13 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e15\u0e49Advertisement \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f: 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2560 \u2013 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e22\u0e01\u0e17\u0e31\u0e1e\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e42\u0e0a\u0e27\u0e4c\u0e42\u0e09\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 Acer Day \u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e40\u0e14\u0e47\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e14\u0e49\u0e27\u0e22 3 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 1.) \u0e2a\u0e30\u0e2a\u0e21\u0e04\u0e30\u0e41\u0e19\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c www.acer-day.com\/th \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d Acer Day 2.) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e0a\u0e34\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e23\u0e27\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 1,000,000 \u0e1a\u0e32\u0e17 \u0e08\u0e32\u0e01\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 3.) \u0e1e\u0e1a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07\u0e23\u0e38\u0e48\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 Predator 21X, Predator Helios 300, Nitro 5 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e25\u0e38\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e21 Acer [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":407779,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,6],"tags":[204,23131,17122,2938,23375],"class_list":["post-407778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","category-hot-promotion","tag-acer","tag-acer-nitro-5","tag-acer-promotion","tag-gaming-notebook","tag-predator-helios-300"],"views":411,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/407778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=407778"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/407778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/407779"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=407778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=407778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=407778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}