{"id":332502,"date":"2016-01-22T07:50:21","date_gmt":"2016-01-22T00:50:21","guid":{"rendered":"http:\/\/notebookspec.com\/web\/?p=332502"},"modified":"2016-01-22T07:50:21","modified_gmt":"2016-01-22T00:50:21","slug":"oculus-to-developers-no-jump-scares-in-vr","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/332502-oculus-to-developers-no-jump-scares-in-vr","title":{"rendered":"[News] Oculus \u0e41\u0e08\u0e49\u0e07\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e08\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2d\u0e1e\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e21\u0e08\u0e33\u0e1e\u0e27\u0e01 &#8220;jump scare&#8221; \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e14\u0e47\u0e14\u0e02\u0e32\u0e14"},"content":{"rendered":"<p>\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49 pre-order \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a Oculus Rift \u0e23\u0e38\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e25\u0e48\u0e19\u0e46 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e40\u0e1b\u0e47\u0e04\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e1e\u0e2d\u0e14\u0e39\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2a\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49 Oculus Rift \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07\u0e17\u0e35\u0e48 Oculus \u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e04\u0e23\u0e31\u0e1a\u0e17\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e25\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e14\u0e35\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07 Oculus \u0e40\u0e1c\u0e22\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e25\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e14\u0e01\u0e25\u0e31\u0e27(Horror) \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e43\u0e2b\u0e49\u0e19\u0e34\u0e22\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u00a0&#8220;jump scare&#8221; \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/oculus-no-jump-scare-software-600-01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-332503\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/oculus-no-jump-scare-software-600-01.jpg\" alt=\"oculus no jump scare software 600 01\" width=\"552\" height=\"248\" \/><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e21\u0e32\u0e14\u0e39\u0e19\u0e34\u0e22\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e04\u0e33\u0e27\u0e48\u0e32\u00a0&#8220;jump scare&#8221; \u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e2d\u0e32\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e40\u0e25\u0e22\u0e19\u0e31\u0e49\u0e19\u00a0&#8220;jump scare&#8221; \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 Horror \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u00a0&#8220;jump scare&#8221; \u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e20\u0e32\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2a\u0e30\u0e14\u0e38\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e46 \u0e01\u0e47\u0e21\u0e35\u0e1c\u0e35\u0e1e\u0e38\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e14\u0e31\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e19\u0e17\u0e35\u0e17\u0e31\u0e19\u0e43\u0e14\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e46 \u0e40\u0e07\u0e35\u0e22\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u00a0&#8220;jump scare&#8221; \u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e31\u0e19\u0e01\u0e47\u0e01\u0e47\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e30\u0e44\u0e23\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e01\u0e25\u0e31\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2a\u0e31\u0e01\u0e1e\u0e31\u0e01\u0e01\u0e47\u0e2b\u0e32\u0e22\u0e44\u0e1b(\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e04\u0e38\u0e13\u0e40\u0e2d\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e1c\u0e35\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e19\u0e35\u0e49\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e15\u0e49\u0e19\u0e41\u0e23\u0e07\u0e21\u0e32\u0e01\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e09\u0e32\u0e01\u00a0&#8220;jump scare&#8221; \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e01\u0e1e\u0e31\u0e01\u0e01\u0e47\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e27\u0e30\u0e1b\u0e01\u0e15\u0e34\u0e04\u0e23\u0e31\u0e1a) \u0e17\u0e27\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19\u0e21\u0e31\u0e19\u0e08\u0e30\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e27\u0e48\u0e32\u00a0&#8220;jump scare&#8221; \u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e37\u0e48\u0e19\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e01\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e14\u0e01\u0e25\u0e31\u0e27(level of panic) \u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u00a0&#8220;jump scare&#8221; \u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e48\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e15\u0e32\u0e21\u0e21\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/oculus-no-jump-scare-software-600-02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-332504\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/oculus-no-jump-scare-software-600-02.jpg\" alt=\"oculus no jump scare software 600 02\" width=\"583\" height=\"329\" \/><\/a><\/p>\n<p>\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e19\u0e31\u0e49\u0e19\u0e17\u0e32\u0e07 Oculus \u0e01\u0e47\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e23\u0e14\u0e32\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e23\u0e14\u0e32\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u00a0&#8220;jump scare&#8221; \u0e1a\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Oculus Rift \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e13\u0e35\u0e43\u0e14\u0e46 \u0e0b\u0e36\u0e48\u0e07 \u0e13 \u0e08\u0e38\u0e14\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e17\u0e32\u0e07 Oculus \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u00a0&#8220;jump scare&#8221; \u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22(\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e14\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e19\u0e35\u0e48\u0e22\u0e31\u0e07\u0e1e\u0e2d\u0e2a\u0e41\u0e01\u0e19\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e19\u0e35\u0e48\u0e04\u0e07\u0e08\u0e30\u0e2b\u0e49\u0e32\u0e21\u0e22\u0e32\u0e01\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e1a)<\/p>\n<p>\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38 &#8211; \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 HTC \u0e41\u0e25\u0e30 PlayStation \u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e04\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/vr-zone.com\/articles\/oculus-to-developers-no-jump-scares-in-vr\/104273.html\"  target=\"_blank\" rel=\"noopener\">vr-zone<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49 pre-order \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a Oculus Rift \u0e23\u0e38\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e25\u0e48\u0e19\u0e46 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e40\u0e1b\u0e47\u0e04\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e1e\u0e2d\u0e14\u0e39\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2a\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e2b\u0e49 Oculus Rift<\/p>\n","protected":false},"author":53,"featured_media":332503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11462,11457,11050,16807,16806],"tags":[18901,18091,19123],"class_list":["post-332502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming-gear","category-game-zone","category-other-news","category-pc-news","category-pc-zone","tag-oculus","tag-oculus-rift","tag-vr-headset"],"views":1008,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/332502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=332502"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/332502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/332503"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=332502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=332502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=332502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}