{"id":329816,"date":"2016-01-09T09:19:54","date_gmt":"2016-01-09T02:19:54","guid":{"rendered":"http:\/\/notebookspec.com\/web\/?p=329816"},"modified":"2016-01-11T10:37:13","modified_gmt":"2016-01-11T03:37:13","slug":"asrock-intel-c232-mainboard","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/329816-asrock-intel-c232-mainboard","title":{"rendered":"\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e1a\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e43\u0e2b\u0e21\u0e48 2 \u0e23\u0e38\u0e48\u0e19 \u0e02\u0e38\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e15 Intel C232 \u0e08\u0e32\u0e01 ASRock \u0e2b\u0e25\u0e31\u0e07\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49"},"content":{"rendered":"<p>\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e, \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 4 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2559 \u2013 \u0e14\u0e49\u0e27\u0e22\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Xeon E3-1200 \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07 Intel \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Core i7 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32\u0e21\u0e32\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 Intel \u0e44\u0e14\u0e49\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Xeon E3-1200 v5 \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e15 C232 \u0e19\u0e31\u0e48\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e19\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e15\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e23\u0e38\u0e48\u0e19 Z170\/H170\/B150\/H110 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e21\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e07\u0e48\u0e14\u0e35\u0e01\u0e47\u0e04\u0e37\u0e2d ASRock \u0e08\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e15 C232 \u0e2a\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c\u0e21\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e44\u0e14\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48 Intel\u2019s E3-1230 v5 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e23\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14 ASRock Fatal1ty E3V5 Performance Gaming\/OC \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 ASRock E3V5 WS.<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-329818\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232.jpg\" alt=\"asrock intel c232\" width=\"527\" height=\"263\" \/><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e2d\u0e2d\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e21\u0e32\u0e1a\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e1a\u0e22\u0e39 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e04\u0e25\u0e31\u0e48\u0e07\u0e44\u0e04\u0e25\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e38\u0e14\u0e2b\u0e23\u0e39\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 ASRock Fatal1ty E3V5 Performance Gaming\/OC \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21 Gaming Armor, Super Alloy, ASRock Hyper BCLK Engine, \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e17\u0e33\u0e25\u0e32\u0e22\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14 DDR4 Non-Z OC \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e44\u0e14\u0e49 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e42\u0e21\u0e14\u0e39\u0e25\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 DDR4 \u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e41\u0e1a\u0e1a ECC DIMMS \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e46 \u0e40\u0e0a\u0e48\u0e19 Key Master, \u0e0a\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e40\u0e21\u0e32\u0e2a\u0e4c Fatal1ty \u0e41\u0e25\u0e30 F-Stream \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-329819\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232-1.jpg\" alt=\"asrock intel c232-1\" width=\"527\" height=\"368\" \/><\/a><\/p>\n<p>\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 ASRock E3V5 WS \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e41\u0e21\u0e49\u0e08\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1a\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 \u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07 \u0e42\u0e21\u0e14\u0e39\u0e25\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 DDR4 \u0e1b\u0e01\u0e15\u0e34, \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 ECC DIMMs, AMD FirePro \u0e41\u0e25\u0e30 \u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e2e\u0e40\u0e2d\u0e19\u0e14\u0e4c NVIDIA Quadro \u0e22\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e0a\u0e34\u0e1b Intel I219LM LAN \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1a\u0e19\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e22\u0e31\u0e07\u0e21\u0e32\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e35\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-329820\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2016\/01\/asrock-intel-c232-2.jpg\" alt=\"asrock intel c232-2\" width=\"527\" height=\"368\" \/><\/a><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e21\u0e19\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<br \/>\nhttp:\/\/www.asrock.com\/MB\/overview.asp?Model=E3V5%20WS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e, \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 4 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2559 \u2013 \u0e14\u0e49\u0e27\u0e22\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Xeon E3-1200 \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07 Intel \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e0b\u0e35\u0e1e\u0e35\u0e22\u0e39 Core i7 <\/p>\n","protected":false},"author":47,"featured_media":329820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16807,16806],"tags":[1351,308,6503],"class_list":["post-329816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pc-news","category-pc-zone","tag-asrock","tag-intel","tag-mainboard"],"views":185,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/329816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=329816"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/329816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/329820"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=329816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=329816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=329816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}