{"id":321418,"date":"2015-11-13T10:19:40","date_gmt":"2015-11-13T03:19:40","guid":{"rendered":"http:\/\/notebookspec.com\/web\/?p=321418"},"modified":"2015-11-13T10:19:40","modified_gmt":"2015-11-13T03:19:40","slug":"candy-crush-creator-gets-gobbled-by-activision-for-5-9b","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/321418-candy-crush-creator-gets-gobbled-by-activision-for-5-9b","title":{"rendered":"Activision Blizzard \u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21 Candy Crush \u0e14\u0e49\u0e27\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e39\u0e07\u0e16\u0e36\u0e07 2.124 \u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17"},"content":{"rendered":"<p>\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u00a0Activision Blizzard \u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0King Digital Entertainment \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e41\u0e25\u0e30\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u00a0Candy Crush Saga \u0e14\u0e49\u0e27\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 $5.9 billion \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u00a02.124 \u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Activision Blizzard \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e43\u0e19\u0e1b\u0e35 2008 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0Vivendi Games (\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 Blizzard \u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e49\u0e19) \u0e08\u0e19\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e08\u0e32\u0e01\u00a0Activision \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u00a0Activision Blizzard \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-321422 size-full\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600.jpg\" alt=\"candy-crush-saga-600\" width=\"635\" height=\"475\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600.jpg 635w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600-375x281.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600-168x126.jpg 168w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/candy-crush-saga-600-320x239.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e21\u0e19\u0e31\u0e49\u0e19\u00a0Activision(\u0e2b\u0e23\u0e37\u0e2d\u00a0Activision Blizzard) \u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e01\u0e21\u0e14\u0e31\u0e07\u0e46 \u0e04\u0e23\u0e31\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e08\u0e30\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e49\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e41\u0e16\u0e21\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e02\u0e2d\u0e07\u0e27\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e41\u0e25\u0e30\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e32\u0e41\u0e23\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e41\u0e1b\u0e25\u0e01\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07\u00a0Activision Blizzard \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u00a0King Digital Entertainment \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e17\u0e35\u0e48\u0e17\u0e33\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e15\u0e31\u0e27\u0e40\u0e01\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e2d\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e33\u0e21\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e1e\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>King Digital Entertainment \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e35 2003 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e42\u0e21\u0e40\u0e14\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e21\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e1a\u00a0freemium \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e1a Free-to-Play \u0e41\u0e15\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e19\u0e40\u0e01\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 King \u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e40\u0e01\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 180 \u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e14\u0e31\u0e07\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e47\u0e04\u0e37\u0e2d\u00a0Candy Crush Saga(\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e43\u0e19\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e19\u0e35\u0e49) \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e31\u0e19\u0e21\u0e32\u0e01\u0e16\u0e36\u0e07 158 \u0e25\u0e49\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e23\u0e27\u0e21\u0e46 \u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 1 \u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19\u0e27\u0e31\u0e19\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Social Network \u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Facebook \u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1a\u0e19 Facebook \u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2012 \u0e44\u0e1b\u0e19\u0e31\u0e49\u0e19\u00a0Candy Crush Saga \u0e01\u0e47\u0e01\u0e49\u0e32\u0e27\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e43\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e46 \u0e02\u0e2d\u0e07 Facebook \u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19\u0e1b\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e01\u0e47\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 iOS \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 Android<\/p>\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e1b\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e01\u0e47\u0e01\u0e49\u0e32\u0e27\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e22\u0e2d\u0e14\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e19\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e01\u0e21 FarmVille 2 \u0e02\u0e2d\u0e07 Zygna \u0e1a\u0e19 Facebook \u0e41\u0e16\u0e21\u0e14\u0e49\u0e27\u0e22\u0e43\u0e19\u0e1b\u0e35 2013 \u0e19\u0e31\u0e49\u0e19\u0e40\u0e01\u0e21\u00a0Candy Crush Saga \u0e01\u0e47\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e19\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2d\u0e1b\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e19\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e04\u0e23\u0e31\u0e1a \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e41\u0e1b\u0e25\u0e01\u0e43\u0e08\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e0d\u0e48\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u00a0Activision Blizzard \u0e08\u0e30\u0e01\u0e25\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0King Digital Entertainment \u0e14\u0e49\u0e27\u0e22\u0e40\u0e07\u0e34\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-321432\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001.png\" alt=\"Activision Blizzard logo 600\" width=\"640\" height=\"448\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001.png 2000w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-375x263.png 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-780x546.png 780w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-180x126.png 180w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-768x538.png 768w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-1536x1075.png 1536w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/11\/Activision-Blizzard-logo-6001-320x224.png 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0Activision Blizzard \u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e0a\u0e48\u0e22\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e21\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e19\u0e34\u0e48\u0e19\u0e19\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e31\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e32\u0e27\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01(\u0e16\u0e36\u0e07\u0e02\u0e31\u0e49\u0e19\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e25\u0e49\u0e21) \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e19\u0e2b\u0e22\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u00a0Activision Blizzard \u0e21\u0e35\u0e40\u0e01\u0e21\u0e14\u0e31\u0e07\u0e46 \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e01\u0e21\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c Call of Duty \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01 ESPN \u0e41\u0e25\u0e30 NFL(Network and Major League Gaming) \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e01\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e19\u0e42\u0e0b\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07 Nintendo, Microsoft \u0e41\u0e25\u0e30 Sony \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e32\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u00a0Wall Street \u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32\u0e17\u0e32\u0e07\u00a0Activision Blizzard \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e21\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e32\u0e07\u00a0Activision Blizzard \u0e40\u0e2d\u0e07\u0e22\u0e31\u0e07\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e49\u0e32\u0e27\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u00a0e-commerce \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u00a0Activision Blizzard \u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.cnet.com\/news\/activision-buys-candy-crush-creator-king-digital-for-5-9b\/\"  target=\"_blank\" rel=\"noopener\">cnet<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Activision Blizzard \u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 King Digital Entertainment \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21<\/p>\n","protected":false},"author":53,"featured_media":321422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11050],"tags":[9440],"class_list":["post-321418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news","tag-call-of-duty"],"views":490,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/321418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=321418"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/321418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/321422"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=321418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=321418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=321418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}