{"id":283773,"date":"2015-03-15T14:13:30","date_gmt":"2015-03-15T07:13:30","guid":{"rendered":"http:\/\/notebookspec.com\/web\/?p=283773"},"modified":"2015-03-15T14:13:30","modified_gmt":"2015-03-15T07:13:30","slug":"huawei-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-mediapad-x2-%e0%b8%a1%e0%b8%b2%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%99%e0%b9%89","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/283773-huawei-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-mediapad-x2-%e0%b8%a1%e0%b8%b2%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%ab%e0%b8%99%e0%b9%89","title":{"rendered":"Huawei \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 MediaPad X2 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e02\u0e19\u0e32\u0e14 7 \u0e19\u0e34\u0e49\u0e27 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a 4G LTE \u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e44\u0e14\u0e49\u0e43\u0e19\u0e15\u0e31\u0e27"},"content":{"rendered":"<p>\u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e19\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e27\u0e2d\u0e17\u0e0a\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 Android Wear \u0e15\u0e31\u0e27\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Huawei \u0e43\u0e19\u0e07\u0e32\u0e19 MWC 2015 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 Huawei MediaPad X2 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e02\u0e2d\u0e07 MediaPad X1 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e22\u0e2d\u0e14\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e35\u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e43\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a MediaPad X2 \u0e19\u0e31\u0e49\u0e19 \u0e08\u0e30\u0e08\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e25\u0e47\u0e01(\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e19\u0e34\u0e49\u0e27) \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e32\u0e07\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e32\u0e21\u0e32\u0e01\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283775\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600.jpg\" alt=\"Huawei's MediaPad X2 01 600\" width=\"640\" height=\"400\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600.jpg 640w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600-375x234.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600-202x126.jpg 202w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-01-600-320x200.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e02\u0e2d\u0e07 MediaPad X2 \u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a MediaPad X1 \u0e43\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e19\u0e31\u0e01\u0e04\u0e23\u0e31\u0e1a(\u0e0b\u0e36\u0e48\u0e07\u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e1c\u0e21\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2a\u0e27\u0e22\u0e14\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e31\u0e1a) \u0e17\u0e27\u0e48\u0e32\u0e2a\u0e40\u0e1b\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e17\u0e27\u0e48\u0e32 MediaPad X2 \u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 2 \u0e23\u0e38\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a\u0e42\u0e14\u0e22\u0e23\u0e38\u0e48\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e20\u0e32\u0e22\u0e43\u0e19 16 Gb \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33(Ram) \u0e02\u0e19\u0e32\u0e14 2 GB \u0e01\u0e31\u0e1a\u0e2d\u0e35\u0e01\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 32 GB \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e02\u0e19\u0e32\u0e14 3 GB \u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-02-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283780\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-02-600.jpg\" alt=\"Huawei's MediaPad X2 02 600\" width=\"597\" height=\"400\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-03-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283781\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-03-600.jpg\" alt=\"Huawei's MediaPad X2 03 600\" width=\"597\" height=\"397\" \/><\/a><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1b\u0e40\u0e0b\u0e47\u0e17\u0e15\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u00a0HiSilicon Kirin 930 \u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07 Huawei \u0e40\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e41\u0e1a\u0e1a Octa-core\u00a02 GHz \u0e08\u0e33\u0e19\u0e27\u0e19 4 cores \u0e41\u0e25\u0e30 1.5 GHz \u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 4 cores \u0e43\u0e0a\u0e49\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 Mali-T628 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a WiFi 802.11ac(\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 MediaPad X1) \u0e2b\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 13 MP(\u0e23\u0e39\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07 f\/2.4) \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 5 MP (\u0e23\u0e39\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07 f\/2.2)<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283785\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600.jpg\" alt=\"Huawei's MediaPad X2 04 600\" width=\"599\" height=\"400\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600.jpg 599w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-04-600-320x214.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283786\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600.jpg\" alt=\"Huawei's MediaPad X2 05 600\" width=\"598\" height=\"398\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600.jpg 598w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-05-600-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e02\u0e19\u0e32\u0e14 7 \u0e19\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a 1,920 x 1,200 pixels \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e1a 4G LTE \u00a0\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e44\u0e14\u0e49\u0e43\u0e19\u0e15\u0e31\u0e27 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e35\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a MediaPad X1 \u0e04\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 239 g \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 7.18 mm \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1a\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e32\u0e07\u0e21\u0e32\u0e01\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e04\u0e23\u0e31\u0e1a \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e44\u0e1b\u0e43\u0e19\u0e15\u0e31\u0e27\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e14\u0e39\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e14\u0e35\u0e19\u0e31\u0e01\u0e2a\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283788\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600.jpg\" alt=\"Huawei's MediaPad X2 06 600\" width=\"599\" height=\"399\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600.jpg 599w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-06-600-320x213.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283789\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600.jpg\" alt=\"Huawei's MediaPad X2 07 600\" width=\"598\" height=\"399\" srcset=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600.jpg 598w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600-375x250.jpg 375w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600-189x126.jpg 189w, https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2015\/03\/Huaweis-MediaPad-X2-07-600-320x214.jpg 320w\" sizes=\"auto, (max-width: 768px) 92vw, (max-width: 992px) 450px, (max-width: 1200px) 597px, 730px\" \/><\/a><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07 Huawei \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07 MediaPad X2 \u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e44\u0e2b\u0e19 \u0e41\u0e15\u0e48 MediaPad X1 \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e19\u0e32\u0e14 16 GB \u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 $445 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 14,700 \u0e1a\u0e32\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07 MediaPad X2 \u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e08\u0e30\u0e2b\u0e19\u0e35\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e21\u0e32\u0e01\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : engadget<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e19\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e27\u0e2d\u0e17\u0e0a\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 Android Wear \u0e15\u0e31\u0e27\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Huawei \u0e43\u0e19\u0e07\u0e32\u0e19 MWC 2015 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 Huawei MediaPad X2<\/p>\n","protected":false},"author":53,"featured_media":283775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19055,6734],"tags":[2959,2521,20091,17828],"class_list":["post-283773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smartphone-news","category-tablet-news","tag-android-tablet","tag-huawei","tag-huawei-mediapad","tag-phablet"],"views":745,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/283773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=283773"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/283773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/283775"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=283773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=283773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=283773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}