{"id":245527,"date":"2014-07-13T12:25:29","date_gmt":"2014-07-13T05:25:29","guid":{"rendered":"http:\/\/notebookspec.com\/?p=245527"},"modified":"2014-07-13T12:25:29","modified_gmt":"2014-07-13T05:25:29","slug":"lg-kizon-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%aa%e0%b8%a7%e0%b8%a1%e0%b9%83%e0%b8%aa%e0%b9%88%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b9%80%e0%b8%94","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/245527-lg-kizon-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%aa%e0%b8%a7%e0%b8%a1%e0%b9%83%e0%b8%aa%e0%b9%88%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b9%80%e0%b8%94","title":{"rendered":"LG KizON \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e46\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32"},"content":{"rendered":"<p>\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07 smartwatch \u0e2b\u0e23\u0e37\u0e2d smartband \u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e31\u0e01\u0e08\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e04\u0e23\u0e31\u0e1a \u0e17\u0e32\u0e07 LG \u0e44\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e15\u0e23\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e2a\u0e32\u0e22\u0e23\u0e31\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e37\u0e2d KizOn \u0e04\u0e23\u0e31\u0e1a \u0e15\u0e31\u0e27 KizOn \u0e19\u0e31\u0e49\u0e19\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e42\u0e14\u0e22\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e43\u0e19\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e47\u0e01\u0e43\u0e19\u0e27\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 GPS \u0e41\u0e25\u0e30 Wi-Fi \u0e42\u0e14\u0e22\u0e15\u0e31\u0e27\u0e2a\u0e32\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e37\u0e2d\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a realtime \u0e42\u0e14\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07 smartphone \u0e41\u0e25\u0e30 tablet \u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e21\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e23\u0e31\u0e1a \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e32\u0e14\u0e40\u0e27\u0e25\u0e32\u0e27\u0e48\u0e32\u0e40\u0e14\u0e47\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>&nbsp;<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2014\/07\/LG_KizON_01-600.jpg\" alt=\"\" width=\"640\" height=\"248\"><\/p>\n<p style=\"text-align: center;\">\n<p>KizOn \u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1b\u0e38\u0e48\u0e21 &#8220;One Step Direct Call&#8221; \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e14\u0e47\u0e01\u0e44\u0e21\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32 10 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 KizOn \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1f\u0e31\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e14\u0e49(\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27 KizOn \u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e44\u0e27\u0e49\u0e42\u0e14\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19) \u0e41\u0e25\u0e30\u0e43\u0e19\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e14\u0e1b\u0e38\u0e48\u0e21\u0e42\u0e17\u0e23\u0e2d\u0e2d\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e42\u0e17\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a \u0e2d\u0e35\u0e01\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07 KizOn \u0e01\u0e47\u0e04\u0e37\u0e2d??Location Reminder? \u0e04\u0e23\u0e31\u0e1a \u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e49\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e02\u0e15\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e2d\u0e19\u0e01\u0e25\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e02\u0e15\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e14\u0e47\u0e01\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e35\u0e48 smartphone \u0e2b\u0e23\u0e37\u0e2d tablet \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2014\/07\/LG_KizON_02-600.jpg\" alt=\"\" width=\"520\" height=\"445\"><\/p>\n<p>KizOn \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e02\u0e19\u0e32\u0e14 400 mAh \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07 LG \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e44\u0e14\u0e49\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 36 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e15\u0e47\u0e21 1 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 KizOn \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48 smartphone \u0e2b\u0e23\u0e37\u0e2d tablet \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e02\u0e2d\u0e07 KizOn \u0e25\u0e14\u0e25\u0e07\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 25% \u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e2a\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e43\u0e2a\u0e48 KizOn \u0e17\u0e32\u0e07?LG \u0e44\u0e14\u0e49\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e27\u0e49\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e15\u0e31\u0e27\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e31\u0e1a KizOn \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 KizOn \u0e08\u0e30\u0e21\u0e35\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 3 \u0e2a\u0e35\u0e04\u0e37\u0e2d \u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19, \u0e0a\u0e21\u0e1e\u0e39 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e27\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e15\u0e49\u0e43\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e19\u0e35\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e32\u0e07 LG \u0e08\u0e30\u0e19\u0e33 KizOn \u0e44\u0e1b\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e43\u0e19\u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 3 \u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e23\u0e32\u0e04\u0e32\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e0a\u0e31\u0e14\u0e27\u0e48\u0e32 KizOn \u0e08\u0e30\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22\u0e19\u0e31\u0e49\u0e19\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e01\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a(\u0e41\u0e15\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e22\u0e32\u0e01\u0e19\u0e34\u0e14\u0e19\u0e36\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32 KizOn \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e48\u0e32\u0e19 Wi-Fi \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e15\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35 Wi-Fi \u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e21\u0e35\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a)<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 :?thenextweb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07 smartwatch \u0e2b\u0e23\u0e37\u0e2d smartband \u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e31\u0e01\u0e08\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e46 \u0e04\u0e23\u0e31\u0e1a \u0e17\u0e32\u0e07 LG <\/p>\n","protected":false},"author":53,"featured_media":245526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11050],"tags":[18452],"class_list":["post-245527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news","tag-wearable"],"views":196,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/245527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=245527"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/245527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/245526"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=245527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=245527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=245527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}