{"id":244437,"date":"2014-07-05T06:30:08","date_gmt":"2014-07-04T23:30:08","guid":{"rendered":"http:\/\/notebookspec.com\/?p=244437"},"modified":"2014-07-08T15:09:24","modified_gmt":"2014-07-08T08:09:24","slug":"%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%9c%e0%b8%a2-iphone-6-%e0%b8%88%e0%b8%b0%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%99%e0%b8%a7%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/244437-%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%9c%e0%b8%a2-iphone-6-%e0%b8%88%e0%b8%b0%e0%b8%a7%e0%b8%b2%e0%b8%87%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%99%e0%b8%a7%e0%b8%b1","title":{"rendered":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e1c\u0e22 iPhone 6 \u0e08\u0e30\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e38\u0e48\u0e19\u0e08\u0e2d 5.5 \u0e19\u0e34\u0e49\u0e27\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 iPhone Air"},"content":{"rendered":"<p>\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 Apple \u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 iPhone 6 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e17\u0e35\u0e48 15 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2014 \u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 25 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2014 \u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1a\u0e2d\u0e01\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 Apple \u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 iPhone \u0e17\u0e31\u0e49\u0e07\u0e23\u0e38\u0e48\u0e19\u0e02\u0e19\u0e32\u0e14\u0e08\u0e2d 4.7 \u0e19\u0e34\u0e49\u0e27 \u0e41\u0e25\u0e30 5.5 \u0e19\u0e34\u0e49\u0e27\u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07 iPhone \u0e23\u0e38\u0e48\u0e19 5.5 \u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e02\u0e19\u0e32\u0e14 16 GB \u0e41\u0e25\u0e30\u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 iPhone Air \u0e04\u0e23\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48?<span style=\"color: #041427;\">5,998 yuan ($965 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 31,845 \u0e1a\u0e32\u0e17) \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e38\u0e48\u0e19\u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d 4.7 \u0e19\u0e34\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 32 GB \u0e42\u0e14\u0e22\u0e08\u0e30\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32?5,288?yuan ($850 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 28,050 \u0e1a\u0e32\u0e17) \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07 iPhone 5S \u0e23\u0e38\u0e48\u0e19 16 GB \u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e13 \u0e40\u0e27\u0e25\u0e32\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a<\/span><br \/>\n<iframe loading=\"lazy\" width=\"640\" height=\"360\" src=\"\/\/www.youtube.com\/embed\/8XC_1eOlGgs\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d 4.7 \u0e19\u0e34\u0e49\u0e27\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e02\u0e19\u0e32\u0e14\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 16 GB \u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e07 Tencent \u0e1e\u0e2d\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e27\u0e48\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 Apple \u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 iPhone 6 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 19 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2014 \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e08\u0e2d 5.5 \u0e19\u0e34\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e02\u0e19\u0e32\u0e14 128 GB \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e43\u0e14\u0e46 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07 Apple \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e04\u0e2d\u0e22\u0e14\u0e39\u0e01\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e27\u0e48\u0e32 Apple \u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 iPhone 6 \u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e17\u0e48\u0e32\u0e44\u0e23\u0e01\u0e31\u0e19\u0e41\u0e19\u0e48 \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e04\u0e37\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e17\u0e32\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 :?macrumors<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 Apple \u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 iPhone 6 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e17\u0e35\u0e48 15 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2014 \u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 25 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2014 \u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e48\u0e32\u0e27\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1a\u0e2d\u0e01\u0e2d\u0e35\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 Apple<\/p>\n","protected":false},"author":53,"featured_media":244436,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7615,7616],"tags":[1297,13,17929,18404],"class_list":["post-244437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-macbook-corner","category-mac-news","tag-apple","tag-iphone","tag-iphone-6","tag-iphone-air"],"views":217,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/244437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=244437"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/244437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/244436"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=244437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=244437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=244437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}