{"id":195616,"date":"2013-09-29T08:30:31","date_gmt":"2013-09-29T01:30:31","guid":{"rendered":"http:\/\/notebookspec.com\/?p=195616"},"modified":"2013-09-29T11:34:12","modified_gmt":"2013-09-29T04:34:12","slug":"toshiba-%e0%b8%a2%e0%b8%81%e0%b8%97%e0%b8%b1%e0%b8%9e%e0%b9%82%e0%b8%99%e0%b9%89%e0%b8%95%e0%b8%9a%e0%b8%b8%e0%b9%8a%e0%b8%84-qosmio-%e0%b9%81%e0%b8%a5%e0%b8%b0-satellite-%e0%b9%83%e0%b8%ab%e0%b8%a1","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/195616-toshiba-%e0%b8%a2%e0%b8%81%e0%b8%97%e0%b8%b1%e0%b8%9e%e0%b9%82%e0%b8%99%e0%b9%89%e0%b8%95%e0%b8%9a%e0%b8%b8%e0%b9%8a%e0%b8%84-qosmio-%e0%b9%81%e0%b8%a5%e0%b8%b0-satellite-%e0%b9%83%e0%b8%ab%e0%b8%a1","title":{"rendered":"Toshiba \u0e22\u0e01\u0e17\u0e31\u0e1e\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 Qosmio \u0e41\u0e25\u0e30 Satellite \u0e43\u0e2b\u0e21\u0e48 \u0e21\u0e32\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e15\u0e47\u0e21\u0e46"},"content":{"rendered":"<p>Toshiba \u0e02\u0e19\u0e17\u0e31\u0e1e\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Satellite \u0e41\u0e25\u0e30 Qosmio \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e1e\u0e39\u0e14\u0e1e\u0e25\u0e48\u0e32\u0e21\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e44\u0e1b\u0e14\u0e39\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195617\" title=\"Toshiba_Qosmio_X75_01\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Toshiba_Qosmio_X75_01-640x461.jpg\" alt=\"\" width=\"448\" height=\"323\"><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e49\u0e27\u0e22 Qosmi \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c X \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e02\u0e36\u0e49\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e23\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e31\u0e1a\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e19\u0e35\u0e49 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46\u0e01\u0e31\u0e19 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e38\u0e48\u0e19 Qosmio X75 \u0e02\u0e19\u0e32\u0e14 17.3 \u0e19\u0e34\u0e49\u0e27 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e34\u0e1b Intel Haswell \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e1b\u0e47\u0e19 Core i7 \u0e0a\u0e34\u0e1b\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e41\u0e22\u0e01\u0e08\u0e32\u0e01 NVIDIA GeForce GTX 770M \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Optimus \u0e41\u0e25\u0e30\u0e21\u0e35\u0e41\u0e23\u0e21\u0e43\u0e19\u0e15\u0e31\u0e27 3GB DDR5 \u0e14\u0e49\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 SSD \u0e2b\u0e23\u0e37\u0e2d\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e1b\u0e01\u0e15\u0e34 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48 1.5TB \u0e2a\u0e40\u0e1b\u0e47\u0e01\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e43\u0e2a\u0e48\u0e21\u0e32\u0e2b\u0e21\u0e14\u0e44\u0e21\u0e48\u0e21\u0e35\u0e02\u0e32\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 HD \u0e44\u0e14\u0e23\u0e1f\u0e4c Blu-ray \u0e25\u0e33\u0e42\u0e1e\u0e07 Harman Kardon \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e15\u0e31\u0e27<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195618\" title=\"Toshiba_Satellite_P_Series_01\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Toshiba_Satellite_P_Series_01-640x509.jpg\" alt=\"\" width=\"448\" height=\"356\"><\/p>\n<p>\u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22 Satellite \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c P \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e2a\u0e40\u0e1b\u0e47\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e01\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27 Qosmio \u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e32\u0e07 \u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Ultrabook \u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e19\u0e32\u0e14 15.6 \u0e19\u0e34\u0e49\u0e27 \u0e41\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 Full HD \u0e21\u0e35\u0e1b\u0e38\u0e48\u0e21\u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 LED \u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e43\u0e19\u0e21\u0e37\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e2a\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e02\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e0a\u0e34\u0e1b\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e01\u0e47\u0e41\u0e22\u0e01\u0e08\u0e32 NVIDIA \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 UltraHD \u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e44\u0e14\u0e49 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07 HDMI \u0e14\u0e49\u0e27\u0e22<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195619\" title=\"Toshiba_Satellite_S_Series_01\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Toshiba_Satellite_S_Series_01-640x424.jpg\" alt=\"\" width=\"512\" height=\"339\"><\/p>\n<p>\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Satellite \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c S \u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e01\u0e47\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a Satellite P \u0e02\u0e19\u0e32\u0e14\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07 17.3 \u0e19\u0e34\u0e49\u0e27 \u0e41\u0e25\u0e30 15.6 \u0e19\u0e34\u0e49\u0e27 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 Full HD \u0e41\u0e25\u0e30 HD+ \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e2a\u0e40\u0e1b\u0e47\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e08\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c P \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48 1TB \u0e41\u0e25\u0e30\u0e41\u0e23\u0e21 16GB \u0e41\u0e15\u0e48\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e19\u0e31\u0e49\u0e19 \u0e08\u0e30\u0e21\u0e35 APU A10 \u0e02\u0e2d\u0e07 AMD \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195620\" title=\"Toshiba_Satellite_L_Series_01\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Toshiba_Satellite_L_Series_01-640x481.jpg\" alt=\"\" width=\"512\" height=\"385\"><\/p>\n<p>\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Satellite \u0e41\u0e15\u0e48\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c L \u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07 \u0e15\u0e31\u0e27\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0a\u0e34\u0e1b\u0e43\u0e2b\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01 Intel \u0e41\u0e25\u0e30 AMD \u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e19\u0e32\u0e14 15.6 \u0e41\u0e25\u0e30 17.3 \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 DTS Studio Sound \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e32\u0e01\u0e25\u0e33\u0e42\u0e1e\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 1TB \u0e41\u0e25\u0e30\u0e41\u0e23\u0e21\u0e17\u0e35\u0e48 8GB<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195621\" title=\"Toshiba_Satellite_C_Series_01\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Toshiba_Satellite_C_Series_01-640x448.jpg\" alt=\"\" width=\"512\" height=\"358\"><\/p>\n<p>\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e47\u0e01\u0e2a\u0e38\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 Satellite C \u0e40\u0e19\u0e49\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e21\u0e35\u0e1f\u0e35\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e02\u0e19\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e01\u0e47\u0e08\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d 15.6 \u0e41\u0e25\u0e30 17.3 \u0e19\u0e34\u0e49\u0e27 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e47\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 750GB \u0e41\u0e25\u0e30\u0e41\u0e23\u0e21 8GB \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e21\u0e35\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e44\u0e23\u0e49\u0e02\u0e2d\u0e1a \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e0a\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e47\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 Intel Core \u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 4 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e23\u0e38\u0e48\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35 Pentium 2020M \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e04\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1f\u0e19 AMD \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e0a\u0e34\u0e1b APU A4 \u0e41\u0e25\u0e30 A6 \u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p>\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e19\u0e35\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19 \u0e15\u0e32\u0e21\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e40\u0e25\u0e22<\/p>\n<ul>\n<li>Qosmio X Series starts at $1,399.99 (43,xxx \u0e1a\u0e32\u0e17)<\/li>\n<li>Satellite P Series starts at $799.99 (25,xxx \u0e1a\u0e32\u0e17)<\/li>\n<li>Satellite S Series starts at $599.99 (18,xxx \u0e1a\u0e32\u0e17)<\/li>\n<li>Satellite L Series starts at $529.99 (16,xxx \u0e1a\u0e32\u0e17)<\/li>\n<li>Satellite C Series starts $359.99 (11,xxx \u0e1a\u0e32\u0e17)<\/li>\n<\/ul>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: TechPowerUp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toshiba \u0e02\u0e19\u0e17\u0e31\u0e1e\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e2a\u0e32\u0e22\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 Satellite \u0e41\u0e25\u0e30 Qosmio \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e1e\u0e39\u0e14\u0e1e\u0e25\u0e48\u0e32\u0e21\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e44\u0e1b\u0e14\u0e39\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22<\/p>\n","protected":false},"author":1011016,"featured_media":195617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1981,2281,367],"class_list":["post-195616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-qosmio","tag-satellite","tag-toshiba"],"views":2212,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/195616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=195616"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/195616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/195617"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=195616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=195616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=195616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}