{"id":195027,"date":"2013-09-27T12:00:12","date_gmt":"2013-09-27T05:00:12","guid":{"rendered":"http:\/\/notebookspec.com\/?p=195027"},"modified":"2014-04-30T11:55:00","modified_gmt":"2014-04-30T04:55:00","slug":"%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%81%e0%b8%84%e0%b8%ad%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b9%84%e0%b8%9b%e0%b9%83%e0%b8%8a%e0%b9%89%e0%b8%87%e0%b8%b2%e0%b8%99","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/195027-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9e%e0%b8%81%e0%b8%84%e0%b8%ad%e0%b8%a1%e0%b8%9e%e0%b9%8c%e0%b9%84%e0%b8%9b%e0%b9%83%e0%b8%8a%e0%b9%89%e0%b8%87%e0%b8%b2%e0%b8%99","title":{"rendered":"\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e16\u0e36\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22"},"content":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e36\u0e07\u0e23\u0e30\u0e27\u0e31\u0e07\u0e44\u0e27\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d \u0e1a\u0e23\u0e23\u0e14\u0e32\u0e23\u0e30\u0e1a\u0e1a Log-in \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a \u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e44\u0e1f\u0e25\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e25\u0e37\u0e21\u0e44\u0e1b\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e39\u0e48 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e17\u0e35\u0e48\u0e44\u0e02\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e30\u0e27\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_lg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195041\" title=\"Ceedo_lg\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_lg.jpg\" width=\"400\" height=\"300\"><\/a><br \/> \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e23\u0e30\u0e1a\u0e1a InPrivate Browsing \u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e19 Internet Explorer \u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e47\u0e08\u0e30\u0e2d\u0e34\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e25\u0e2d\u0e07 Windows Vista, Windows 7 \u0e41\u0e25\u0e30 Windows 8 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32 Ceedo \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e02\u0e49\u0e32\u0e07\u0e19\u0e2d\u0e01 \u0e41\u0e15\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e25\u0e47\u0e2d\u0e04\u0e2d\u0e34\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a Gigabyte \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1a\u0e2d\u0e01\u0e44\u0e27\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a ?Trial \u0e17\u0e14\u0e25\u0e2d\u0e07\u0e43\u0e0a\u0e49 45 \u0e27\u0e31\u0e19? \u0e2b\u0e32\u0e01\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e16\u0e39\u0e01\u0e43\u0e08 \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e27\u0e40\u0e15\u0e47\u0e21\u0e21\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e44\u0e1b\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Ceedo \u0e21\u0e32\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e15\u0e48\u0e2d External HDD \u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195042\" title=\"Ceedo_1\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_1.jpg\" width=\"500\" height=\"366\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">1<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e47\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 Install \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e14\u0e23\u0e1f\u0e4c External HDD \u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195043\" title=\"Ceedo_2\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_2.jpg\" width=\"395\" height=\"207\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">2<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e15\u0e23\u0e07\u0e08\u0e38\u0e14\u0e19\u0e35\u0e49<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195044\" title=\"Ceedo_3\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_3.jpg\" width=\"500\" height=\"394\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">3<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e41\u0e23\u0e01\u0e43\u0e2b\u0e49\u0e15\u0e48\u0e2d USB \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2d\u0e22\u0e39\u0e48 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a Auto Run \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e1f\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e14\u0e23\u0e1f\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195045\" style=\"border: 1px solid black;\" title=\"Ceedo_4\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_4.jpg\" width=\"500\" height=\"330\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">4<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19 Start Ceedo \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e44\u0e14\u0e23\u0e1f\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e41\u0e16\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e40\u0e21\u0e19\u0e39\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e47\u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195046\" style=\"border: 1px solid black;\" title=\"Ceedo_5\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_5.jpg\" width=\"500\" height=\"343\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">5<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e2a\u0e48\u0e27\u0e19\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e21\u0e19\u0e39 All Program \u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e1a Start Menu \u0e02\u0e2d\u0e07\u0e27\u0e34\u0e19\u0e42\u0e14\u0e27\u0e2a\u0e4c\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195047\" style=\"border: 1px solid black;\" title=\"Ceedo_6\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_6.jpg\" width=\"500\" height=\"414\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">6<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e39\u0e02\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e21\u0e32\u0e44\u0e14\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e01\u0e0b\u0e49\u0e32\u0e22\u0e04\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e1b-\u0e21\u0e32\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195048\" style=\"border: 1px solid black;\" title=\"Ceedo_7\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_7.jpg\" width=\"500\" height=\"301\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">7<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e41\u0e15\u0e48\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e32\u0e07\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e02\u0e2d\u0e07 Ceedo \u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 All Program \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48 Program Directory \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195049\" title=\"Ceedo_8\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_8.jpg\" width=\"500\" height=\"329\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">8<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e25\u0e34\u0e01 Download \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195032\" style=\"border: 1px solid black;\" title=\"Ceedo_9\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_9.jpg\" width=\"500\" height=\"368\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">9<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e08\u0e30\u0e44\u0e1b\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19 Tray \u0e02\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Ceedo \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195033\" style=\"border: 1px solid black;\" title=\"Ceedo_10\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_10.jpg\" width=\"500\" height=\"363\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">10<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e21\u0e32\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Ceedo \u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e43\u0e14\u0e46 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e2a\u0e35\u0e2a\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 Ceedo \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d Save \u0e44\u0e1f\u0e25\u0e4c\u0e07\u0e32\u0e19\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 External Drive \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 My Document \u0e1a\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1a\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e4c\u0e2b\u0e25\u0e31\u0e01<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195034\" style=\"border: 1px solid black;\" title=\"Ceedo_11\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_11.jpg\" width=\"500\" height=\"340\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">11<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e25\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e39\u0e43\u0e19 Recent \u0e02\u0e2d\u0e07 MS Word \u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e40\u0e0b\u0e1f\u0e44\u0e1f\u0e25\u0e4c\u0e44\u0e1b \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35 Recent file \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 PowerPoint, Excel \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-195035\" style=\"border: 1px solid black;\" title=\"Ceedo_12\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_12.jpg\" width=\"500\" height=\"303\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">12<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e19 Web browser \u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e42\u0e2b\u0e21\u0e14\u0e02\u0e2d\u0e07 Ceedo \u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e2a\u0e35\u0e2a\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e02\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e43\u0e19\u0e42\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e25\u0e07\u0e44\u0e1b<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195036\" style=\"border: 1px solid black;\" title=\"Ceedo_13\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_13.jpg\" width=\"500\" height=\"374\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">13<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e2b\u0e19\u0e49\u0e32 IE \u0e1a\u0e19\u0e27\u0e34\u0e19\u0e42\u0e14\u0e27\u0e2a\u0e4c\u0e1b\u0e01\u0e15\u0e34 \u0e19\u0e2d\u0e01\u0e42\u0e2b\u0e21\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 Ceedo \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e19 Ceedo \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b \u0e01\u0e47\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e47\u0e1a\u0e2b\u0e23\u0e37\u0e2d History \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e19\u0e0a\u0e48\u0e2d\u0e07 URL \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_14.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195037\" title=\"Ceedo_14\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_14.jpg\" width=\"500\" height=\"298\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">14<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07 Sign-in \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e42\u0e2b\u0e21\u0e14\u0e02\u0e2d\u0e07 Ceedo \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e23\u0e30\u0e1a\u0e38\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e14\u0e08\u0e33\u0e2b\u0e23\u0e37\u0e2d Remember password \u0e01\u0e47\u0e15\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e42\u0e2b\u0e21\u0e14 Ceede \u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32 Windows \u0e1b\u0e01\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e44\u0e21\u0e48\u0e08\u0e14\u0e08\u0e33\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49 \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23 Sign-in \u0e43\u0e2b\u0e21\u0e48\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e21\u0e32\u0e01\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e25\u0e37\u0e21 Sign-out \u0e2d\u0e2d\u0e01 \u0e41\u0e21\u0e49\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21 Sign-in \u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e0b\u0e49\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e35\u0e01\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 Facebook \u0e41\u0e15\u0e48\u0e43\u0e19 Ceedo \u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32 Windows \u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1c\u0e25<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195038\" title=\"Ceedo_15\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_15.jpg\" width=\"500\" height=\"368\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">15<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e43\u0e19\u0e42\u0e1f\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c My Document \u0e19\u0e31\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 Picture, Music \u0e2b\u0e23\u0e37\u0e2d Video \u0e01\u0e47\u0e08\u0e30\u0e16\u0e39\u0e01\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e42\u0e1f\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07 Ceedo \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e1b\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-195039\" style=\"border: 1px solid black;\" title=\"Ceedo_16\" alt=\"\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/Ceedo_16.jpg\" width=\"500\" height=\"311\"><\/a><\/p>\n<div class=\"clear\">?<\/div>\n<div class=\"number_title_border\">\n<div class=\"number_title_in\">16<\/div>\n<\/div>\n<div class=\"text_detail\">\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e30\u0e14\u0e36\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e21\u0e23\u0e39\u0e1b\u0e2a\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e1a\u0e19\u0e41\u0e16\u0e1a\u0e40\u0e21\u0e19\u0e39 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e04\u0e25\u0e34\u0e01 Ok \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e40\u0e0b\u0e1f\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e14\u0e36\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35<\/div>\n<div class=\"clear\">?<\/div>\n<div class=\"clear\">?<\/div>\n<p>\u0e08\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e35\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e21\u0e32\u0e41\u0e01\u0e30\u0e23\u0e2d\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e36\u0e07\u0e23\u0e30\u0e27\u0e31\u0e07\u0e44\u0e27\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d \u0e1a\u0e23\u0e23\u0e14\u0e32\u0e23\u0e30\u0e1a\u0e1a Log-in \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a <\/p>\n","protected":false},"author":47,"featured_media":195033,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[17290,2419,254,1856,17494,920,10],"class_list":["post-195027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-special-story","category-tips-tricks","tag-document","tag-external-harddisk","tag-external-hdd","tag-ie","tag-ms-word","tag-security","tag-windows"],"views":2529,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/195027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=195027"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/195027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/195033"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=195027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=195027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=195027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}