{"id":190553,"date":"2012-09-03T17:52:39","date_gmt":"2012-09-03T10:52:39","guid":{"rendered":"http:\/\/notebookspec.com\/?p=190553"},"modified":"2014-03-12T19:41:15","modified_gmt":"2014-03-12T12:41:15","slug":"%e0%b8%a3%e0%b8%a7%e0%b8%a1%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%b9%e0%b8%a5-iphone-%e0%b8%a3%e0%b8%b2%e0%b8%84%e0%b8%b2-ais-dtac-true-%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%aa","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/190553-%e0%b8%a3%e0%b8%a7%e0%b8%a1%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%b9%e0%b8%a5-iphone-%e0%b8%a3%e0%b8%b2%e0%b8%84%e0%b8%b2-ais-dtac-true-%e0%b8%9e%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%a1%e0%b8%aa","title":{"rendered":"\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 iPhone \u0e23\u0e32\u0e04\u0e32 AIS, DTAC, TRUE \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e40\u0e1b\u0e01"},"content":{"rendered":"<p>iPhone \u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Apple \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 iPhone \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e35\u0e40\u0e21\u0e25 \u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e48\u0e07 SMS \u0e17\u0e48\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 Safari \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 Wi-Fi (802.11b\/g) \u0e1a\u0e25\u0e39\u0e17\u0e39\u0e18 2.0 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e 2.0-megapixel \u0e44\u0e2d\u0e42\u0e1f\u0e19\u0e23\u0e38\u0e48\u0e19\u0e41\u0e23\u0e01\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 2.5G quad band GSM \u0e41\u0e25\u0e30 EDGE \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e43\u0e0a\u0e49 UMTS \u0e41\u0e25\u0e30 HSDPA<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iphone2g.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-190784\" title=\"iphone2g\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iphone2g.jpg\" alt=\"\" width=\"567\" height=\"368\"><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>Apple \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e44\u0e2d\u0e42\u0e1f\u0e19\u0e23\u0e38\u0e48\u0e19\u0e41\u0e23\u0e01\u0e42\u0e14\u0e22 Steve Job?\u0e43\u0e19\u0e07\u0e32\u0e19 Macworld \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2550 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2550 iPhone \u0e44\u0e14\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e08\u0e32\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e44\u0e17\u0e21\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2550 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e38\u0e48\u0e19\u0e16\u0e31\u0e14\u0e21\u0e32\u0e04\u0e37\u0e2d iPhone 3G \u0e41\u0e25\u0e30 iPhone?3GS \u0e41\u0e25\u0e30?iPhone 4 \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 7 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2553 iPhone?\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e04\u0e37\u0e2d iPhone 5 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iphones.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-190785\" title=\"iphones\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iphones.jpg\" alt=\"\" width=\"455\" height=\"254\"><\/a><\/p>\n<p>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c iPhone \u0e19\u0e35\u0e49\u0e08\u0e30\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22 iPhone?\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e38\u0e48\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e31\u0e0a\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01 iOS \u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e08\u0e2d\u0e20\u0e32\u0e1e \u0e40\u0e0a\u0e48\u0e19\u0e2b\u0e32\u0e01\u0e27\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e43\u0e19\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07 \u0e2b\u0e32\u0e01\u0e27\u0e32\u0e07\u0e43\u0e19\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e43\u0e19\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iPhone-5-Review-081.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-190786\" title=\"iPhone-5-Review-081\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/iPhone-5-Review-081.jpg\" alt=\"\" width=\"540\" height=\"360\"><\/a><\/p>\n<p>iPhone \u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2550 \u0e42\u0e14\u0e22\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35\u0e44\u0e27\u0e23\u0e4c\u0e40\u0e25\u0e2a\u0e2a\u0e4c (\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d \u0e0b\u0e34\u0e07\u0e01\u0e34\u0e27\u0e25\u0e32\u0e23\u0e4c\u0e44\u0e27\u0e23\u0e4c\u0e40\u0e25\u0e2a\u0e2a\u0e4c) \u0e42\u0e14\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e49\u0e32\u0e19 Apple \u0e44\u0e14\u0e49\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 14 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e02\u0e32\u0e22 iPhone \u0e43\u0e19\u0e40\u0e27\u0e25\u0e32 18 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32\u0e15\u0e32\u0e21\u0e40\u0e27\u0e25\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e23\u0e2d\u0e04\u0e34\u0e27\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07 Apple \u0e02\u0e32\u0e22 iPhone?\u0e44\u0e14\u0e49 270,000 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 30 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19 iPhone \u0e23\u0e38\u0e48\u0e19\u0e41\u0e23\u0e01\u0e21\u0e35\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e44\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e2a\u0e2b\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e1d\u0e23\u0e31\u0e48\u0e07\u0e40\u0e28\u0e2a \u0e40\u0e22\u0e2d\u0e23\u0e21\u0e19\u0e35 \u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/apple_iphone_3gs-54.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-190787\" title=\"apple_iphone_3gs-54\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/apple_iphone_3gs-54.jpg\" alt=\"\" width=\"550\" height=\"314\"><\/a><\/p>\n<p>\u0e42\u0e14\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2551 iPhone \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d iPhone?3G \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19 22 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e21\u0e35\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e43\u0e19 48 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e23\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 70 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e19\u0e08\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e1b\u0e34\u0e19\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 iPhone?\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d iPhone?\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e14\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 2 \u0e1b\u0e35<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/images_13177542251.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-190788\" title=\"images_13177542251\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/images_13177542251.jpg\" alt=\"\" width=\"480\" height=\"313\"><\/a><\/p>\n<p>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 iPhone??3G \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2552 \u0e42\u0e14\u0e22\u0e17\u0e23\u0e39\u0e21\u0e39\u0e1f \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16-18 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2552 \u0e13 \u0e23\u0e2d\u0e22\u0e31\u0e25\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e2a\u0e22\u0e32\u0e21\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e35\u0e41\u0e17\u0e04\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e41\u0e23\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2553 \u0e13 \u0e25\u0e32\u0e19\u0e1e\u0e32\u0e23\u0e4c\u0e01\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2a\u0e22\u0e32\u0e21\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2553 \u0e40\u0e27\u0e25\u0e32 0.00 \u0e19. iPhone??4 \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e17\u0e23\u0e39\u0e21\u0e39\u0e1f, \u0e14\u0e35\u0e41\u0e17\u0e04 \u0e41\u0e25\u0e30 AIS \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/2012-iphone5-gallery7-zoom.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-190789\" title=\"2012-iphone5-gallery7-zoom\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2013\/09\/2012-iphone5-gallery7-zoom.jpg\" alt=\"\" width=\"540\" height=\"324\"><\/a><em><span style=\"text-align: left;\">iPhone 5 \u0e23\u0e38\u0e48\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19<\/span><\/em><\/p>\n<p style=\"text-align: left;\">\u0e17\u0e35\u0e48\u0e21\u0e32 :?wikipedia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>iPhone \u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Apple \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 iPhone \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e35\u0e40\u0e21\u0e25 \u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e48\u0e07 SMS \u0e17\u0e48\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 Safari \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 Wi-Fi (802.11b\/g) \u0e1a\u0e25\u0e39\u0e17\u0e39\u0e18 2.0 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e 2.0-megapixel \u0e44\u0e2d\u0e42\u0e1f\u0e19\u0e23\u0e38\u0e48\u0e19\u0e41\u0e23\u0e01\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 2.5G quad band GSM \u0e41\u0e25\u0e30 EDGE \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e43\u0e0a\u0e49 UMTS \u0e41\u0e25\u0e30 HSDPA Advertisement Apple \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e44\u0e2d\u0e42\u0e1f\u0e19\u0e23\u0e38\u0e48\u0e19\u0e41\u0e23\u0e01\u0e42\u0e14\u0e22 Steve Job?\u0e43\u0e19\u0e07\u0e32\u0e19 Macworld \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2550 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2550 iPhone \u0e44\u0e14\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e08\u0e32\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e44\u0e17\u0e21\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2550 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e38\u0e48\u0e19\u0e16\u0e31\u0e14\u0e21\u0e32\u0e04\u0e37\u0e2d iPhone [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":190784,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13],"class_list":["post-190553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-iphone"],"views":616,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/190553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=190553"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/190553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/190784"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=190553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=190553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=190553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}