{"id":158122,"date":"2009-11-30T07:14:17","date_gmt":"2009-11-30T00:14:17","guid":{"rendered":""},"modified":"2010-05-29T07:17:09","modified_gmt":"2010-05-29T00:17:09","slug":"%e0%b8%ae%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%94%e0%b9%81%e0%b8%a7%e0%b8%a3%e0%b9%8c-%e0%b9%80%e0%b8%ae%e0%b9%89%e0%b8%b2%e0%b8%aa%e0%b9%8c-%e0%b8%a2%e0%b8%81%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/158122-%e0%b8%ae%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%94%e0%b9%81%e0%b8%a7%e0%b8%a3%e0%b9%8c-%e0%b9%80%e0%b8%ae%e0%b9%89%e0%b8%b2%e0%b8%aa%e0%b9%8c-%e0%b8%a2%e0%b8%81%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b","title":{"rendered":"\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e22\u0e01\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e25\u0e07\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33259\" title=\"logo-hardwarehouse-supersto\" src=\"\/web\/wp-content\/uploads\/2010\/05\/n4g_logo-hardwarehouse-supersto.jpg\" alt=\"logo-hardwarehouse-supersto\" width=\"442\" height=\"252\" \/><\/p>\n<p>\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c? \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e44\u0e2d\u0e17\u0e35 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e01\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e32\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e27\u0e48\u0e32 1,300 \u0e15\u0e23.\u0e21. \u0e43\u0e19\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e01\u0e23\u0e35\u0e11\u0e32\u0e17\u0e31\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e15\u0e25\u0e2d\u0e14 4 \u0e27\u0e31\u0e19 \u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e14\u0e49\u0e27\u0e22\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e41\u0e08\u0e01\u0e23\u0e16 \u0e0a\u0e39\u0e08\u0e38\u0e14\u0e02\u0e32\u0e22 ?\u0e0a\u0e47\u0e2d\u0e1b\u0e41\u0e1a\u0e1a\u0e0a\u0e34\u0e27\u0e46?<\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33261\" title=\"Chatchai_HWH\" src=\"\/web\/wp-content\/uploads\/2010\/05\/n4g_Chatchai_HWH-300x450.jpg\" alt=\"Chatchai_HWH\" width=\"300\" height=\"450\" \/><\/p>\n<p>?\u0e19\u0e32\u0e22 \u0e0a\u0e32\u0e15\u0e34\u0e0a\u0e32\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e18\u0e23\u0e23\u0e21\u0e42\u0e2a\u0e20\u0e13 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14? \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\u0e42\u0e09\u0e21\u0e43\u0e2b\u0e21\u0e48? \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e21\u0e32\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e27\u0e48\u0e32 1,300 \u0e15\u0e23.\u0e21. \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e2d\u0e17\u0e35\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 ?\u0e04\u0e2d\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d \u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e1c\u0e22\u0e42\u0e09\u0e21\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e22\u0e01 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e21\u0e32\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07?<\/p>\n<table border=\"0\" width=\"600\">\n<tbody>\n<tr>\n<td>?<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33262\" title=\"Creative_World_of_warcraft\" src=\"\/web\/wp-content\/uploads\/2010\/05\/n4g_Creative_World_of_warcraft-300x415.jpg\" alt=\"Creative_World_of_warcraft\" width=\"300\" height=\"415\" \/><\/td>\n<td>?<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-33263\" title=\"Manli_Nettop_T1\" src=\"\/web\/wp-content\/uploads\/2010\/05\/n4g_Manli_Nettop_T1-300x400.jpg\" alt=\"Manli_Nettop_T1\" width=\"300\" height=\"400\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>?\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e22 \u0e0a\u0e32\u0e15\u0e34\u0e0a\u0e32\u0e22 \u0e22\u0e31\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e27\u0e48\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e2e\u0e40\u0e2d\u0e19 \u0e08\u0e32\u0e01\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f (Creative) \u0e23\u0e38\u0e48\u0e19 \u0e25\u0e34\u0e21\u0e34\u0e40\u0e15\u0e47\u0e14 \u0e40\u0e2d\u0e14\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14 \u0e2d\u0e2d\u0e1f \u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e32\u0e1f (World of Warcraft) \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 5 \u0e0a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e17\u0e31\u0e0a\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c-\u0e44\u0e1f \u0e17\u0e39 \u0e08\u0e32\u0e01\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e21\u0e48\u0e32\u0e19\u0e25\u0e35 (Manli) \u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19 \u0e17\u0e35\u0e48\u0e02\u0e2d\u0e0a\u0e34\u0e21\u0e25\u0e32\u0e07\u0e15\u0e25\u0e32\u0e14\u0e40\u0e19\u0e47\u0e15\u0e1a\u0e38\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e47\u0e15\u0e17\u0e4a\u0e2d\u0e1b \u0e14\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p>?\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19? \u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e44\u0e17\u0e21\u0e4c \u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e41\u0e25\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29? \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e1a\u0e32\u0e17? \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e1a\u0e34\u0e14\u0e44\u0e17\u0e21\u0e4c \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22? \u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e39\u0e18\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e25\u0e38\u0e49\u0e19\u0e42\u0e0a\u0e04\u0e43\u0e2b\u0e0d\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0b\u0e39\u0e0b\u0e39\u0e01\u0e34 \u0e2a\u0e27\u0e34\u0e1f\u0e17\u0e4c \u0e08\u0e32\u0e01\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d ?\u0e42\u0e01 \u0e42\u0e01\u0e25\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e21\u0e01\u0e49\u0e32 \u0e40\u0e0b\u0e25\u0e25\u0e4c? \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e0a\u0e32\u0e15\u0e34\u0e0a\u0e32\u0e22\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 \u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e15\u0e25\u0e2d\u0e14 4 \u0e27\u0e31\u0e19 <\/p>\n","protected":false},"author":24,"featured_media":566317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16718],"tags":[],"class_list":["post-158122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming-notebook"],"views":3074,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/158122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=158122"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/158122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/566317"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=158122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=158122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=158122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}