{"id":157370,"date":"2009-03-07T00:25:21","date_gmt":"2009-03-06T17:25:21","guid":{"rendered":""},"modified":"2009-09-03T00:25:21","modified_gmt":"2009-09-02T17:25:21","slug":"%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-gateway-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b9%81%e0%b8%a3%e0%b8%81%e0%b9%83%e0%b8%99%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/157370-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-gateway-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b9%81%e0%b8%a3%e0%b8%81%e0%b9%83%e0%b8%99%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2","title":{"rendered":"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Gateway \u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c &#8220;Cool Simplicity&#8221; \u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e4b\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e14\u0e39\u0e14\u0e35 \u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c"},"content":{"rendered":"<p><span id=\"lblStory\"><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<div style=\"text-align: left;\"><span id=\"lblStory\"><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\">Gateway \u0e1c\u0e39\u0e49\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a Desktop \u0e41\u0e25\u0e30 Notebook \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/span><\/span><\/div>\n<div><span><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><!--more--><\/span><\/span><\/div>\n<div><span><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><br \/>\n<\/span><\/span><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20307\" title=\"gateway4\" src=\"\/web\/wp-content\/uploads\/2009\/09\/n4g_gateway4.jpg\" alt=\"gateway4\" width=\"450\" height=\"359\" \/><\/div>\n<div><\/div>\n<p>\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07 Gateway \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c &#8220;Cool Simplicity&#8221;? \u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e4b\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e14\u0e39\u0e14\u0e35 \u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e42\u0e14\u0e22\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 Gateway \u0e44\u0e14\u0e49\u0e19\u0e33 Notebook \u0e21\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e19\u0e07\u0e32\u0e19\u0e16\u0e36\u0e07 4 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30Desktop 2 \u0e23\u0e38\u0e48\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e0a\u0e32\u0e27\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e02\u0e2d\u0e07 Gateway \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 ? 13 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2552 \u0e0a\u0e31\u0e49\u0e19 G \u0e2b\u0e19\u0e49\u0e32\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e1e\u0e25\u0e32\u0e0b\u0e32 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"> <strong>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22 Desktop Series \u0e02\u0e2d\u0e07 Gateway \u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e14\u0e49\u0e27\u0e22 3 \u0e23\u0e38\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 <\/strong><br \/>\n-? Gateway DX4800 [The Black Autumn Collection] : \u0e40\u0e1b\u0e47\u0e19 Desktop \u0e17\u0e35\u0e48\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e19\u0e14\u0e33 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e23\u0e27\u0e21\u0e2d\u0e22\u0e39\u0e48 Gateway DX4800<br \/>\n-? Gateway SX2800 [The Autumn Collection] : \u0e40\u0e1b\u0e47\u0e19 Desktop \u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07 Multi Function \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e04\u0e25\u0e31\u0e48\u0e07\u0e43\u0e04\u0e25\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e02\u0e19\u0e32\u0e14\u0e08\u0e33\u0e01\u0e31\u0e14<br \/>\n-? Gateway ZX2300 [The White Summer Collection] : \u0e40\u0e1b\u0e47\u0e19 Desktop \u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e35\u0e02\u0e32\u0e27 \u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e07\u0e2b\u0e19\u0e35\u0e44\u0e21\u0e48\u0e1e\u0e49\u0e19\u0e01\u0e32\u0e23\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 <\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><\/p>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20309\" title=\"gateway4\" src=\"\/web\/wp-content\/uploads\/2009\/09\/n4g_gateway41.jpg\" alt=\"gateway4\" width=\"450\" height=\"398\" \/><\/div>\n<div><\/div>\n<p><\/span><\/p>\n<p style=\"text-align: left;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a Notebook \u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07 Gateway \u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c \u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e15\u0e23\u0e35 \u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e1d\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e01 (\u0e41\u0e15\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07&#8230;\u0e17\u0e48\u0e32\u0e08\u0e30\u0e2b\u0e19\u0e31\u0e01) \u0e41\u0e25\u0e30\u0e1a\u0e32\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e1e\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e49\u0e32\u0e07\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07<\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><strong>Gateway \u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e48\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14 Notebook \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e23\u0e38\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 <\/strong><br \/>\n&#8211; Gateway NV48 [The Winter Snow Collection] : Notebook \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e1d\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e04\u0e25\u0e32\u0e2a\u0e34\u0e04\u0e21\u0e31\u0e19\u0e27\u0e32\u0e27 \u0e17\u0e32\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e42\u0e25\u0e42\u0e01\u0e49 Gateway \u0e2a\u0e35\u0e40\u0e07\u0e37\u0e19\u0e1a\u0e19\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e22\u0e39\u0e48 2 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e35\u0e14\u0e33 (Night Sky Back)? \u0e41\u0e25\u0e30 \u0e2a\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 (Copper Brown) \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22<br \/>\n&#8211; Gateway ID58 [The Perfect Storm Collection] : Notebook \u0e2a\u0e35\u0e21\u0e31\u0e19\u0e27\u0e32\u0e27 \u0e1c\u0e2a\u0e21\u0e14\u0e49\u0e27\u0e22\u0e42\u0e04\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e16\u0e39\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e42\u0e04\u0e49\u0e07\u0e21\u0e19 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07<br \/>\n&#8211; Gateway TC79 [The Autumn Shade Collection] : Notebook \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e39 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e17\u0e48\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2a\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e16\u0e36\u0e07 2 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e35\u0e14\u0e33\u0e41\u0e25\u0e30\u0e2a\u0e35\u0e41\u0e14\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e08\u0e2d\u0e41\u0e1a\u0e1a 16:9 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e17\u0e34\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07\u0e01\u0e31\u0e1a Blu-Ray<br \/>\n&#8211; Gateway LT31 [The Summer Breeze Collection] : Notebook \u0e02\u0e19\u0e32\u0e14\u0e01\u0e23\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 11.6 \u0e19\u0e34\u0e49\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e01\u0e1e\u0e32 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 2 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e35\u0e14\u0e33 \u0e41\u0e25\u0e30 \u0e2a\u0e35\u0e41\u0e14\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e15\u0e4c\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e42\u0e04\u0e49\u0e07\u0e21\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e16\u0e16\u0e37\u0e2d\u0e21\u0e37\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e1a\u0e32\u0e22 \u0e46<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000; font-family: Microsoft Sans Serif;\"> <span style=\"text-decoration: underline;\">\u0e1e\u0e25\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19 ?Gateway Grand Opening? \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 11 ? 13 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2552 \u0e0a\u0e31\u0e49\u0e19 G \u0e2b\u0e19\u0e49\u0e32\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e1e\u0e25\u0e32\u0e0b\u0e32 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15<\/span><\/span><\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Advertisement Gateway \u0e1c\u0e39\u0e49\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a Desktop \u0e41\u0e25\u0e30 Notebook \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n","protected":false},"author":24,"featured_media":565676,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16718],"tags":[],"class_list":["post-157370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming-notebook"],"views":2391,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/157370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=157370"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/157370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/565676"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=157370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=157370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=157370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}