{"id":142432,"date":"2012-12-28T10:00:49","date_gmt":"2012-12-28T03:00:49","guid":{"rendered":"http:\/\/notebookspec.com\/?p=142432"},"modified":"2013-10-02T12:13:33","modified_gmt":"2013-10-02T05:13:33","slug":"%e0%b9%80%e0%b8%9e%e0%b8%a3%e0%b8%b2%e0%b8%b0%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b9%83%e0%b8%94-%e0%b8%84%e0%b8%ad%e0%b8%a1%e0%b8%9e%e0%b8%b4%e0%b8%a7%e0%b9%80%e0%b8%95%e0%b8%ad%e0%b8%a3%e0%b9%8c","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/142432-%e0%b9%80%e0%b8%9e%e0%b8%a3%e0%b8%b2%e0%b8%b0%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b9%83%e0%b8%94-%e0%b8%84%e0%b8%ad%e0%b8%a1%e0%b8%9e%e0%b8%b4%e0%b8%a7%e0%b9%80%e0%b8%95%e0%b8%ad%e0%b8%a3%e0%b9%8c","title":{"rendered":"\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e16\u0e36\u0e07\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19 External HDD \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e41\u0e04\u0e48 2.2 TB"},"content":{"rendered":"<p>\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 External HDD \u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 (\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e19\u0e04\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e35\u0e01) \u0e42\u0e14\u0e22\u0e1a\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e21\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e32\u0e22 TB \u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e15\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e32\u0e07\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d HDD \u0e01\u0e31\u0e1a\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48 (Enclosure Box) \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e07 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e04\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 External HDD \u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 2.2 TB \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e2d\u0e07\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e25\u0e07 Windows \u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2b\u0e32\u0e22<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/12\/I10224252.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"margin: 10px auto; display: block;\" title=\"I10224252\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/12\/I10224252.jpg\" alt=\"\" width=\"440\" height=\"330\"><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30 Windows, OS X \u0e2b\u0e23\u0e37\u0e2d Linux \u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e01\u0e47\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 HDD \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e46 \u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e0a\u0e48\u0e19\u0e15\u0e31\u0e27 OS X \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a HDD \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 ?8 Exabytes (1 EB = 1,000,000 TB) \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e2d\u0e31\u0e19\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e0a\u0e34\u0e1b\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 Enclosure Box \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e0a\u0e34\u0e1b\u0e23\u0e38\u0e48\u0e19\u0e40\u0e01\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1a\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e41\u0e04\u0e48 32 bit \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e43\u0e19 HDD \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e25\u0e30 512 byte \u0e42\u0e14\u0e22\u0e16\u0e49\u0e32\u0e04\u0e33\u0e19\u0e27\u0e13\u0e08\u0e32\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1a\u0e34\u0e15\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a 2<sup>32 <\/sup>\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e27\u0e46 4,294,967,296 \u0e1a\u0e25\u0e47\u0e2d\u0e01 \u0e42\u0e14\u0e22\u0e16\u0e49\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e25\u0e30 512 byte \u0e01\u0e47\u0e08\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 HDD \u0e17\u0e35\u0e48\u0e0a\u0e34\u0e1b\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e14\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d 2.199 TB \u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 HDD \u0e44\u0e14\u0e49\u0e41\u0e04\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07 2.2 TB \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\n<p>\u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e34\u0e1b\u0e02\u0e2d\u0e07 Enclosure Box \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1a\u0e34\u0e15\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19 48 bit (\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32) \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e43\u0e19 HDD \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e25\u0e30 4,096 byte \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e04\u0e33\u0e19\u0e27\u0e13\u0e41\u0e25\u0e49\u0e27\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e47\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 HDD \u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 1,016.5 EB \u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e43\u0e04\u0e23\u0e2b\u0e32 Enclosure Box \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e07 \u0e16\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e01\u0e47\u0e04\u0e27\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : CNET<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 External HDD \u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07<\/p>\n","protected":false},"author":1011016,"featured_media":563715,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11050],"tags":[254,2448,11221],"class_list":["post-142432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news","tag-external-hdd","tag-hdd","tag--notebook"],"views":2924,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/142432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=142432"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/142432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/563715"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=142432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=142432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=142432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}