{"id":135367,"date":"2012-11-12T12:00:17","date_gmt":"2012-11-12T05:00:17","guid":{"rendered":"http:\/\/notebookspec.com\/?p=135367"},"modified":"2012-11-12T09:46:18","modified_gmt":"2012-11-12T02:46:18","slug":"%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b8%9e%e0%b8%9a-%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b9%83%e0%b8%8a%e0%b9%89-youtube-%e0%b8%a1%e0%b8%b1%e0%b8%81","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/135367-%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b8%9e%e0%b8%9a-%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b9%83%e0%b8%8a%e0%b9%89-youtube-%e0%b8%a1%e0%b8%b1%e0%b8%81","title":{"rendered":"\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e1a \u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 YouTube \u0e21\u0e31\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2b\u0e21\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e42\u0e2b\u0e25\u0e14\u0e40\u0e01\u0e34\u0e19 2 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35"},"content":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e43\u0e19 YouTube \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27 content \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e35\u0e48\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e08\u0e19\u0e21\u0e32\u0e01\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e14\u0e39\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07\u0e1a\u0e19 YouTube \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e04\u0e19\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 YouTube \u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e47\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e42\u0e2b\u0e25\u0e14\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e0a\u0e49\u0e32\u0e25\u0e07 \u0e08\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e14\u0e39\u0e44\u0e1b\u0e01\u0e23\u0e30\u0e15\u0e38\u0e01\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e41\u0e21\u0e15\u0e0b\u0e32\u0e0a\u0e39\u0e40\u0e2a\u0e2a \u0e08\u0e32\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e23\u0e2d\u0e42\u0e2b\u0e25\u0e14\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e19\u0e32\u0e19 2 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2b\u0e21\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e14\u0e39\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e22\u0e34\u0e48\u0e07\u0e23\u0e2d\u0e19\u0e32\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e25\u0e30 6% \u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e16\u0e49\u0e32\u0e23\u0e2d\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07 30 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e01\u0e47\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e42\u0e14\u0e22\u0e21\u0e32\u0e01\u0e08\u0e30\u0e21\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0b\u0e47\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a 80% (\u0e0b\u0e36\u0e48\u0e07\u0e16\u0e49\u0e32\u0e23\u0e2d\u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49 \u0e04\u0e19\u0e23\u0e2d\u0e01\u0e47\u0e04\u0e07\u0e1b\u0e25\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e27\u0e32\u0e07\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27) \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e21\u0e04\u0e25\u0e34\u0e1b YouTube \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\/\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e21\u0e32\u0e01 \u0e04\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e07\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e35\u0e0b\u0e35 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\/\u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e31\u0e07\u0e01\u0e23\u0e32\u0e1f\u0e1d\u0e31\u0e48\u0e07\u0e02\u0e27\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/11\/9-2_4pos2dxk.png\"><img loading=\"lazy\" decoding=\"async\" style=\"margin: 10px auto; display: block;\" title=\"9-2_4pos2dxk\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/11\/9-2_4pos2dxk.png\" alt=\"\" width=\"560\" height=\"238\"><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e0b\u0e49\u0e32\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e2d\u0e0a\u0e21\u0e04\u0e25\u0e34\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e27\u0e48\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 (\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e08\u0e19\u0e16\u0e36\u0e07 30 \u0e19\u0e32\u0e17\u0e35) \u0e01\u0e31\u0e1a\u0e04\u0e25\u0e34\u0e1b\u0e22\u0e32\u0e27\u0e1a\u0e19 YouTube \u0e41\u0e1a\u0e1a\u0e44\u0e2b\u0e19\u0e04\u0e19\u0e08\u0e30\u0e22\u0e2d\u0e21\u0e2d\u0e14\u0e17\u0e19\u0e23\u0e2d\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e31\u0e19 \u0e1c\u0e25\u0e01\u0e47\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e08\u0e30\u0e2d\u0e14\u0e17\u0e19\u0e23\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e25\u0e34\u0e1b\u0e22\u0e32\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e23\u0e48\u0e27\u0e21 2 \u0e40\u0e17\u0e48\u0e32\u0e15\u0e31\u0e27 \u0e40\u0e0a\u0e48\u0e19\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e42\u0e2b\u0e25\u0e14 10 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e02\u0e2d\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e2a\u0e31\u0e49\u0e19 \u0e04\u0e19\u0e08\u0e30\u0e21\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e01\u0e27\u0e48\u0e32 40% \u0e41\u0e15\u0e48\u0e01\u0e31\u0e1a\u0e04\u0e25\u0e34\u0e1b\u0e22\u0e32\u0e27 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e08\u0e30\u0e21\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0b\u0e47\u0e07\u0e41\u0e04\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13? 20% \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : The Verge<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e43\u0e19 YouTube \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27 content \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e35\u0e48\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19<\/p>\n","protected":false},"author":1011016,"featured_media":563416,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11050],"tags":[3751],"class_list":["post-135367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news","tag-youtube"],"views":1456,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/135367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=135367"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/135367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/563416"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=135367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=135367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=135367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}