{"id":114253,"date":"2012-05-28T16:05:00","date_gmt":"2012-05-28T09:05:00","guid":{"rendered":"http:\/\/www.notebookspec.com\/web\/?p=114253"},"modified":"2012-05-28T16:05:00","modified_gmt":"2012-05-28T09:05:00","slug":"%e0%b9%80%e0%b8%a5%e0%b8%ad%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a7-%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%97%e0%b8%a5-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%8a%e0%b8%b4","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/114253-%e0%b9%80%e0%b8%a5%e0%b8%ad%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a7-%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%97%e0%b8%a5-%e0%b8%88%e0%b8%b1%e0%b8%9a%e0%b8%a1%e0%b8%b7%e0%b8%ad-%e0%b8%8a%e0%b8%b4","title":{"rendered":"\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25 \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 IdeaCentre A720 \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/notebookspec.com\/web\/111557\/\">\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e35\u0e27\u0e34\u0e27 Lenovo?<\/a><strong><a href=\"https:\/\/notebookspec.com\/web\/111557\/\">IdeaCentre A720 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e04\u0e23\u0e31\u0e1a &lt;&lt;&lt;<\/a><\/strong><\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25 \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27?IdeaCentre A720<\/strong><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p style=\"text-align: center;\" align=\"center\"><strong>\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e42\u0e2b\u0e21\u0e14\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a?Digital Home?<\/strong><\/p>\n<ul>\n<li>\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2b\u0e23\u0e39 \u0e25\u0e07\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d?Full HD?\u0e02\u0e19\u0e32\u0e14 27 \u0e19\u0e34\u0e49\u0e27 \u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01<\/li>\n<li>\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e01\u0e31<wbr>\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e31\u0e0a\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e31\u0e21\u0e1c\u0e31<wbr>\u0e2a\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e16\u0e36\u0e07?10?\u0e08\u0e38\u0e14<\/wbr><\/wbr><\/li>\n<li>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 -5 \u0e16\u0e36\u0e07 90 \u0e2d\u0e07\u0e28\u0e32 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e38\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49<wbr>\u0e2d\u0e07\u0e01\u0e32\u0e23<\/wbr><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><strong>?<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114255\" title=\"A720_Hero_09\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/A720_Hero_09.jpg\" alt=\"\" width=\"557\" height=\"522\"><\/strong><\/p>\n<p><strong>\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/strong><strong>,?<\/strong><strong>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22?<\/strong><strong>??<\/strong><strong>28 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21?<\/strong><strong>255<\/strong><strong>5<\/strong><strong>:<\/strong>?\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25<strong>?<\/strong>\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d?\u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e42\u0e2e\u0e21\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e14\u0e35<wbr>\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22?\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2a\u0e01\u0e4c\u0e17\u0e47<wbr>\u0e2d\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25?IdeaCentre A720?\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e41\u0e2b\u0e48<wbr>\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48<wbr>\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e22\u0e38<wbr>\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e42\u0e2b\u0e21\u0e14\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a?Digital Home?\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48 \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39<wbr>\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e04\u0e23\u0e1a 5,000 \u0e1a\u0e32\u0e17 \u0e23\u0e31\u0e1a\u0e17\u0e31\u0e19\u0e17\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14 5,000 \u0e1a\u0e32\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-<wbr>\u0e27\u0e31\u0e25?IdeaCentre A720?\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49???30 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2555 \u0e19\u0e35\u0e49\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/p>\n<p style=\"text-align: center;\">?<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114256\" title=\"Lenovo IdeaCentre A720 Opening 102\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/Lenovo-IdeaCentre-A720-Opening-102.jpg\" alt=\"\" width=\"630\" height=\"420\"><\/p>\n<p><strong>\u0e04\u0e38\u0e13\u0e08\u0e35\u0e23\u0e27\u0e38\u0e12\u0e34 \u0e27\u0e07\u0e28\u0e4c\u0e1e\u0e34\u0e21\u0e25\u0e1e\u0e23? \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong>\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32??\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e19\u0e27\u0e31<wbr>\u0e15\u0e01\u0e23\u0e23\u0e21\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e22\u0e38\u0e04\u0e14\u0e34\u0e08\u0e34<wbr>\u0e15\u0e2d\u0e25\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31<wbr>\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e04\u0e19\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31<wbr>\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19?\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49?IdeaCentre A720?\u0e22\u0e31\u0e07\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-<wbr>\u0e27\u0e31\u0e25\u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47<wbr>\u0e19\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2a\u0e01\u0e4c\u0e17\u0e47<wbr>\u0e2d\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25 \u0e08\u0e32\u0e01\u0e07\u0e32\u0e19?CES?2012 \u0e17\u0e35\u0e48\u0e25\u0e32\u0e2a\u0e40\u0e27\u0e01\u0e31\u0e2a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e08\u0e32\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23?PC Mag,?PC World?\u0e41\u0e25\u0e30?Computer Shopper?\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22?<\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114257\" title=\"Lenovo IdeaCentre A720 Opening 117\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/Lenovo-IdeaCentre-A720-Opening-117.jpg\" alt=\"\" width=\"630\" height=\"420\">?<\/p>\n<p><strong>IdeaCentre A720?<\/strong><strong>\u0e1c\u0e2a\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31<wbr>\u0e22\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13<\/wbr><\/strong><\/p>\n<p>IdeaCentre A720?\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48<wbr>\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25 \u0e1e\u0e35\u0e0b\u0e35?\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49<wbr>\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31<wbr>\u0e15\u0e34\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22?\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48<wbr>\u0e1d\u0e31\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e21\u0e35\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a??Digital?Home?<strong><\/strong><\/wbr><\/wbr><\/wbr><\/wbr><\/p>\n<p style=\"text-align: center;\"><strong>?<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114259\" title=\"Lenovo IdeaCentre A720 Opening 94\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/Lenovo-IdeaCentre-A720-Opening-94.jpg\" alt=\"\" width=\"630\" height=\"420\"><\/strong><\/p>\n<p>&#8211; \u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34<wbr>\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e22\u0e38<wbr>\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e31\u0e1a\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e14\u0e49<wbr>\u0e27\u0e22 3rd?Generation Intel? Core? Processors<\/wbr><\/wbr><\/wbr><\/p>\n<p>&#8211; \u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e08\u0e2d\u0e20\u0e32\u0e1e\u0e44\u0e27\u0e14\u0e4c\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39<wbr>\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e23\u0e2d\u0e1a \u0e02\u0e19\u0e32\u0e14 27 \u0e19\u0e34\u0e49\u0e27 \u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34<wbr>\u0e07\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e14\u0e49\u0e27\u0e22\u0e20\u0e32\u0e1e\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e47\u0e21\u0e2d\u0e34\u0e48\u0e21\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07?Dolby Home Theatre V4<\/wbr><\/wbr><\/p>\n<p>&#8211; \u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49<wbr>\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e31\u0e0a 10 \u0e08\u0e38\u0e14 \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e04\u0e25\u0e34\u0e01\u0e01\u0e47\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19IdeaCentre A720?\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e19\u0e15\u0e23\u0e35\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 5 \u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19?Grand Piano, Electronic Piano, Guitar, Violin?\u0e41\u0e25\u0e30?Bass<\/wbr><\/p>\n<p>&#8211; \u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48<wbr>\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38<wbr>\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e28\u0e32\u0e08\u0e2d\u0e44\u0e14\u0e49<wbr>\u0e43\u0e19\u0e21\u0e38\u0e21\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e14\u0e36\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e42\u0e14\u0e22\u0e17\u0e33\u0e21\u0e38<wbr>\u0e21?-5<sup>o<\/sup>?\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e2b\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e42\u0e14\u0e22\u0e17\u0e33\u0e21\u0e38<wbr>\u0e21\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07?90<sup>o<strong><\/strong><\/sup><\/wbr><\/wbr><\/wbr><\/wbr><\/wbr><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114260\" title=\"Lenovo IdeaCentre A720 Opening 103\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/Lenovo-IdeaCentre-A720-Opening-103.jpg\" alt=\"\" width=\"630\" height=\"420\"><\/p>\n<p><strong>\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22<\/strong><strong><\/strong><\/p>\n<p>\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25?IdeaCentre A720?\u0e21\u0e35\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48?\u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22 &#8211; \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e39\u0e0b\u0e35\u0e1f \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c<wbr>\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27?\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34<wbr>\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 \u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e04\u0e2d\u0e25\u0e25\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e17\u0e23. 1800-060-087?\u0e2b\u0e23\u0e37\u0e2d 02-689-6451\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48<wbr>\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48<wbr>\u0e32\u0e07\u0e46\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c?Lenovo Thailand (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.lenovo.com\/th\/en\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.lenovo.com\/th\/en\/<\/a>)?\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48?Lenovo RSS Feeds (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/news.lenovo.com\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/news.lenovo.com\/<\/a>)?\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19?Facebook (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.facebook.com\/lenovo.lover\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.facebook.com\/<wbr>lenovo.lover<\/wbr><\/a>)<\/wbr><\/wbr><\/wbr><\/wbr><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-114261\" title=\"Lenovo IdeaCentre A720 Opening 107\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/05\/Lenovo-IdeaCentre-A720-Opening-107.jpg\" alt=\"\" width=\"420\" height=\"630\"><\/p>\n<p style=\"text-align:center\">\n","protected":false},"excerpt":{"rendered":"<p>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e35\u0e27\u0e34\u0e27 Lenovo?IdeaCentre A720 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e04\u0e23\u0e31\u0e1a &lt;&lt;&lt; \u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25 \u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27?IdeaCentre A720Advertisement \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e42\u0e2b\u0e21\u0e14\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a?Digital Home? \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2b\u0e23\u0e39 \u0e25\u0e07\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d?Full HD?\u0e02\u0e19\u0e32\u0e14 27 \u0e19\u0e34\u0e49\u0e27 \u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01 \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e21\u0e31\u0e25\u0e15\u0e34\u0e17\u0e31\u0e0a\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e16\u0e36\u0e07?10?\u0e08\u0e38\u0e14 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 -5 \u0e16\u0e36\u0e07 90 \u0e2d\u0e07\u0e28\u0e32 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e38\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 ? \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f,?\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22???28 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21?2555:?\u0e40\u0e25\u0e2d\u0e42\u0e19\u0e42\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25?\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d?\u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e42\u0e2e\u0e21\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22?\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2a\u0e01\u0e4c\u0e17\u0e47\u0e2d\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25?IdeaCentre A720?\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2a\u0e19\u0e2d\u0e07\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e2a\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e42\u0e2b\u0e21\u0e14\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a?Digital Home?\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48 \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e0a\u0e34\u0e04 \u0e23\u0e35\u0e1e\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e04 \u0e04\u0e23\u0e1a 5,000 \u0e1a\u0e32\u0e17 \u0e23\u0e31\u0e1a\u0e17\u0e31\u0e19\u0e17\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14 5,000 \u0e1a\u0e32\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e25-\u0e2d\u0e34\u0e19-\u0e27\u0e31\u0e25?IdeaCentre A720?\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49???30 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2555 \u0e19\u0e35\u0e49\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 ? [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":567381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1066,1450,9345],"class_list":["post-114253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notebook-news","tag-all-in-one","tag-ideacentre","tag-lenovo-ideacentre-a720"],"views":897,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/114253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=114253"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/114253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media\/567381"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=114253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=114253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=114253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}