{"id":106780,"date":"2012-04-11T12:04:00","date_gmt":"2012-04-11T05:04:00","guid":{"rendered":"http:\/\/www.notebookspec.com\/web\/?p=106780"},"modified":"2012-04-11T12:04:00","modified_gmt":"2012-04-11T05:04:00","slug":"sony-%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b8%84%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81-10000-%e0%b8%95%e0%b8%b3%e0%b9%81%e0%b8%ab%e0%b8%99%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/notebookspec.com\/web\/106780-sony-%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b8%84%e0%b8%99%e0%b8%ad%e0%b8%ad%e0%b8%81-10000-%e0%b8%95%e0%b8%b3%e0%b9%81%e0%b8%ab%e0%b8%99%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2","title":{"rendered":"Sony \u0e04\u0e31\u0e14\u0e04\u0e19\u0e2d\u0e2d\u0e01 10,000 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e08\u0e32\u0e01\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e04\u0e19\u0e43\u0e2b\u0e21\u0e48"},"content":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e19\u0e32\u0e21 Sony Corp \u0e44\u0e14\u0e49\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e27\u0e48\u0e32 10,000 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19 6 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01 Sony \u0e17\u0e31\u0e48\u0e27\u0e17\u0e31\u0e49\u0e07\u0e42\u0e25\u0e01 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c Nikkei \u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 CEO \u0e04\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07 Sony \u0e19\u0e32\u0e22 Kazuo Hirai \u0e44\u0e14\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e41\u0e14\u0e07\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 4 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/04\/download.jpg\" rel=\"lightbox[106780]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-106781\" title=\"A logo of Sony is pictured at an electronic store in Tokyo\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/04\/download.jpg\" alt=\"\" width=\"450\" height=\"303\"><\/a><\/p><div class='zox-widget-ad' style='float:none'><span class='zox-ad-label'>Advertisement<\/span><iframe id='a141c1a9' name='a141c1a9' src='https:\/\/openx.notebookspec.com\/www\/delivery\/afr.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE' frameborder='0' scrolling='no' width='300' height='250' allow='autoplay'><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/openx.notebookspec.com\/www\/delivery\/ck.php?n=a0e6abb9&amp;cb=INSERT_RANDOM_NUMBER_HERE\"  target='_blank' loading='lazy'><img decoding=\"async\" src=\"https:\/\/openx.notebookspec.com\/www\/delivery\/avw.php?zoneid=123&amp;cb=INSERT_RANDOM_NUMBER_HERE&amp;n=a0e6abb9\" border=\"0\" alt=\"\" loading=\"lazy\"><\/a><\/iframe><\/div>\n<p>\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e0d\u0e35\u0e1b\u0e38\u0e48\u0e48\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07 NEC \u0e41\u0e25\u0e30\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e35\u0e01\u0e23\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07 Panasonic \u0e17\u0e35\u0e48\u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e21\u0e32\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e1b\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Apple \u0e41\u0e25\u0e30 Samsung<\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e27\u0e35\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e08\u0e30\u0e15\u0e35\u0e15\u0e25\u0e32\u0e14\u0e44\u0e14\u0e49\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07 Sharp \u0e01\u0e47\u0e25\u0e14\u0e25\u0e07\u0e2d\u0e35\u0e01 \u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07 3 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e31\u0e01\u0e29\u0e4c Sony, Panasonic \u0e41\u0e25\u0e30 Sharp \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 1.7 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e35\u0e19\u0e35\u0e49<\/p>\n<p><a href=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/04\/download-1.jpg\" rel=\"lightbox[106780]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-106782\" title=\"ASony Corp&#039;s logo is pictured at an electronics store in Tokyo\" src=\"https:\/\/notebookspec.com\/web\/wp-content\/uploads\/2012\/04\/download-1.jpg\" alt=\"\" width=\"450\" height=\"282\"><\/a><\/p>\n<p>\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e47\u0e08\u0e30\u0e40\u0e1d\u0e49\u0e32\u0e14\u0e39\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e38\u0e1b\u0e02\u0e2d\u0e07 Hirai \u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e19\u0e35\u0e49 \u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e02\u0e2d\u0e07 Hirai \u0e19\u0e31\u0e49\u0e19\u0e14\u0e39\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e01\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19 \u0e41\u0e49\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49 Sony \u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e42\u0e14\u0e22 Hirai \u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 CEO \u0e19\u0e35\u0e49\u0e41\u0e17\u0e19\u0e04\u0e19\u0e40\u0e01\u0e48\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e48\u0e32\u0e19 Sir Howard Stringer<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: Reuters<\/p>\n<p style=\"text-align:center\">\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e19\u0e32\u0e21 Sony Corp \u0e44\u0e14\u0e49\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e27\u0e48\u0e32 10,000 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19 6 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01 Sony \u0e17\u0e31\u0e48\u0e27\u0e17\u0e31\u0e49\u0e07\u0e42\u0e25\u0e01 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c Nikkei \u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 CEO \u0e04\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07 Sony \u0e19\u0e32\u0e22 Kazuo Hirai \u0e44\u0e14\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e41\u0e14\u0e07\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e27\u0e48\u0e32 4 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27 Advertisement \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e0d\u0e35\u0e1b\u0e38\u0e48\u0e48\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07 NEC \u0e41\u0e25\u0e30\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e35\u0e01\u0e23\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07 Panasonic \u0e17\u0e35\u0e48\u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e21\u0e32\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e41\u0e02\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e1b\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Apple \u0e41\u0e25\u0e30 Samsung \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e27\u0e35\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e08\u0e30\u0e15\u0e35\u0e15\u0e25\u0e32\u0e14\u0e44\u0e14\u0e49\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07 Sharp \u0e01\u0e47\u0e25\u0e14\u0e25\u0e07\u0e2d\u0e35\u0e01 \u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07 3 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e31\u0e01\u0e29\u0e4c Sony, Panasonic \u0e41\u0e25\u0e30 Sharp \u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32 1.7 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e35\u0e19\u0e35\u0e49 [&hellip;]<\/p>\n","protected":false},"author":1011016,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1297,498,219,9060,9061],"class_list":["post-106780","post","type-post","status-publish","format-standard","hentry","category-notebook-news","tag-apple","tag-samsung","tag-sony","tag-sony-ceo","tag-sony-corp"],"views":229,"_links":{"self":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/106780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/users\/1011016"}],"replies":[{"embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/comments?post=106780"}],"version-history":[{"count":0,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/posts\/106780\/revisions"}],"wp:attachment":[{"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/media?parent=106780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/categories?post=106780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notebookspec.com\/web\/wp-json\/wp\/v2\/tags?post=106780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}